{"id":39442,"date":"2021-06-06T08:22:12","date_gmt":"2021-06-06T12:22:12","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=39442"},"modified":"2021-06-06T08:22:12","modified_gmt":"2021-06-06T12:22:12","slug":"anvisa-autoriza-importacao-da-sputnik-v-comprada-pelo-governo-de-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/anvisa-autoriza-importacao-da-sputnik-v-comprada-pelo-governo-de-mato-grosso\/","title":{"rendered":"Anvisa autoriza importa\u00e7\u00e3o da Sputnik V, comprada pelo Governo de Mato Grosso"},"content":{"rendered":"<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<p>A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) autorizou a importa\u00e7\u00e3o da vacina Sputnik V, da R\u00fassia, que \u00e9 usada contra a covid-19, e foi adquirida pelo governador Mauro Mendes em mar\u00e7o deste ano.<\/p>\n<p>A autoriza\u00e7\u00e3o foi concedida nesta sexta-feira (04.06), durante reuni\u00e3o extraordin\u00e1ria da Diretoria Colegiada do \u00f3rg\u00e3o. O imunizante tem 91,6% de efic\u00e1cia contra o v\u00edrus e \u00e9 usado em 68 pa\u00edses.<\/p>\n<p>A importa\u00e7\u00e3o foi concedida mediante algumas condicionantes, como a an\u00e1lise dos lotes que chegarem pelo Instituto Nacional de Controle de Qualidade de Sa\u00fade (INCQS) e a aplica\u00e7\u00e3o reduzida inicialmente aos primeiros lotes, sendo aumentada gradativamente ap\u00f3s o acompanhamento da efetividade.<\/p>\n<p>\u201cEssa \u00e9 uma vit\u00f3ria para a popula\u00e7\u00e3o de Mato Grosso e do Brasil. Ainda que os lotes liberados por enquanto sejam reduzidos, toda e qualquer quantidade de vacina j\u00e1 \u00e9 suficiente para salvar vidas, e \u00e9 isso que importa. A importa\u00e7\u00e3o vai acelerar o processo de vacina\u00e7\u00e3o e complementar a imuniza\u00e7\u00e3o que est\u00e1 sendo coordenada pelo Governo Federal. Fico feliz por termos colaborado para isso\u201d, afirmou o governador Mauro Mendes.<\/p>\n<p>O secret\u00e1rio de Estado de Sa\u00fade, Gilberto Figueiredo, comemorou a decis\u00e3o. Ele pontuou que a aplica\u00e7\u00e3o do imunizante vai resultar em menos interna\u00e7\u00f5es e \u00f3bitos, que \u00e9 o mais importante neste momento.<\/p>\n<p>\u201cCom essa autoriza\u00e7\u00e3o pela Anvisa, poderemos vislumbrar uma amplia\u00e7\u00e3o da cobertura vacinal em Mato Grosso\u201d, mencionou.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><\/p>\n<p>O Governo do Estado adquiriu 1,2 milh\u00e3o de doses da Sputnik V, que j\u00e1 cont\u00e9m os dois componentes da vacina, ou seja, as doses poder\u00e3o imunizar 1,2 milh\u00e3o de pessoas.<\/p>\n<p>A aquisi\u00e7\u00e3o ocorreu junto ao F\u00f3rum de Governadores da Amaz\u00f4nia Legal e do Cons\u00f3rcio Nordeste.<\/p>\n<p>Na pr\u00f3xima semana, o Governo de Mato Grosso deve se reunir com a Anvisa e com o Fundo Russo para alinhar os pr\u00f3ximos passos para a chegada e aplica\u00e7\u00e3o do imunizante.<\/p>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"http:\/\/www.mt.gov.br\/-\/17224917-anvisa-autoriza-importacao-da-sputnik-v-comprada-pelo-governo-de-mato-grosso#73\" target=\"_blank\" rel=\"noopener\">GOV MT<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) autorizou a importa\u00e7\u00e3o da vacina Sputnik V, da &hellip;<\/p>\n","protected":false},"author":4,"featured_media":39443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-39442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/39442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=39442"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/39442\/revisions"}],"predecessor-version":[{"id":39444,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/39442\/revisions\/39444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/39443"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=39442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=39442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=39442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}