{"id":39834,"date":"2021-06-12T08:00:34","date_gmt":"2021-06-12T12:00:34","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=39834"},"modified":"2021-06-12T08:00:34","modified_gmt":"2021-06-12T12:00:34","slug":"tribunal-mantem-condenacao-de-produtor-de-tijolos-por-extracao-de-argila-sem-licenca-ambiental","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/tribunal-mantem-condenacao-de-produtor-de-tijolos-por-extracao-de-argila-sem-licenca-ambiental\/","title":{"rendered":"Tribunal mantem condena\u00e7\u00e3o de produtor de tijolos por extra\u00e7\u00e3o de argila sem licen\u00e7a ambiental"},"content":{"rendered":"<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<p>A 7\u00aa Turma do Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF4), de maneira un\u00e2nime, negou o recurso de um agricultor e produtor de tijolos de argila de 53 anos, residente em \u00c1gua Santa (RS), que havia sido condenado em primeira inst\u00e2ncia a uma pena de presta\u00e7\u00e3o de servi\u00e7os \u00e0 comunidade e pagamento de multa por danos ambientais e minera\u00e7\u00e3o sem autoriza\u00e7\u00e3o legal. A decis\u00e3o do colegiado foi proferida em sess\u00e3o virtual realizada nesta semana (8\/6).<\/p>\n<p><strong>O caso<\/strong><\/p>\n<p>Segundo a den\u00fancia do Minist\u00e9rio P\u00fablico Federal (MPF), o homem, juntamente com sua fam\u00edlia, operava uma olaria para a produ\u00e7\u00e3o de tijolos de argila em Gramado do Erval, localidade da zona rural do munic\u00edpio de \u00c1gua Santa. O \u00f3rg\u00e3o ministerial alegou que o acusado explorou a mat\u00e9ria-prima pertencente \u00e0 Uni\u00e3o sem a devida autoriza\u00e7\u00e3o legal.<\/p>\n<p>\u201cO denunciado extraiu recurso mineral (argila) sem a competente autoriza\u00e7\u00e3o ou licen\u00e7a ambiental. Ainda, o denunciado fez funcionar estabelecimento potencialmente poluidor, qual seja, uma olaria, sem autoriza\u00e7\u00e3o dos \u00f3rg\u00e3os ambientais competentes\u201d, apontou o MPF.<\/p>\n<p>A den\u00fancia destacou que, em uma fiscaliza\u00e7\u00e3o realizada em janeiro de 2017, a Pol\u00edcia Ambiental da Brigada Militar constatou diversas irregularidades ambientais no processo de extra\u00e7\u00e3o de mat\u00e9ria-prima e fabrica\u00e7\u00e3o de tijolos por parte do agricultor.<\/p>\n<p><strong>Senten\u00e7a<\/strong><\/p>\n<p>Em novembro de 2020, o ju\u00edzo da 3\u00aa Vara Federal de Passo Fundo (RS), ao analisar o caso, fixou a pena em um ano, oito meses e 15 dias de deten\u00e7\u00e3o, sendo substitu\u00edda por duas penas restritivas de direitos, uma delas de presta\u00e7\u00e3o pecuni\u00e1ria de um sal\u00e1rio m\u00ednimo e a outra de presta\u00e7\u00e3o de servi\u00e7os comunit\u00e1rios.<\/p>\n<p>Al\u00e9m disso, o r\u00e9u tamb\u00e9m foi condenado ao pagamento de 22 dias-multa \u00e0 raz\u00e3o unit\u00e1ria de 1\/30 do sal\u00e1rio m\u00ednimo vigente na data da fiscaliza\u00e7\u00e3o da Pol\u00edcia Ambiental.<\/p>\n<p><strong>Decis\u00e3o do colegiado<\/strong><\/p>\n<p>O homem recorreu da senten\u00e7a ao TRF4. No recurso, a defesa pleiteou a absolvi\u00e7\u00e3o do r\u00e9u, alegando a suposta insufici\u00eancia probat\u00f3ria de dolo e materialidade.<\/p>\n<p>Com a apela\u00e7\u00e3o, a decis\u00e3o ficou sob responsabilidade da 7\u00aa Turma do Tribunal. O colegiado votou unanimemente por negar o recurso. No entanto, de of\u00edcio, foi reconhecida a atenuante de confiss\u00e3o do crime por parte do r\u00e9u, reduzindo em parte a pena.<\/p>\n<p>A relatora do caso, desembargadora federal Cl\u00e1udia Cristina Cristofani, ressaltou que \u201cpor ocasi\u00e3o da fiscaliza\u00e7\u00e3o realizada em janeiro de 2017, o recorrente informou ser respons\u00e1vel pela olaria e pela retirada de argila do banhado, e disse que sabia da necessidade das licen\u00e7as, mas que n\u00e3o as possu\u00eda, visto que nunca tinha sido fiscalizado. Tamb\u00e9m, o policial militar testemunha declarou que a \u00e1rea de extra\u00e7\u00e3o da argila estava localizada em APP, um banhado, pr\u00f3ximo \u00e0 olaria\u201d.<\/p>\n<p>\u201cPelo exposto, percebe-se que o r\u00e9u extra\u00eda argila na sua atividade e n\u00e3o terra seca, como defendido pela defesa. Ainda, mostra-se evidente o dolo na conduta perpetrada pelo r\u00e9u, tendo sido robustamente comprovado que o demandado efetuou extra\u00e7\u00e3o e lavra de argila em APP, consistente em banhado, ecossistema esse especialmente protegido pela legisla\u00e7\u00e3o, bem como que o recorrente detinha conhecimento de que a lavra e a extra\u00e7\u00e3o da argila exigia licen\u00e7as e autoriza\u00e7\u00f5es por parte dos \u00f3rg\u00e3os competentes\u201d, complementou Cristofani, fundamentando sua decis\u00e3o de negar o recurso.<\/p>\n<p>Com o resultado do julgamento, a pena privativa de liberdade ficou estabelecida em 1 ano e 4 meses de deten\u00e7\u00e3o, devido ao atenuante da confiss\u00e3o, mantendo-se a substitui\u00e7\u00e3o pelas penas restritivas de direitos. As multas aplicadas n\u00e3o se alteraram.<\/p>\n<p><a href=\"https:\/\/odocumento.com.br\/tribunal-mantem-condenacao-de-produtor-de-tijolos-por-extracao-de-argila-sem-licenca-ambiental\/controlador.php?acao=consulta_processual_resultado_pesquisa&amp;selForma=NU&amp;txtValor=50081486120184047104&amp;selOrigem=TRF&amp;chkMostrarBaixados=1\">N\u00ba 5008148-61.2018.4.04.7104\/TRF<\/a><\/p>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"https:\/\/www.trf4.jus.br\/trf4\/controlador.php?acao=noticia_visualizar&amp;id_noticia=15915#73\" target=\"_blank\" rel=\"noopener\">TRF4<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A 7\u00aa Turma do Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF4), de maneira un\u00e2nime, negou &hellip;<\/p>\n","protected":false},"author":4,"featured_media":39835,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-39834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/39834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=39834"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/39834\/revisions"}],"predecessor-version":[{"id":39836,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/39834\/revisions\/39836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/39835"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=39834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=39834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=39834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}