{"id":40222,"date":"2021-06-18T10:06:58","date_gmt":"2021-06-18T14:06:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=40222"},"modified":"2021-06-18T10:06:58","modified_gmt":"2021-06-18T14:06:58","slug":"soja-e-milho-tem-forte-queda-nos-precos-confira-noticias-desta-sexta","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/soja-e-milho-tem-forte-queda-nos-precos-confira-noticias-desta-sexta\/","title":{"rendered":"Soja e milho t\u00eam forte queda nos pre\u00e7os; confira not\u00edcias desta sexta"},"content":{"rendered":"<ul>\n<li dir=\"ltr\">\n<p dir=\"ltr\">Boi: mercado f\u00edsico tem estabilidade, enquanto futuro segue em baixa<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\">Milho: Chicago cai forte e pre\u00e7o em Campinas (SP) volta a ficar abaixo de R$ 90 por saca<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\">Soja: cota\u00e7\u00f5es despencam em Chicago e pressionam mercado brasileiro<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\">Caf\u00e9: Nova York volta a recuar e carrega pre\u00e7os no Brasil<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\">No Exterior: pedidos de seguro desemprego ficam piores que os projetados nos EUA<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\">No Brasil: bolsa fecha em queda um dia ap\u00f3s Banco Central elevar os juros<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\">Agenda:<\/p>\n<ul>\n<li dir=\"ltr\">\n<p dir=\"ltr\">Argentina: atualiza\u00e7\u00e3o da condi\u00e7\u00e3o das lavouras do pa\u00eds<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\">Brasil: dados das lavouras do Mato Grosso (Imea)<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\">EUA: posi\u00e7\u00e3o l\u00edquida dos fundos no mercado futuro (CFTC)<\/p>\n<\/li>\n<\/ul>\n<h3 dir=\"ltr\">Boi: mercado f\u00edsico tem estabilidade, enquanto futuro segue em baixa<\/h3>\n<p dir=\"ltr\">De acordo com a consultoria Safras &amp; Mercado, a arroba do boi gordo registrou pre\u00e7os est\u00e1veis no mercado f\u00edsico brasileiro. O analista Fernando Iglesias voltou a observar alguns neg\u00f3cios pontuais acima da refer\u00eancia m\u00e9dia das cota\u00e7\u00f5es em algumas regi\u00f5es importantes. Al\u00e9m disso, tamb\u00e9m \u00e9 poss\u00edvel verificar um bom ritmo de embarques de carne bovina, sobretudo para a China, no decorrer do m\u00eas de junho.<\/p>\n<p dir=\"ltr\">Na B3, os contratos futuros do boi gordo recuaram novamente e chegaram \u00e0s m\u00ednimas observadas em abril deste ano, no come\u00e7o do movimento da safra. O ajuste do vencimento para junho passou de R$ 320,50 para R$ 318,30, do outubro foi de R$ 328,70 para R$ 325,15 e do novembro, de R$ 332,05 para R$ 328,45 por arroba.<\/p>\n<div id=\"supertag-ad-vnlumyr01\" data-google-query-id=\"COLTuJOtofECFcEBuQYdU6YBGA\">\n<div id=\"google_ads_iframe_\/21692678505\/Canal_Rural_Display\/BALCAO_RURAL_DESK_0__container__\"><iframe id=\"google_ads_iframe_\/21692678505\/Canal_Rural_Display\/BALCAO_RURAL_DESK_0\" title=\"3rd party ad content\" name=\"google_ads_iframe_\/21692678505\/Canal_Rural_Display\/BALCAO_RURAL_DESK_0\" width=\"728\" height=\"90\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" data-google-container-id=\"1\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<h3 dir=\"ltr\">Milho: Chicago cai forte e pre\u00e7o em Campinas (SP) volta a ficar abaixo de R$ 90 por saca<\/h3>\n<p dir=\"ltr\">O indicador do milho do Cepea teve um dia de baixa dos pre\u00e7os, acompanhando a forte queda em Chicago. A cota\u00e7\u00e3o variou -2,23% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 91,6 para R$ 89,56 por saca. Em Chicago, o vencimento para dezembro recuou 6,99% e passou de US$ 5,724 para US$ 5,324 por bushel.<\/p>\n<p dir=\"ltr\">Os contratos futuros do milho negociados na B3 aumentaram a sequ\u00eancia de baixas com mais uma forte queda influenciada pela expressiva desvaloriza\u00e7\u00e3o observada em Chicago. O ajuste do vencimento para julho passou de R$ 87,16 para R$ 82,80, do setembro caiu de R$ 87,42 para R$ 83,05 e do mar\u00e7o de 2022 recuou de R$ 90,90 para R$ 86,37 por saca.<\/p>\n<h3 dir=\"ltr\">Soja: cota\u00e7\u00f5es despencam em Chicago e pressionam mercado brasileiro<\/h3>\n<p dir=\"ltr\">Em Chicago, os contratos futuros da soja chegaram ao quinto dia consecutivo de queda, com um recuo acumulado no per\u00edodo de 14,17%. O vencimento para novembro caiu 6,75% e passou de US$ 13,432 para US$ 12,526 por bushel. O mercado de commodities foi bastante impactado pela possibilidade de o Banco Central dos Estados Unidos ter que elevar os juros mais cedo que o projetado. Com isso, os investidores buscam posi\u00e7\u00f5es mais seguras e liquidam as que possuem em commodities.<\/p>\n<p dir=\"ltr\">No Brasil, o indicador da soja do Cepea para o porto de Paranagu\u00e1 (PR) ficou muito pr\u00f3ximo de registrar a menor cota\u00e7\u00e3o do ano. A cota\u00e7\u00e3o variou -2,76% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 161,32 para R$ 156,86 por saca. No acumulado do ano, o indicador valorizou 1,92% e em 12 meses, os pre\u00e7os alcan\u00e7aram 41,32% de alta.<\/p>\n<h3 dir=\"ltr\">Caf\u00e9: Nova York volta a recuar e carrega pre\u00e7os no Brasil<\/h3>\n<p dir=\"ltr\">Em Nova York, as cota\u00e7\u00f5es do caf\u00e9 ar\u00e1bica seguiram a tend\u00eancia de outras commodities agr\u00edcolas e recuaram de maneira expressiva, chegando \u00e0s m\u00ednimas em praticamente um m\u00eas. O vencimento para setembro recuou 2,48% na compara\u00e7\u00e3o com o dia anterior e passou de US$ 1,5545 para US$ 1,5160 por libra-peso.<\/p>\n<p dir=\"ltr\">De acordo com a consultoria Safras &amp; Mercado, os pre\u00e7os no Brasil seguiram a queda observada no exterior. No sul de Minas Gerais, o ar\u00e1bica bebida boa com 15% de cata\u00e7\u00e3o caiu de R$ 820\/825 para R$ 800\/805, enquanto que no cerrado mineiro, o bebida dura com 15% de cata\u00e7\u00e3o passou de R$ 830\/835 para R$ 810\/815.<\/p>\n<h3 dir=\"ltr\">No Exterior: pedidos de seguro desemprego ficam piores que os projetados nos EUA<\/h3>\n<p dir=\"ltr\">Um dia ap\u00f3s o Banco Central dos Estados Unidos reafirmar a recupera\u00e7\u00e3o econ\u00f4mica do pa\u00eds, mas pontuar que o mercado de trabalho segue distante dos n\u00edveis \u00f3timos, os pedidos de seguro desemprego ficaram piores que os projetados por analistas de mercado. Os investidores esperavam a continuidade da queda observada nos \u00faltimos resultados, mas foram surpreendidos com um aumento nos pedidos.<\/p>\n<p dir=\"ltr\">Outro destaque no mercado internacional foi a queda do petr\u00f3leo, que seguiu a baixa observada em outras importantes commodities como soja, milho, trigo e caf\u00e9. O barril do tipo Brent teve desvaloriza\u00e7\u00e3o de 1,84% na passagem de dia e ficou cotado a US$ 73,02, logo ap\u00f3s registrar o quinto dia consecutivo de alta e atingir US$ 75.<\/p>\n<h3 dir=\"ltr\">No Brasil: bolsa fecha em queda um dia ap\u00f3s Banco Central elevar os juros<\/h3>\n<p dir=\"ltr\">O Ibovespa fechou em queda um dia depois do Banco Central elevar a taxa Selic para 4,25% ao ano, por\u00e9m, os destaques foram as empresas ligadas \u00e0s commodities. O \u00edndice da bolsa brasileira teve uma baixa de 0,93% na compara\u00e7\u00e3o di\u00e1ria e fechou cotado a 128.057 pontos. O Senado Federal aprovou a MP que viabiliza a privatiza\u00e7\u00e3o da Eletrobras, o texto agora volta \u00e0 C\u00e2mara em virtude das altera\u00e7\u00f5es feitas pelos senadores.<\/p>\n<p dir=\"ltr\">Enquanto isso, o d\u00f3lar comercial fechou em queda de 0,74% e ficou cotado a R$ 5,022. O movimento mostra a tend\u00eancia de for\u00e7a da moeda brasileira nos \u00faltimos meses, pois ap\u00f3s a reuni\u00e3o do Banco Central dos Estados Unidos desta quarta-feira, o d\u00f3lar se fortaleceu em rela\u00e7\u00e3o a grande parte das outras moedas.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">\n<p dir=\"ltr\">Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boi: mercado f\u00edsico tem estabilidade, enquanto futuro segue em baixa Milho: Chicago cai forte e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":40223,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-40222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"As cota\u00e7\u00f5es do gr\u00e3o despencaram no mercado brasileiro acompanhando o tombo na Bolsa de Chicago observado nesta quinta","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/40222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=40222"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/40222\/revisions"}],"predecessor-version":[{"id":40224,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/40222\/revisions\/40224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/40223"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=40222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=40222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=40222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}