{"id":40949,"date":"2021-06-30T14:52:53","date_gmt":"2021-06-30T18:52:53","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=40949"},"modified":"2021-06-30T14:52:53","modified_gmt":"2021-06-30T18:52:53","slug":"governo-de-mt-lanca-operacao-de-reforco-no-combate-aos-incendios-florestais-com-presenca-de-secretario-nacional","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governo-de-mt-lanca-operacao-de-reforco-no-combate-aos-incendios-florestais-com-presenca-de-secretario-nacional\/","title":{"rendered":"Governo de MT lan\u00e7a opera\u00e7\u00e3o de refor\u00e7o no combate aos inc\u00eandios florestais com presen\u00e7a de secret\u00e1rio nacional"},"content":{"rendered":"<p>O governador Mauro Mendes lan\u00e7a nesta quinta-feira (01.07), \u00e0s 8h30, na Pra\u00e7a das Bandeiras, a fase de resposta da Temporada de Inc\u00eandios Florestais (TIF) 2021, per\u00edodo em que haver\u00e1 refor\u00e7o das a\u00e7\u00f5es das for\u00e7as de seguran\u00e7a no combate aos inc\u00eandios florestais e ao desmatamento ilegal em todo o Estado.<\/p>\n<p>O lan\u00e7amento ter\u00e1 a presen\u00e7a do secret\u00e1rio nacional de Seguran\u00e7a P\u00fablica, Carlos Paim, dos secret\u00e1rios de Estado de Seguran\u00e7a P\u00fablica, Alexandre Bustamante, e de Meio Ambiente, Mauren Lazzaretti, al\u00e9m do comandante-geral do Corpo de Bombeiros Militar, Alessandro Borges, e outras autoridades estaduais.<\/p>\n<p>O governador, secret\u00e1rio nacional e secret\u00e1rios de Estado atender\u00e3o a imprensa em entrevista coletiva ap\u00f3s a solenidade.<\/p>\n<p>A Secretaria de Estado de Meio Ambiente (Sema-MT) entregar\u00e1 40 ve\u00edculos locados, sendo 20 para a as equipes da Superintend\u00eancia de Fiscaliza\u00e7\u00e3o para o combate ao desmatamento ilegal, e 20 para a fase de resposta comandada pelo Corpo de Bombeiros Militar com brigadistas em campo nas \u00e1reas com maior incid\u00eancia de focos de calor.<\/p>\n<p>O dia 1\u00ba de julho marca tamb\u00e9m a data em que come\u00e7a o per\u00edodo proibitivo do uso do fogo em Mato Grosso, que foi adiantada por decreto estadual. Com o decreto n\u00ba 938\/2021, fica proibida qualquer atividade de limpeza de pastagem com o uso do fogo nas \u00e1reas rurais at\u00e9 30 de outubro de 2021. O uso do fogo em \u00e1reas urbanas \u00e9 proibido o ano todo.<\/p>\n<p><strong>Servi\u00e7o<\/strong><\/p>\n<p>Governo lan\u00e7a fase de resposta da Temporada de Inc\u00eandios Florestais (TIF) 2021<br \/>\nData e hora: quinta-feira (01.07), \u00e0s 8h30<br \/>\nLocal: Pra\u00e7a das Bandeiras<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Foto:\u00a0 Christiano Antonucci\u00a0 \u00a0 \u00a0|\u00a0 \u00a0 \u00a0Fonte:\u00a0 MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes lan\u00e7a nesta quinta-feira (01.07), \u00e0s 8h30, na Pra\u00e7a das Bandeiras, a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":40950,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-40949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Solenidade ser\u00e1 \u00e0s 8h30, na Pra\u00e7a das Bandeiras","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/40949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=40949"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/40949\/revisions"}],"predecessor-version":[{"id":40951,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/40949\/revisions\/40951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/40950"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=40949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=40949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=40949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}