{"id":41608,"date":"2021-07-09T07:56:09","date_gmt":"2021-07-09T11:56:09","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=41608"},"modified":"2021-07-09T07:56:09","modified_gmt":"2021-07-09T11:56:09","slug":"milho-alta-do-preco-no-acumulado-do-ano-ja-ultrapassa-21-vejas-noticias-dessa-sexta","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/milho-alta-do-preco-no-acumulado-do-ano-ja-ultrapassa-21-vejas-noticias-dessa-sexta\/","title":{"rendered":"Milho: alta do pre\u00e7o no acumulado do ano j\u00e1 ultrapassa 21%; vejas noticias dessa sexta"},"content":{"rendered":"<ul>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">Boi: escalas de abate folgadas geram baixas, diz Safras &amp; Mercado<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">Milho: Campinas (SP) chega ao d\u00e9cimo dia consecutivo de alta<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">Soja: d\u00f3lar impulsiona cota\u00e7\u00f5es no mercado brasileiro<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">Caf\u00e9: pre\u00e7os sobem novamente no Brasil com alta em Nova York<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">No Exterior: avan\u00e7o de casos de Covid-19 preocupa mercados<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">No Brasil: d\u00f3lar tem alta limitada com a\u00e7\u00e3o do Banco Central<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\"><strong>Agenda:<\/strong><\/p>\n<ul>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">Brasil: IPC-S primeira quadrissemana de julho (FGV)<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">Brasil: dados sobre as lavouras do Mato Grosso (Imea)<\/p>\n<\/li>\n<li dir=\"ltr\">\n<p dir=\"ltr\" role=\"presentation\">EUA: exporta\u00e7\u00f5es semanais de gr\u00e3os (USDA)<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\"><strong>Boi: escalas de abate folgadas geram baixas, diz Safras &amp; Mercado<\/strong><\/p>\n<p dir=\"ltr\">De acordo com a consultoria Safras &amp; Mercado, ap\u00f3s mais de duas semanas com escalas de abate confort\u00e1veis, mas com pre\u00e7os est\u00e1veis, o mercado f\u00edsico do boi gordo finalmente teve baixas. Em S\u00e3o Paulo, a arroba passou de R$ 320 para R$ 318, na modalidade a prazo. Ainda assim, o cen\u00e1rio de oferta restrita impede quedas maiores.<\/p>\n<div id=\"supertag-ad-gk6xzbbq4\" data-google-query-id=\"CL_oiJf31fECFXUDuQYd6OoJBQ\">\n<div id=\"google_ads_iframe_\/21692678505\/Canal_Rural_Display\/BALCAO_RURAL_DESK_0__container__\"><iframe id=\"google_ads_iframe_\/21692678505\/Canal_Rural_Display\/BALCAO_RURAL_DESK_0\" title=\"3rd party ad content\" name=\"google_ads_iframe_\/21692678505\/Canal_Rural_Display\/BALCAO_RURAL_DESK_0\" width=\"728\" height=\"90\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" data-google-container-id=\"1\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<p dir=\"ltr\">Na B3, os contratos futuros do boi gordo seguiram o movimento de queda observado no mercado f\u00edsico e tiveram desvaloriza\u00e7\u00e3o. O ajuste do contrato que vence em julho passou de R$ 317,50 para R$ 316,85, do outubro foi de R$ 326,85 para R$ 324,65 e do novembro caiu de R$ 330,05 para R$ 327,85 por arroba.<\/p>\n<p dir=\"ltr\"><strong>Milho: Campinas (SP) chega ao d\u00e9cimo dia consecutivo de alta<\/strong><\/p>\n<p dir=\"ltr\">O indicador do milho do Cepea, calculado com base nos pre\u00e7os praticados em Campinas (SP),chegou ao d\u00e9cimo dia consecutivo de alta. A cota\u00e7\u00e3o variou 0,8% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 95,17 para R$ 95,93 por saca. Portanto, no acumulado do ano, o indicador teve uma alta de 21,97%. Em 12 meses, os pre\u00e7os alcan\u00e7aram 90,45% de valoriza\u00e7\u00e3o.<\/p>\n<p dir=\"ltr\">Na bolsa brasileira, a B3, os contratos futuros do milho subiram pelo segundo dia e seguem acompanhando a tend\u00eancia de valoriza\u00e7\u00e3o observada no mercado f\u00edsico. O ajuste do vencimento para julho passou de R$ 94,10 para R$ 95,25, do setembro foi de R$ 95,54 para R$ 97,28 e do mar\u00e7o\/22 subiu de R$ 97,51 para R$ 98,64 por saca.<\/p>\n<p dir=\"ltr\"><strong>Soja: d\u00f3lar impulsiona cota\u00e7\u00f5es no mercado brasileiro<\/strong><\/p>\n<p dir=\"ltr\">Apesar da queda em Chicago, o indicador da soja do Cepea para o porto de Paranagu\u00e1 (PR) teve um dia de alta dos pre\u00e7os em virtude da valoriza\u00e7\u00e3o do d\u00f3lar. A cota\u00e7\u00e3o variou 1,36% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 164,08 para R$ 166,31 por saca. Dessa forma, no acumulado do ano, o indicador j\u00e1 valorizou 8,06%.<\/p>\n<p dir=\"ltr\">Em Chicago, como dito anteriormente, o preg\u00e3o foi marcado por um dia de baixa das cota\u00e7\u00f5es da soja. O vencimento para novembro recuou 0,59% e passou de US$ 13,272 para US$ 13,194 por bushel. O movimento do dia foi causado pelo aumento da apreens\u00e3o nos mercados globais com o avan\u00e7o de casos de Covid-19 pelo mundo.<\/p>\n<p dir=\"ltr\"><strong>Caf\u00e9: pre\u00e7os sobem novamente no Brasil com alta em Nova York<\/strong><\/p>\n<p dir=\"ltr\">De acordo com a consultoria Safras &amp; Mercado, a alta do ar\u00e1bica em Nova York impulsionou novamente o mercado brasileiro. Al\u00e9m disso, o d\u00f3lar tamb\u00e9m ajudou. No sul de Minas Gerais, o ar\u00e1bica bebida boa com 15% de cata\u00e7\u00e3o ficou passou de R$ 825\/830 para R$ 830\/835, enquanto que no cerrado mineiro, o bebida dura com 15% de cata\u00e7\u00e3o foi de R$ 830\/835 para R$ 835\/840 por saca.<\/p>\n<p dir=\"ltr\">Como dito anteriormente, o caf\u00e9 ar\u00e1bica negociado na bolsa de Nova York subiu pelo segundo dia consecutivo e voltou a superar o n\u00edvel de US$ 1,50 por libra-peso. O vencimento para setembro subiu 1,53% e passou de US$ 1,4995 para US$ 1,5225. O mercado segue travado por fatores t\u00e9cnicos relacionados \u00e0s posi\u00e7\u00f5es dos fundos e busca decidir se consegue romper o intervalo entre US$ 1,50 e US$ 1,60 por libra-peso.<\/p>\n<p dir=\"ltr\"><strong>No Exterior: avan\u00e7o de casos de Covid-19 preocupa mercados<\/strong><\/p>\n<p dir=\"ltr\">A preocupa\u00e7\u00e3o com o avan\u00e7o de casos de Covid-19 causado pela variante Delta gerou um dia de baixas nos mercados globais. Com a recupera\u00e7\u00e3o econ\u00f4mica ainda em diferentes n\u00edveis entre os pa\u00edses, o medo dos investidores \u00e9 que algumas localidades precisem adotar novas medidas de restri\u00e7\u00e3o \u00e0 circula\u00e7\u00e3o de pessoas, mesmo com a vacina\u00e7\u00e3o avan\u00e7ada.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, os dados de pedidos de seguro-desemprego nos EUA surpreenderam negativamente os investidores. Houve um aumento de pedidos em rela\u00e7\u00e3o \u00e0 semana anterior, enquanto que as proje\u00e7\u00f5es esperavam uma nova queda, seguindo a tend\u00eancia dos \u00faltimos resultados. Dessa forma, estes n\u00fameros se somaram aos de servi\u00e7os divulgados durante a semana e lan\u00e7am d\u00favidas quanto \u00e0 velocidade de recupera\u00e7\u00e3o da economia nos Estados Unidos.<\/p>\n<p dir=\"ltr\"><strong>No Brasil: bolsa se recupera seguindo EUA; d\u00f3lar sobe novamente<\/strong><\/p>\n<p dir=\"ltr\">O d\u00f3lar subiu pela oitava sess\u00e3o consecutiva, por\u00e9m, a alta foi limitada pelo leil\u00e3o de swaps cambiais do Banco Central. A moeda norte-americana subiu 0,29% e fechou o dia cotada a R$ 5,255. Enquanto isso, a bolsa brasileira teve um dia de desvaloriza\u00e7\u00e3o em virtude de press\u00f5es do exterior. O Ibovespa caiu 1,25% e ficou cotado a 125.427 pontos.<\/p>\n<p dir=\"ltr\">O IPCA de junho divulgado pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) ficou abaixo do projetado pelos analistas de mercado. O indicador apresentou desacelera\u00e7\u00e3o e passou de 0,83% em maio para 0,53% em junho. Com isso, no ano, o IPCA acumula uma alta de 3,77% e de 8,35% nos \u00faltimos 12 meses.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">\n<p dir=\"ltr\">\n<p dir=\"ltr\">Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boi: escalas de abate folgadas geram baixas, diz Safras &amp; Mercado Milho: Campinas (SP) chega &hellip;<\/p>\n","protected":false},"author":4,"featured_media":41609,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-41608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"De acordo com o Cepea, os pre\u00e7os praticados em Campinas (SP), chegou ao d\u00e9cimo dia consecutivo de alta nesta quinta, 8","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/41608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=41608"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/41608\/revisions"}],"predecessor-version":[{"id":41610,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/41608\/revisions\/41610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/41609"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=41608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=41608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=41608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}