{"id":66283,"date":"2023-01-16T14:38:27","date_gmt":"2023-01-16T18:38:27","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=66283"},"modified":"2023-01-16T14:38:27","modified_gmt":"2023-01-16T18:38:27","slug":"precos-da-carne-suina-e-de-frango-caem-nos-primeiros-dias-de-janeiro","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/precos-da-carne-suina-e-de-frango-caem-nos-primeiros-dias-de-janeiro\/","title":{"rendered":"Pre\u00e7os da carne su\u00edna e de frango caem nos primeiros dias de janeiro"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Como planejar a sucess\u00e3o familiar entre pais e filhos no campo? | Ligados&amp;Integrados  - 12\/01\/2023\" src=\"https:\/\/www.youtube.com\/embed\/rxb1TvL2bVM?feature=oembed\" width=\"500\" height=\"281\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>Os pre\u00e7os do su\u00edno no mercado independente v\u00eam registrando queda. A principal raz\u00e3o \u00e9 a demanda dom\u00e9stica enfraquecida, que tem pressionado as cota\u00e7\u00f5es tanto da carne quanto do animal vivo.<\/p>\n<p>Um cen\u00e1rio desafiador para os produtores independentes, j\u00e1 que os pre\u00e7os dos insumos para a produ\u00e7\u00e3o, como milho e farelo de soja, subiram.\u00a0 Luiz Melo, analista de mercados do Cepea (Centro de Estudos Avan\u00e7ados em Economia Aplicada da Esalq\/USP), analisa os cen\u00e1rios da avicultura e da suinocultura neste in\u00edcio de m\u00eas. Confira a entrevista.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 CanalRural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os pre\u00e7os do su\u00edno no mercado independente v\u00eam registrando queda. A principal raz\u00e3o \u00e9 a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":66284,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-66283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Demanda dom\u00e9stica enfraquecida est\u00e1 atrelada ao menor poder de compra da popula\u00e7\u00e3o em in\u00edcio o de an","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/66283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=66283"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/66283\/revisions"}],"predecessor-version":[{"id":66285,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/66283\/revisions\/66285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/66284"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=66283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=66283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=66283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}