{"id":70693,"date":"2023-05-30T16:08:06","date_gmt":"2023-05-30T20:08:06","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=70693"},"modified":"2023-05-30T16:08:06","modified_gmt":"2023-05-30T20:08:06","slug":"natureza-na-veia-moringa-arvore-da-vida","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/natureza-na-veia-moringa-arvore-da-vida\/","title":{"rendered":"NATUREZA NA VEIA \u2013 Moringa, \u00e1rvore da vida"},"content":{"rendered":"<p><strong>Por Ademir Galitzkt<\/strong><\/p>\n<p>Surgiu na \u00cdndia por volta de 1920. N\u00e3o se trata daquela moringa que geralmente usamos para colocar \u00e1gua. \u00c9 uma esp\u00e9cie de \u00e1rvore, conhecida como a \u00e1rvore da vida, que por volta de 1943, era o \u00fanico alimento na cidade de Bengala, na \u00cdndia. Morreu de 3,5 a 4,5 milh\u00f5es de pessoas, na grande fome que assolou o mundo, a maioria dessas pessoas eram indianas.<\/p>\n<p>Tradicionalmente, pode se usar da moringa as folhas, as sementes, as cascas, as flores e at\u00e9 as ra\u00edzes s\u00e3o usadas \u2013 como alimento. Para restaurar a sa\u00fade do ser humano, devido \u00e0s suas qualidades terap\u00eauticas, e pelas prote\u00ednas e sais minerais e riqueza em amino\u00e1cidos, ela tamb\u00e9m tem uma quantidade significativa de vitaminas, como vitamina C, b1, b2, b3 e b6. Na moringa tamb\u00e9m encontramos c\u00e1lcio, f\u00f3sforo, pot\u00e1ssio, ferro, magn\u00e9sio, zinco e pouca gordura. O que tem ajudado a prevenir e curar v\u00e1rias doen\u00e7as, como problemas de f\u00edgado, diabetes, prote\u00e7\u00e3o para os olhos, melhora a sa\u00fade cardiovascular, problemas nos ossos, \u00f3tima na cicatriza\u00e7\u00e3o de feridas, para cabelos e pele, al\u00e9m de possuir a\u00e7\u00f5es antibacterianas, anti-inflamat\u00f3rias, antif\u00fangicas.<\/p>\n<p>Algumas pesquisas apontam que na composi\u00e7\u00e3o da moringa h\u00e1 mais de 100 vitaminas e ela auxilia no combate de mais de 300 doen\u00e7as. Inclusive, foi por acaso que se descobriu que a moringa poderia ser usada como alimento. Alguns animais comiam as folhas da \u00e1rvore, j\u00e1 que n\u00e3o havia muitas op\u00e7\u00f5es de alimento, durante a grande fome. Nesse momento, perceberam que as vacas estavam bem nutridas e aparentavam sinais de fome. Pesquisando mais afundo para ver o que elas comiam, perceberam que se alimentavam das folhas da parte baixa das \u00e1rvores de moringa. Hoje h\u00e1 planta\u00e7\u00f5es de moringa em todas as partes do mundo, mas poucas pessoas possuem o conhecimento desta fa\u00e7anha. Em compara\u00e7\u00e3o com outros alimentos, a moringa possui vinte vezes mais c\u00e1lcio que o leite, vinte e cinco mais ferro que o espinafre, dez vezes mais prote\u00edna e vitamina que a cenoura, dez vezes mais prote\u00edna que os iogurtes em geral, duas vezes mais prote\u00edna que o ovo e duas vezes mais vitamina C que a laranja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ademir Galitzkt Surgiu na \u00cdndia por volta de 1920. N\u00e3o se trata daquela moringa &hellip;<\/p>\n","protected":false},"author":4,"featured_media":70694,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-70693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/70693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=70693"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/70693\/revisions"}],"predecessor-version":[{"id":70695,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/70693\/revisions\/70695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/70694"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=70693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=70693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=70693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}