{"id":72170,"date":"2023-07-27T09:01:04","date_gmt":"2023-07-27T13:01:04","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=72170"},"modified":"2023-07-27T09:01:04","modified_gmt":"2023-07-27T13:01:04","slug":"resultados-dos-impactos-socioeconomicos-da-recuperacao-de-pastagens-em-mt-serao-apresentados","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/resultados-dos-impactos-socioeconomicos-da-recuperacao-de-pastagens-em-mt-serao-apresentados\/","title":{"rendered":"Resultados dos impactos socioecon\u00f4micos da recupera\u00e7\u00e3o de pastagens em MT ser\u00e3o apresentados"},"content":{"rendered":"<p>Os primeiros resultados da avalia\u00e7\u00e3o de impactos da integra\u00e7\u00e3o lavoura-pecu\u00e1ria na recupera\u00e7\u00e3o de pastagens degradadas em Mato Grosso e os impactos de pol\u00edticas p\u00fablicos como o Plano ABC+, que visam reduzir as emiss\u00f5es de gases de efeito estufa pela agropecu\u00e1ria, ser\u00e3o debatidos no Semin\u00e1rio \u201cImpactos socioecon\u00f4micos da recupera\u00e7\u00e3o de pastagens degradadas em Mato Grosso\u201d.<\/p>\n<p>O evento \u00e9 promovido pelo Grupo de Pol\u00edticas P\u00fablicas da Esalq-USP, pelo Programa das Na\u00e7\u00f5es Unidas para Meio Ambiente (PNUMA), pelo Programa ABC+ Mato Grosso e pela Embrapa. O evento vai ocorrer na sede da Embrapa Agrossilvipastoril, em Sinop, e ser\u00e1 realizada na pr\u00f3pria institui\u00e7\u00e3o na quarta-feira (2), a partir das 8 horas.<\/p>\n<p>O semin\u00e1rio \u00e9 gratuito e tem como p\u00fablico profissionais ligados \u00e0s pol\u00edticas p\u00fablicas, t\u00e9cnicos e extensionistas, pesquisadores, agentes p\u00fablicos e representantes de entidades do setor produtivo.<\/p>\n<p>A programa\u00e7\u00e3o do semin\u00e1rio contar\u00e1 inicialmente com uma apresenta\u00e7\u00e3o do Plano ABC+ MT e do projeto TEEB Agricultura de Alimentos. Na sequ\u00eancia ser\u00e1 feita a apresenta\u00e7\u00e3o dos impactos socioecon\u00f4micos da recupera\u00e7\u00e3o de pastagens em Mato Grosso e, em seguida, haver\u00e1 espa\u00e7o para discuss\u00e3o com os participantes sobre os m\u00e9todos e resultados apresentados.<\/p>\n<p>O encerramento ser\u00e1 \u00e0s 12h.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 ODOC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os primeiros resultados da avalia\u00e7\u00e3o de impactos da integra\u00e7\u00e3o lavoura-pecu\u00e1ria na recupera\u00e7\u00e3o de pastagens degradadas &hellip;<\/p>\n","protected":false},"author":4,"featured_media":72171,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-72170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Resultados ser\u00e3o conhecidos na quarta-feira em evento da Embrapa, em Sinop","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/72170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=72170"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/72170\/revisions"}],"predecessor-version":[{"id":72172,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/72170\/revisions\/72172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/72171"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=72170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=72170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=72170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}