{"id":72212,"date":"2023-07-28T10:35:25","date_gmt":"2023-07-28T14:35:25","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=72212"},"modified":"2023-07-28T10:35:25","modified_gmt":"2023-07-28T14:35:25","slug":"mt-gera-106-mil-vagas-de-empregos-com-carteira-assinada-em-junho-maior-saldo-do-centro-oeste","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mt-gera-106-mil-vagas-de-empregos-com-carteira-assinada-em-junho-maior-saldo-do-centro-oeste\/","title":{"rendered":"MT gera 10,6 mil vagas de empregos com carteira assinada em junho, maior saldo do Centro-Oeste"},"content":{"rendered":"<p>O estado de Mato Grosso teve um saldo de 10,6 mil empregos com carteira assinada no m\u00eas de junho. No per\u00edodo, foram registradas 55,3 mil admiss\u00f5es e 44,6 mil demiss\u00f5es. \u00c9 o maior saldo registrado na regi\u00e3o Centro-Oeste. Os dados do novo Cadastro Geral de Empregados e Desempregados (Novo Caged) foram divulgados nesta quinta-feira, 27\/7, pelo Minist\u00e9rio do Trabalho e Emprego.<\/p>\n<p>Nos primeiros seis meses de 2023, houve 324,4 mil admiss\u00f5es e 284,3 mil demiss\u00f5es no estado, resultado positivo de 40,1 mil vagas formais. Levando em conta os \u00faltimos 12 meses, Mato Grosso acumula 44,7 mil empregos criados com carteira assinada. Isso indica que 89,7% do saldo de novos empregos formais no estado nos \u00faltimos 12 meses \u00e9 composto por vagas criadas em 2023.<\/p>\n<p>Os cinco setores de economia avaliados pelo Caged tiveram saldo positivo de vagas de emprego formal em junho de 2023 no Mato Grosso. O destaque no estado foi a agropecu\u00e1ria, com 11 mil admiss\u00f5es e 6.308 desligamentos registrados, em um saldo de 4.777. Na sequ\u00eancia aparecem os setores de Servi\u00e7os (2.540), Ind\u00fastria (1.178), Com\u00e9rcio (1.150) e Constru\u00e7\u00e3o (1.038).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 ODOC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O estado de Mato Grosso teve um saldo de 10,6 mil empregos com carteira assinada &hellip;<\/p>\n","protected":false},"author":4,"featured_media":72213,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-72212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"O destaque no estado foi a agropecu\u00e1ria, com 11 mil admiss\u00f5es e 6.308 desligamentos registrados, em um saldo de 4.777","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/72212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=72212"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/72212\/revisions"}],"predecessor-version":[{"id":72214,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/72212\/revisions\/72214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/72213"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=72212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=72212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=72212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}