{"id":74092,"date":"2023-10-03T12:31:53","date_gmt":"2023-10-03T16:31:53","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=74092"},"modified":"2023-10-03T12:31:53","modified_gmt":"2023-10-03T16:31:53","slug":"preco-pago-ao-produtor-de-leite-em-mato-grosso-recua-e-atinge-menor-valor-dos-ultimos-tres-anos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/preco-pago-ao-produtor-de-leite-em-mato-grosso-recua-e-atinge-menor-valor-dos-ultimos-tres-anos\/","title":{"rendered":"Pre\u00e7o pago ao produtor de leite em Mato Grosso recua e atinge menor valor dos \u00faltimos tr\u00eas anos"},"content":{"rendered":"<p>O pre\u00e7o do leite pago ao produtor de Mato Grosso pelo leite captado em agosto fechou em R$ 2,12, valor 24,17% menor do que se pagava h\u00e1 um ano. Para se ter uma ideia de como est\u00e1 dif\u00edcil para os produtores fecharem as contas, a cota\u00e7\u00e3o do leite captado em agosto \u00e9 10,17% inferior \u00e0 m\u00e9dia paga ao produtor nos \u00faltimos 3 anos em agosto.<\/p>\n<p>Conforme o boletim do leite, do Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea), esse movimento refor\u00e7a o cen\u00e1rio at\u00edpico de retra\u00e7\u00e3o durante a entressafra.<\/p>\n<p>Uma das explica\u00e7\u00f5es dos baixos pre\u00e7os nos latic\u00ednios e at\u00e9 mesmo no supermercado mesmo na entressafra, \u00e9 a concorr\u00eancia no Brasil de leite oriundos de outros pa\u00edses que abastecem as g\u00f4ndolas dos supermercados e padarias.<\/p>\n<p>Na segunda-feira (2), as equipes t\u00e9cnicas do Mapa e do Minist\u00e9rio do Desenvolvimento Agr\u00e1rio e Agricultura Familiar (MDA) se reuniram com o ministro da Fazenda, Fernando Haddad, para tratar de uma medida tribut\u00e1ria para aumentar a competitividade da cadeia produtiva do leite brasileira.<\/p>\n<p>\u201cO governo nunca foi displicente. Nossas equipes trabalharam intensamente durante todo o fim de semana em busca da solu\u00e7\u00e3o para que possamos dar uma resposta efetiva para este setor t\u00e3o importante da nossa economia. A minha mensagem \u00e9 de comprometimento\u201d, destacou o ministro da Agricultura e Pecu\u00e1ria, Carlos F\u00e1varo.<\/p>\n<p>Importa\u00e7\u00e3o do leite e subven\u00e7\u00e3o aos produtores brasileiros<\/p>\n<p>Desde os decretos editados em 2022 que permitiram o aumento da importa\u00e7\u00e3o de leite e seus derivados, a cadeia produtiva do leite alcan\u00e7ou, neste ano, uma situa\u00e7\u00e3o emergencial que vem sendo enfrentada pelo Governo Federal com diversas medidas adotadas de junho para c\u00e1.<\/p>\n<p>As primeiras delas foram a revoga\u00e7\u00e3o das medidas, num trabalho da C\u00e2mara de Com\u00e9rcio Exterior (Camex), e a intensifica\u00e7\u00e3o da fiscaliza\u00e7\u00e3o de poss\u00edveis pr\u00e1ticas ilegais, ou seja, uma esp\u00e9cie de triangula\u00e7\u00e3o, trazendo ao Brasil, produtos de fora do Mercosul.<\/p>\n<p>Al\u00e9m da compra de leite em p\u00f3 por meio da Companhia Nacional de Abastecimento (Conab), cujo prazo da chamada p\u00fablica se encerra no pr\u00f3ximo dia 10 para aquisi\u00e7\u00e3o de at\u00e9 R$ 100 milh\u00f5es do produto que ser\u00e1 distribu\u00eddo \u00e0s redes de assist\u00eancia social, o Minist\u00e9rio da Agricultura e Pecu\u00e1ria (Mapa), apresentou a proposta de subven\u00e7\u00e3o econ\u00f4mica aos produtores de leite.<\/p>\n<p>De acordo com o secret\u00e1rio-executivo do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, M\u00e1rcio Elias Rosa, a partir de agosto do ano passado que as importa\u00e7\u00f5es saltaram de cerca de 5 toneladas para 14 toneladas, mas desde junho, o Brasil j\u00e1 vem registrando quedas expressivas nas importa\u00e7\u00f5es, em torno de 25%, fruto das medidas adotadas com urg\u00eancia e responsabilidade pelo governo federal.<\/p>\n<p>F\u00e1varo ponderou que a rela\u00e7\u00e3o comercial com o Mercosul \u00e9 muito positiva para o Brasil, mas que todas as a\u00e7\u00f5es est\u00e3o sendo observadas pelo governo, dentro das regras, para que os produtores de leite n\u00e3o sejam mais prejudicados.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 ODOC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pre\u00e7o do leite pago ao produtor de Mato Grosso pelo leite captado em agosto &hellip;<\/p>\n","protected":false},"author":4,"featured_media":74093,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-74092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Uma das explica\u00e7\u00f5es dos baixos pre\u00e7os \u00e9 a concorr\u00eancia no Brasil de leite oriundos de outros pa\u00edses","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=74092"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74092\/revisions"}],"predecessor-version":[{"id":74094,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74092\/revisions\/74094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/74093"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=74092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=74092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=74092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}