{"id":74111,"date":"2023-10-04T08:54:34","date_gmt":"2023-10-04T12:54:34","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=74111"},"modified":"2023-10-04T08:54:34","modified_gmt":"2023-10-04T12:54:34","slug":"programa-de-armazenagem-mostra-viabilidade-para-produtores-que-tem-mais-de-350-hectares-de-graos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/programa-de-armazenagem-mostra-viabilidade-para-produtores-que-tem-mais-de-350-hectares-de-graos\/","title":{"rendered":"Programa de armazenagem mostra viabilidade para produtores que t\u00eam mais de 350 hectares de gr\u00e3os"},"content":{"rendered":"<p>O programa Armaz\u00e9m para Todos, de iniciativa da Associa\u00e7\u00e3o de Produtores de Soja e Milho (Aprosoja) aponta que os pequenos produtores de gr\u00e3os, que plantam acima de 350 hectares t\u00eam viabilidade financeira em investir em armazenagem pr\u00f3pria na fazenda. O d\u00e9ficit da armazenagem \u00e9 um dos principais gargalos da agricultura de Mato Grosso.<\/p>\n<p>\u201cEssa narrativa de que o pequeno produtor n\u00e3o teria viabilidade para construir a armazenagem dentro da sua fazenda foi desmistificada com a campanha Armaz\u00e9m para Todos. N\u00f3s constru\u00edmos dentro do nosso site um simulador onde o produtor insere os seus dados da \u00e1rea, tamanho de propriedade, e ele consegue ver se ele tem viabilidade para esse tipo de investimento ou n\u00e3o\u201d, explicou o diretor-executivo da Aprosoja, Wellington Rodrigues de Andrade.<\/p>\n<p>Ele destaca que nos Estados Unidos, principal concorrente da soja mato-grossense, todo produtor rural tem um armaz\u00e9m dentro da sua fazenda proporcional ao tamanho da sua produ\u00e7\u00e3o. Num primeiro momento, eles detectaram que os que possuem acima de 350 hectares, o investimento vale a pena.<\/p>\n<p>Wellington destaca que embora os volumes expressivos de R$ 440 bilh\u00f5es no Plano Safra 2023\/2024, e parte pode ser utilizada para investir em armazenamento, boa parte dos produtores rurais n\u00e3o conseguem acessar os recursos pelo acesso burocr\u00e1tico ao cr\u00e9dito.<\/p>\n<p>\u201cH\u00e1 uma dificuldade de acesso ao cr\u00e9dito, s\u00e3o poucos tomadores que est\u00e3o acessando o cr\u00e9dito e a maioria dos produtores ficam sem acessar. Al\u00e9m disso o pre\u00e7o atual da infraestrutura com concreto, a\u00e7o para fazer os armaz\u00e9ns. Os desafios s\u00e3o grandes, a pol\u00edtica p\u00fablica do governo \u00e9 necess\u00e1ria, principalmente com subs\u00eddios de juros para esse tipo de investimento, que \u00e9 um investimento de longo prazo e traz seguran\u00e7a, n\u00e3o s\u00f3 alimentar, mas para o produtor tamb\u00e9m dentro da fazenda\u201d.<\/p>\n<p>Para o produtor rural de Campo Verde, Fernando Ferri, que produz soja, milho e feij\u00e3o, vale a pena investir em armaz\u00e9m pr\u00f3prio. \u201cEu consigo programar minha colheita, porque sei que tenho capacidade de colheita, recebimento e armazenagem. \u00c9 um investimento que se paga f\u00e1cil na propriedade, o estudo que eu tinha feito era para nove anos e ele se pagou com seis anos\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 ODOC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O programa Armaz\u00e9m para Todos, de iniciativa da Associa\u00e7\u00e3o de Produtores de Soja e Milho &hellip;<\/p>\n","protected":false},"author":4,"featured_media":74112,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-74111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"D\u00e9ficit da armazenagem \u00e9 um dos principais gargalos da agricultura de Mato Grosso","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=74111"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74111\/revisions"}],"predecessor-version":[{"id":74113,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74111\/revisions\/74113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/74112"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=74111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=74111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=74111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}