{"id":74924,"date":"2023-11-09T09:22:03","date_gmt":"2023-11-09T13:22:03","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=74924"},"modified":"2023-11-09T09:22:03","modified_gmt":"2023-11-09T13:22:03","slug":"nova-onda-de-calor-preocupa-produtores-e-embrapa-recomenda-o-sistema-lavoura-pecuaria-floresta","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/nova-onda-de-calor-preocupa-produtores-e-embrapa-recomenda-o-sistema-lavoura-pecuaria-floresta\/","title":{"rendered":"Nova onda de calor preocupa produtores e Embrapa recomenda o sistema Lavoura-Pecu\u00e1ria-Floresta"},"content":{"rendered":"<div class=\"flex flex-grow flex-col max-w-full gap-3 gizmo:gap-0\">\n<div class=\"min-h-[20px] text-message peer flex flex-col items-start gap-3 whitespace-pre-wrap break-words peer-[.text-message]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"8c0d1285-57f6-4c3c-abde-5d46c08f20b1\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>O Instituto Nacional de Meteorologia (Inmet) emitiu um alerta de perigo para cinco estados por causa de uma nova onda de calor, que deve elevar as temperaturas acima de 42 graus no Centro-Oeste, com \u00eanfase em S\u00e3o Paulo, Minas Gerais, Mato Grosso, Mato Grosso do Sul e Goi\u00e1s.<\/p>\n<p>As previs\u00f5es de temperaturas elevadas para o ver\u00e3o que se aproxima preocupa os produtores j\u00e1 quem podem resultar na perda de colheitas, degradar o solo e causar estresse t\u00e9rmico nos animais.<\/p>\n<p>A Empresa Brasileira de Pesquisa Agropecu\u00e1ria (Embrapa), alerta que o setor agropecu\u00e1rio brasileiro precisa se preocupar e recomenda que a melhor forma de mitigar os impactos no setor \u00e9 a utiliza\u00e7\u00e3o do Sistema de Integra\u00e7\u00e3o Lavoura-Pecu\u00e1ria-Floresta (ILPF), o que tamb\u00e9m promove o aumento da produtividade.<\/p>\n<p>Conforme a Embrapa, os benef\u00edcios ambientais do ILPF incluem a melhoria dos nutrientes no solo, o bem-estar dos animais e a preserva\u00e7\u00e3o dos recursos naturais, al\u00e9m dos ganhos proporcionados pelo cultivo de alimentos saud\u00e1veis. Do ponto de vista econ\u00f4mico, essa t\u00e9cnica impulsiona a produ\u00e7\u00e3o de gr\u00e3os, fibras, carne e leite, gerando empregos diretos e indiretos e contribuindo para a renda dos produtores.<\/p>\n<p>No ILPF, ocorre a integra\u00e7\u00e3o harmoniosa entre culturas agr\u00edcolas, pecu\u00e1rias e florestais na mesma \u00e1rea, principalmente por meio de cultivos rotacionados. Os pecuaristas dividem a propriedade em v\u00e1rias partes menores, chamadas de \u201cpiquetes\u201d, por meio de cercas, principalmente el\u00e9tricas, permitindo que os bovinos alternem entre essas \u00e1reas.<\/p>\n<p>Para garantir a efic\u00e1cia dessa integra\u00e7\u00e3o, segundo a Embrapa, \u00e9 essencial que o produtor adote o plantio direto com milho e pasto simult\u00e2neos no in\u00edcio do per\u00edodo de chuvas. Ap\u00f3s a colheita do milho, os animais s\u00e3o introduzidos, estabelecendo uma rota\u00e7\u00e3o cont\u00ednua entre bovinos e culturas agr\u00edcolas, sempre aguardando a recupera\u00e7\u00e3o do pasto antes de retornar com os animais a determinada \u00e1rea.<\/p>\n<p>A qualidade do cercamento \u00e9 crucial nesse sistema, dividindo a propriedade em piquetes e mantendo os animais afastados durante o per\u00edodo de lavoura. Cercas el\u00e9tricas s\u00e3o altamente recomendadas, pois reduzem os custos de manuten\u00e7\u00e3o e implanta\u00e7\u00e3o, possibilitando um maior espa\u00e7amento entre os mour\u00f5es e proporcionando uma excelente rela\u00e7\u00e3o custo-benef\u00edcio.<\/p>\n<p>Ao investir em cercamento de qualidade para o ILPF, os produtores n\u00e3o apenas garantem a preserva\u00e7\u00e3o dos recursos naturais, mas tamb\u00e9m contribuem para a mitiga\u00e7\u00e3o das emiss\u00f5es de gases do efeito estufa, unindo o setor produtivo em benef\u00edcio do agroneg\u00f3cio e do planeta.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u187feae22f40e236a02f0dfb49efe47f-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0<span class=\"postTitle\">Criado plano de desenvolvimento para o \u201cmatopiba\u201d. Regi\u00e3o deve atingir 48 milh\u00f5es de toneladas em 10 anos<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Com informa\u00e7\u00f5es de\u00a0<strong>O Presente Rural<\/strong><\/p>\n<\/div>\n<\/div>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/nova-onda-de-calor-preocupa-produtores-e-embrapa-recomenda-o-sistema-lavoura-pecuaria-floresta\/#0359647f-8cdd-444c-b944-f07e2e1e9ab4\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Nacional de Meteorologia (Inmet) emitiu um alerta de perigo para cinco estados por &hellip;<\/p>\n","protected":false},"author":4,"featured_media":74925,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-74924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=74924"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74924\/revisions"}],"predecessor-version":[{"id":74926,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/74924\/revisions\/74926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/74925"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=74924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=74924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=74924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}