{"id":77107,"date":"2024-02-09T09:17:02","date_gmt":"2024-02-09T13:17:02","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=77107"},"modified":"2024-02-09T09:17:02","modified_gmt":"2024-02-09T13:17:02","slug":"governo-cria-linha-de-credito-emergencial-para-o-nordeste-e-o-norte-de-minas-gerais","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governo-cria-linha-de-credito-emergencial-para-o-nordeste-e-o-norte-de-minas-gerais\/","title":{"rendered":"Governo cria linha de cr\u00e9dito emergencial para o Nordeste e o norte de Minas Gerais"},"content":{"rendered":"<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"b10f2758-5b84-4599-89eb-459453bee619\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>O Minist\u00e9rio do Desenvolvimento Agr\u00e1rio anunciou a implementa\u00e7\u00e3o de uma nova linha de cr\u00e9dito emergencial destinada ao custeio pecu\u00e1rio, com foco no atendimento de 130 mil agricultores familiares nas regi\u00f5es Nordeste e norte de Minas Gerais. A medida foi formalizada por meio de uma resolu\u00e7\u00e3o aprovada pelo Conselho Monet\u00e1rio Nacional (CMN) na \u00faltima quarta-feira (07.02).<\/p>\n<p>Al\u00e9m da linha de cr\u00e9dito, uma outra resolu\u00e7\u00e3o do CMN autoriza a renegocia\u00e7\u00e3o de d\u00edvidas de custeio e investimentos para produtores dessas regi\u00f5es, podendo abranger at\u00e9 586 mil contratos, envolvendo um montante de at\u00e9 R$ 8,2 bilh\u00f5es em d\u00e9bitos.<\/p>\n<p>A operacionaliza\u00e7\u00e3o da linha emergencial ser\u00e1 conduzida pelo Banco do Nordeste (BNB), utilizando recursos do Fundo Constitucional de Financiamento do Nordeste (FNE). A iniciativa visa beneficiar os agricultores que enfrentaram perdas na produ\u00e7\u00e3o devido \u00e0s condi\u00e7\u00f5es de seca na regi\u00e3o.<\/p>\n<p>A linha de cr\u00e9dito emergencial n\u00e3o possui um limite espec\u00edfico, ficando condicionada \u00e0s disponibilidades de recursos programados do FNE para o ano corrente. A taxa de juros varia de 0,5% a at\u00e9 8,01% ao ano, com prazo de pagamento estendido para cinco anos, incluindo um per\u00edodo de car\u00eancia de 12 meses.<\/p>\n<p>O cr\u00e9dito destina-se ao custeio pecu\u00e1rio, abrangendo a alimenta\u00e7\u00e3o do rebanho, recupera\u00e7\u00e3o ou preserva\u00e7\u00e3o das atividades pecu\u00e1rias, sendo vedada a aquisi\u00e7\u00e3o de animais com os recursos.<\/p>\n<p>Durante um evento em Belo Horizonte (MG), que contou com a participa\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva, foram apresentados detalhes sobre o cr\u00e9dito de custeio pecu\u00e1rio. Os valores variam de R$ 10 mil a R$ 80 mil.<\/p>\n<p>No caso da renegocia\u00e7\u00e3o de d\u00edvidas, ficou autorizado o perd\u00e3o de at\u00e9 100% das d\u00edvidas para todos os agricultores que acessaram cr\u00e9dito por meio do FNE via Banco do Nordeste. Essa condi\u00e7\u00e3o abrange aqueles que possuem parcelas vencidas e vincendas no per\u00edodo de 1\u00ba de julho de 2023 a 30 de dezembro de 2024.<\/p>\n<p>As condi\u00e7\u00f5es aplicam-se a empreendimentos que sofreram preju\u00edzos decorrentes de seca ou estiagem em munic\u00edpios sob a \u00e1rea de atua\u00e7\u00e3o da Superintend\u00eancia de Desenvolvimento do Nordeste (Sudene) no per\u00edodo de 1\u00b0 de junho de 2023 at\u00e9 a data de publica\u00e7\u00e3o do decreto.<\/p>\n<p>Al\u00e9m dessas medidas, o governo j\u00e1 havia anunciado outras a\u00e7\u00f5es para auxiliar os agricultores, como o pagamento do Garantia-Safra, no valor de R$ 1,2 mil em parcela \u00fanica, beneficiando mais de 790 mil fam\u00edlias.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"ue730cc640d3006fc4e0e7e39f594d717-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0<span class=\"postTitle\">Conab faz leil\u00e3o de frete para levar milho de Goi\u00e1s para a Bahia<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Tamb\u00e9m foram destinados recursos para assist\u00eancia t\u00e9cnica e extens\u00e3o rural, assim como a venda subsidiada de 86,3 mil toneladas de milho pela Conab para apoiar pequenos criadores de animais na regi\u00e3o, beneficiando cerca de 44 mil pecuaristas. O investimento total nessas iniciativas ser\u00e1 de R$ 68,8 milh\u00f5es.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/governo-cria-linha-de-credito-emergencial-para-o-nordeste-e-o-norte-de-minas-gerais\/#25995d1d-ef78-4098-8c37-3f32ad45b69a\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio do Desenvolvimento Agr\u00e1rio anunciou a implementa\u00e7\u00e3o de uma nova linha de cr\u00e9dito emergencial &hellip;<\/p>\n","protected":false},"author":4,"featured_media":77108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-77107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/77107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=77107"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/77107\/revisions"}],"predecessor-version":[{"id":77109,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/77107\/revisions\/77109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/77108"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=77107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=77107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=77107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}