{"id":82510,"date":"2024-07-04T15:08:19","date_gmt":"2024-07-04T19:08:19","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=82510"},"modified":"2024-07-04T15:08:19","modified_gmt":"2024-07-04T19:08:19","slug":"exportacoes-de-cafe-crescem-98-em-maio-brasil-deve-colher-5881-milhoes-de-sacas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/exportacoes-de-cafe-crescem-98-em-maio-brasil-deve-colher-5881-milhoes-de-sacas\/","title":{"rendered":"Exporta\u00e7\u00f5es de caf\u00e9 crescem 9,8% em maio; Brasil deve colher 58,81 milh\u00f5es de sacas"},"content":{"rendered":"<p>A Organiza\u00e7\u00e3o Internacional do Caf\u00e9 (OIC) informou nesta quarta-feira (03.07) que as exporta\u00e7\u00f5es globais de caf\u00e9 continuam a mostrar um crescimento s\u00f3lido em 2024. Em maio deste ano, o volume exportado atingiu 11,78 milh\u00f5es de sacas de 60 quilos, marcando um aumento de 9,8% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior.<\/p>\n<p>Este incremento faz parte de uma tend\u00eancia positiva que se estende ao longo da safra 2023\/24, com um total de 92,73 milh\u00f5es de sacas exportadas nos primeiros oito meses. Esse n\u00famero representa um crescimento de 10,9% comparado ao ciclo anterior, que registrou 83,60 milh\u00f5es de sacas no mesmo per\u00edodo.<\/p>\n<p>No contexto brasileiro, os produtores est\u00e3o projetando uma colheita de 58,81 milh\u00f5es de sacas beneficiadas para a atual temporada. Caso se confirme, ser\u00e1 o terceiro ano consecutivo de aumento no volume total colhido. Em compara\u00e7\u00e3o com o ano anterior, o crescimento \u00e9 de 6,8%, e em rela\u00e7\u00e3o a 2022, um ano de bienalidade positiva mas com baixas produtividades devido a condi\u00e7\u00f5es clim\u00e1ticas adversas, o incremento alcan\u00e7a 15,5%.<\/p>\n<p>A \u00e1rea total dedicada \u00e0 cafeicultura no Brasil em 2024, abrangendo as esp\u00e9cies ar\u00e1bica e conilon, totaliza 2,25 milh\u00f5es de hectares, um aumento de 0,5% em rela\u00e7\u00e3o \u00e0 safra anterior. Destes, 1,9 milh\u00e3o de hectares est\u00e3o em produ\u00e7\u00e3o, apresentando um crescimento de 1,5% em rela\u00e7\u00e3o ao ano anterior, enquanto 344,61 mil hectares est\u00e3o em forma\u00e7\u00e3o, registrando uma redu\u00e7\u00e3o de 4,7% comparado ao mesmo per\u00edodo.<\/p>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/exportacoes-de-cafe-crescem-98-em-maio-brasil-deve-colher-5881-milhoes-de-sacas\/#83740827-88d8-479e-a9fb-b885300db80b\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Organiza\u00e7\u00e3o Internacional do Caf\u00e9 (OIC) informou nesta quarta-feira (03.07) que as exporta\u00e7\u00f5es globais de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":82512,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-82510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/82510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=82510"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/82510\/revisions"}],"predecessor-version":[{"id":82513,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/82510\/revisions\/82513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/82512"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=82510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=82510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=82510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}