{"id":83343,"date":"2024-07-30T10:43:04","date_gmt":"2024-07-30T14:43:04","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=83343"},"modified":"2024-07-30T10:43:04","modified_gmt":"2024-07-30T14:43:04","slug":"titulos-que-financiam-o-agronegocio-superam-r-1-trilhao","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/titulos-que-financiam-o-agronegocio-superam-r-1-trilhao\/","title":{"rendered":"T\u00edtulos que financiam o agroneg\u00f3cio superam R$ 1 trilh\u00e3o"},"content":{"rendered":"<p>Os t\u00edtulos voltados ao financiamento do agroneg\u00f3cio com recursos privados atingiram um total de R$ 1,036 trilh\u00e3o em estoques ao final de junho, representando um aumento de 23,8% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior, conforme divulgado pelo Minist\u00e9rio da Agricultura no \u201cBoletim de Finan\u00e7as Privadas do Agro\u201d.<\/p>\n<p>No mesmo m\u00eas do ano passado, os estoques de C\u00e9dulas de Produto Rural (CPR), Letras de Cr\u00e9dito do Agroneg\u00f3cio (LCA), Certificados de Direitos Credit\u00f3rios do Agroneg\u00f3cio (CDCA), Certificados de Receb\u00edveis do Agroneg\u00f3cio (CRA) e Fundos de Investimento nas Cadeias Produtivas do Agroneg\u00f3cio (Fiagro) totalizavam R$ 836,55 bilh\u00f5es. Em maio, o estoque era de R$ 1,019 trilh\u00e3o.<\/p>\n<p>O maior crescimento foi observado nos Fundos de Investimento nas Cadeias Produtivas do Agroneg\u00f3cio (Fiagro), cujo patrim\u00f4nio aumentou 147% em junho deste ano em compara\u00e7\u00e3o ao mesmo m\u00eas do ano anterior, saltando de R$ 15,60 bilh\u00f5es para R$ 38,51 bilh\u00f5es, administrados por 109 fundos em opera\u00e7\u00e3o.<\/p>\n<p>Durante o mesmo per\u00edodo, os estoques de C\u00e9dulas de Produto Rural (CPRs) subiram 36%, de R$ 258,57 bilh\u00f5es para R$ 351,92 bilh\u00f5es. Tamb\u00e9m houve um avan\u00e7o significativo de 26% nos estoques de Certificados de Receb\u00edveis do Agroneg\u00f3cio (CRAs), alcan\u00e7ando R$ 140,59 bilh\u00f5es no final do m\u00eas passado.<\/p>\n<p>As Letras de Cr\u00e9dito do Agroneg\u00f3cio (LCAs) registraram um aumento de 12% nos estoques em rela\u00e7\u00e3o ao ano anterior, totalizando R$ 472,66 bilh\u00f5es, demonstrando um desempenho mais moderado desde o in\u00edcio do ano, segundo o minist\u00e9rio. Atualmente, as LCAs s\u00e3o a principal fonte de recursos livres destinados ao cr\u00e9dito rural.<\/p>\n<p>Por outro lado, os estoques de Certificados de Direitos Credit\u00f3rios do Agroneg\u00f3cio (CDCA) cresceram 8%, atingindo R$ 32,79 bilh\u00f5es em junho.<\/p>\n<p>Com informa\u00e7\u00f5es do\u00a0<strong><span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">Broadcast Agro<\/span><\/strong><\/p>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/titulos-que-financiam-o-agronegocio-superam-r-1-trilhao\/#9c853555-0217-4424-839e-fb0c376b9a3e\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os t\u00edtulos voltados ao financiamento do agroneg\u00f3cio com recursos privados atingiram um total de R$ &hellip;<\/p>\n","protected":false},"author":4,"featured_media":83344,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-83343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=83343"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83343\/revisions"}],"predecessor-version":[{"id":83345,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83343\/revisions\/83345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/83344"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=83343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=83343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=83343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}