{"id":83418,"date":"2024-08-01T11:15:03","date_gmt":"2024-08-01T15:15:03","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=83418"},"modified":"2024-08-01T11:15:03","modified_gmt":"2024-08-01T15:15:03","slug":"mp-do-governo-concede-subsidios-a-produtores-gauchos-mas-medidas-sao-limitadas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mp-do-governo-concede-subsidios-a-produtores-gauchos-mas-medidas-sao-limitadas\/","title":{"rendered":"MP do Governo concede subs\u00eddios a produtores ga\u00fachos, mas medidas s\u00e3o limitadas"},"content":{"rendered":"<p data-sourcepos=\"5:1-5:373\">O governo federal publicou nesta quarta-feira (31.07) a medida provis\u00f3ria que havia prometido, autorizando a concess\u00e3o de subs\u00eddios para produtores rurais do Rio Grande do Sul, atingidos pelas fortes chuvas de abril e maio.<\/p>\n<p data-sourcepos=\"26:1-26:25\">A avalia\u00e7\u00e3o do setor produtivo \u00e9 de que as medidas s\u00e3o limitadas e n\u00e3o atendem a todas as necessidades do setor. Representantes do agroneg\u00f3cio criticaram a medida por considerar que ela n\u00e3o atende especialmente aqueles produtores que acumularam d\u00edvidas por conta de eventos clim\u00e1ticos anteriores. Al\u00e9m disso, a avalia\u00e7\u00e3o \u00e9 de que os crit\u00e9rios para concess\u00e3o dos descontos s\u00e3o muito rigorosos e que apenas uma pequena parcela dos produtores ser\u00e1 beneficiada.<\/p>\n<p data-sourcepos=\"7:1-7:1\">A principal medida da MP \u00e9 a concess\u00e3o de descontos para liquida\u00e7\u00e3o ou renegocia\u00e7\u00e3o de parcelas de opera\u00e7\u00f5es de custeio, investimento e industrializa\u00e7\u00e3o. No entanto, o benef\u00edcio \u00e9 condicionado a um conjunto de crit\u00e9rios rigorosos, como a comprova\u00e7\u00e3o de perdas superiores a 30% da renda esperada e a an\u00e1lise de cada caso por uma comiss\u00e3o espec\u00edfica.<\/p>\n<p data-sourcepos=\"9:1-9:210\">A medida se restringe a opera\u00e7\u00f5es contratadas at\u00e9 abril de 2024 e os descontos ser\u00e3o concedidos apenas para uma parcela limitada.<\/p>\n<p data-sourcepos=\"11:1-11:23\"><strong>Pontos-chave da MP:<\/strong><\/p>\n<ul data-sourcepos=\"13:1-17:0\">\n<li data-sourcepos=\"13:1-13:136\"><strong>Descontos em opera\u00e7\u00f5es de custeio, investimento e industrializa\u00e7\u00e3o:<\/strong>\u00a0Para produtores com perdas superiores a 30% da renda esperada.<\/li>\n<li data-sourcepos=\"14:1-14:83\"><strong>An\u00e1lise de cada caso:<\/strong>\u00a0Comiss\u00e3o espec\u00edfica ir\u00e1 avaliar os pedidos de desconto.<\/li>\n<li data-sourcepos=\"15:1-15:111\"><strong>Limita\u00e7\u00e3o do benef\u00edcio:<\/strong>\u00a0A medida n\u00e3o contempla todas as d\u00edvidas dos produtores e tem crit\u00e9rios rigorosos.<\/li>\n<li data-sourcepos=\"16:1-17:0\"><strong>Aumento do Fundo Garantidor para Investimentos (FGI):<\/strong>\u00a0Para cobrir opera\u00e7\u00f5es de cr\u00e9dito aos produtores rurais ga\u00fachos.<\/li>\n<\/ul>\n<p data-sourcepos=\"24:1-24:101\">O governo ainda precisa publicar um decreto que ir\u00e1 definir os percentuais e limites de desconto para cada caso. Al\u00e9m disso, os produtores ter\u00e3o que apresentar os documentos necess\u00e1rios para comprovar as perdas e solicitar os benef\u00edcios.<\/p>\n<div id=\"attachment_284684\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-284684\" src=\"https:\/\/pensaragro.com.br\/wp-content\/uploads\/2024\/08\/isan5-188x300.jpg\" alt=\"\" width=\"214\" height=\"341\" aria-describedby=\"caption-attachment-284684\" \/><\/p>\n<p id=\"caption-attachment-284684\" class=\"wp-caption-text\"><em>Isan Rezende, Presidente do Instituto do Agroneg\u00f3cio<\/em><\/p>\n<\/div>\n<p>INSUFICIENTES \u2013 Para o presidente do Instituto do Agroneg\u00f3cio (IA), Isan Reende, a medida provis\u00f3ria \u00e9 um passo t\u00edmido e insuficiente para atender as necessidades dos produtores rurais ga\u00fachos. \u201cOs crit\u00e9rios para acesso aos benef\u00edcios s\u00e3o extremamente restritivos e n\u00e3o contemplam a totalidade das perdas sofridas pelo setor. A falta de uma pol\u00edtica mais abrangente para a renegocia\u00e7\u00e3o das d\u00edvidas e a aus\u00eancia de medidas para prevenir futuras crises clim\u00e1ticas s\u00e3o lacunas graves\u201d, disse o presidente.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u6b880db9439524e5114a3e02ab213e19-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Exporta\u00e7\u00f5es do agroneg\u00f3cio atingiram US$ 126 bilh\u00f5es de janeiro a setembro<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\u201cA medida provis\u00f3ria traz um al\u00edvio tempor\u00e1rio para alguns produtores, mas n\u00e3o resolve o problema de forma estrutural. Os descontos nas parcelas s\u00e3o importantes, mas n\u00e3o s\u00e3o suficientes para recuperar as perdas e os investimentos. \u00c9 preciso um olhar mais amplo para o setor, com pol\u00edticas p\u00fablicas que promovam o desenvolvimento sustent\u00e1vel e a resili\u00eancia da produ\u00e7\u00e3o agr\u00edcola\u201dcontinua Isan.<\/p>\n<p>Para Rezende o governo deveria melhorar criando um programa de renegocia\u00e7\u00f5es mais flex\u00edvel e abrangente. \u201cEntendemos a dificuldade do governo em lidar com a situa\u00e7\u00e3o, mas acreditamos que a medida provis\u00f3ria poderia ser aprimorada. Sugerimos a cria\u00e7\u00e3o de um programa de renegocia\u00e7\u00e3o de d\u00edvidas mais flex\u00edvel, que contemple todas as opera\u00e7\u00f5es de cr\u00e9dito rural e n\u00e3o apenas aquelas com vencimento em 2024. Al\u00e9m disso, \u00e9 fundamental investir em medidas de preven\u00e7\u00e3o e adapta\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas, como a recupera\u00e7\u00e3o de \u00e1reas degradadas e a ado\u00e7\u00e3o de pr\u00e1ticas agr\u00edcolas sustent\u00e1veis.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/mp-do-governo-concede-subsidios-a-produtores-gauchos-mas-medidas-sao-limitadas\/#ecfb3c26-8f7a-43f9-b150-de93a30e3130\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo federal publicou nesta quarta-feira (31.07) a medida provis\u00f3ria que havia prometido, autorizando a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":83419,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-83418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=83418"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83418\/revisions"}],"predecessor-version":[{"id":83420,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83418\/revisions\/83420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/83419"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=83418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=83418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=83418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}