{"id":83711,"date":"2024-08-12T10:01:17","date_gmt":"2024-08-12T14:01:17","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=83711"},"modified":"2024-08-12T10:01:17","modified_gmt":"2024-08-12T14:01:17","slug":"maranhao-vai-sediar-pela-primeira-vez-a-abertura-do-plano-safra","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/maranhao-vai-sediar-pela-primeira-vez-a-abertura-do-plano-safra\/","title":{"rendered":"Maranh\u00e3o vai sediar, pela primeira vez, a abertura do plano safra"},"content":{"rendered":"<p>O Maranh\u00e3o ser\u00e1 palco de um evento hist\u00f3rico para o agroneg\u00f3cio brasileiro: a Abertura Nacional do Plantio da Safra de Soja 2024\/2025. Pela primeira vez, o estado sediar\u00e1 essa importante cerim\u00f4nia, que ocorrer\u00e1 na Fazenda Pau-Brasil, localizada no munic\u00edpio de A\u00e7ail\u00e2ndia.<\/p>\n<p>O evento marcar\u00e1 o in\u00edcio oficial do plantio, com um desfile de plantadeiras em campo, al\u00e9m de uma s\u00e9rie de debates sobre temas cruciais para o setor. Entre os t\u00f3picos em destaque est\u00e3o gest\u00e3o e diversifica\u00e7\u00e3o nas propriedades, rentabilidade, a relev\u00e2ncia da regi\u00e3o do MATOPIBA, impactos clim\u00e1ticos na lavoura e a sustentabilidade na produ\u00e7\u00e3o.<\/p>\n<p>A entrada \u00e9 gratuita, mas para participar presencialmente ser\u00e1 necess\u00e1rio realizar inscri\u00e7\u00e3o por meio de um formul\u00e1rio online. O evento faz parte do Projeto Soja Brasil, promovido pelo Canal Rural em parceria com a Aprosoja Brasil.<\/p>\n<p><strong>SERVI\u00c7O:<\/strong><\/p>\n<ul>\n<li><strong>O qu\u00ea:<\/strong>\u00a0Abertura Nacional do Plantio da Safra de Soja 2024\/2025<\/li>\n<li><strong>Quando:<\/strong>\u00a011 de outubro, \u00e0s 9h (hor\u00e1rio de Bras\u00edlia)<\/li>\n<li><strong>Onde:<\/strong>\u00a0Fazenda Pau-Brasil, A\u00e7ail\u00e2ndia, Maranh\u00e3o<\/li>\n<\/ul>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/maranhao-vai-sediar-pela-primeira-vez-a-abertura-do-plano-safra\/#fe71ca94-ee73-4744-8cf9-88e56347522d\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Maranh\u00e3o ser\u00e1 palco de um evento hist\u00f3rico para o agroneg\u00f3cio brasileiro: a Abertura Nacional &hellip;<\/p>\n","protected":false},"author":4,"featured_media":83713,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-83711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=83711"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83711\/revisions"}],"predecessor-version":[{"id":83714,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/83711\/revisions\/83714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/83713"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=83711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=83711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=83711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}