{"id":84768,"date":"2024-09-12T09:26:27","date_gmt":"2024-09-12T13:26:27","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=84768"},"modified":"2024-09-12T09:26:27","modified_gmt":"2024-09-12T13:26:27","slug":"primeira-dama-de-alto-araguaia-assume-cadeira-na-almt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/primeira-dama-de-alto-araguaia-assume-cadeira-na-almt\/","title":{"rendered":"Primeira-dama de Alto Araguaia assume cadeira na ALMT"},"content":{"rendered":"<p>A primeira-dama da cidade de Alto Araguaia, Priscila Dourado (PSB), suplente de deputada estadual, assumiu uma cadeira no Parlamento nesta quarta-feira (11), durante sess\u00e3o ordin\u00e1ria presidida pela deputada Janaina Riva (MDB). Priscila Dourado assumiu a vaga devido ao pedido de licen\u00e7a do deputado estadual Beto Dois a Um (Uni\u00e3o). A nova deputada foi conduzida ao plen\u00e1rio pelos deputados J\u00falio Campos (Uni\u00e3o) e Dr. Jo\u00e3o (MDB).<\/p>\n<p>Em discurso na tribuna, Priscila Dourado falou da oportunidade em estar no Parlamento e poder representar o estado de Mato Grosso. \u201cHoje \u00e9 um dia hist\u00f3rico para mim, assim como para toda minha regi\u00e3o, o Vale do Araguaia. Estou aqui para somar com todos os deputados, em conjunto com a deputada Janaina Riva, \u00a0juntar nossa for\u00e7a em favor do estado\u201d, disse.<\/p>\n<p>\u201cQuero gradecer diretamente o deputado Max Russi, que me deu a oportunidade de sair candidata para representar a mulher no nosso estado. E desde j\u00e1 agradecer aos 70 munic\u00edpios que me deram \u00a0voto para que eu estivesse aqui, representando Mato Grosso. Tamb\u00e9m agradecer ao deputado Beto Dois a Um, que teve a sensibilidade de me conceder esse per\u00edodo em sua vaga\u201d, destacou.<\/p>\n<p>O primeiro-secret\u00e1rio da Assembleia Legislativa, deputado Max Russi (PSB), que deu boas-vindas \u00e0 nova deputada, destacou o \u201cmomento feliz\u201d vivido no Parlamento com a posse de tr\u00eas novos deputados; al\u00e9m de Priscila Dourado, os suplentes Gilberto Figueiredo (Uni\u00e3o), e Silvano Amaral (MDB), que vai assumir com a licen\u00e7a do deputado Dr. Jo\u00e3o (MDB).<\/p>\n<p>\u201cTemos a felicidade hoje de tr\u00eas deputados assumirem: Gilberto, Priscila e Silvano Amaral\u201d, disse Max Russi. Sobre a posse da deputada Priscila Dourado, Russi destacou a postura do deputado Beto Dois a Um.<\/p>\n<p>\u201cQuero agradecer ao deputado Beto pela grandeza. Nesse momento, s\u00e3o duas mulheres representando o estado. O Parlamento ganha muito. A Priscila \u00e9 uma mulher de fibra, corajosa. Teve uma grande vota\u00e7\u00e3o&#8230;fazer sete mil votos n\u00e3o \u00e9 f\u00e1cil. A posse fortalece o partido, fortalece novas lideran\u00e7as. Alto Araguaia ganha muito, a regi\u00e3o est\u00e1 muito bem representada na Assembleia Legislativa\u201d, completou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 ALMT\u00a0 \u00a0|\u00a0 \u00a0 Foto:\u00a0 \u00a0<i>ANGELO VARELA \/ ALMT<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A primeira-dama da cidade de Alto Araguaia, Priscila Dourado (PSB), suplente de deputada estadual, assumiu &hellip;<\/p>\n","protected":false},"author":4,"featured_media":84769,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-84768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"A suplente Priscila Dourado (PSB) tomou posse durante sess\u00e3o ordin\u00e1ria","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/84768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=84768"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/84768\/revisions"}],"predecessor-version":[{"id":84770,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/84768\/revisions\/84770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/84769"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=84768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=84768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=84768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}