{"id":84863,"date":"2024-09-16T09:32:36","date_gmt":"2024-09-16T13:32:36","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=84863"},"modified":"2024-09-16T09:32:36","modified_gmt":"2024-09-16T13:32:36","slug":"cuiaba-nao-pode-ter-prefeito-louco-de-pedra-afirma-mauro-mendes","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/cuiaba-nao-pode-ter-prefeito-louco-de-pedra-afirma-mauro-mendes\/","title":{"rendered":"Cuiab\u00e1 n\u00e3o pode ter prefeito \u201clouco de pedra\u201d, afirma Mauro Mendes"},"content":{"rendered":"<p>O governador Mauro Mendes (Uni\u00e3o) reafirmou, no domingo (15), seu apoio ao candidato Eduardo Botelho (Uni\u00e3o) na disputa pela Prefeitura de Cuiab\u00e1, destacando \u201co preparo e a experi\u00eancia\u201d de Botelho como fundamentais para a capital.<\/p>\n<p>Durante um encontro com os candidatos a vereador da coliga\u00e7\u00e3o \u201cJuntos por Cuiab\u00e1\u201d, Mauro fez compara\u00e7\u00f5es com os outros candidatos e refor\u00e7ou a import\u00e2ncia de a popula\u00e7\u00e3o cuiabana escolher um prefeito alinhado com o Governo do Estado, garantindo que essa parceria trar\u00e1 avan\u00e7os significativos para a cidade.<\/p>\n<p>O governador n\u00e3o poupou cr\u00edticas aos outros candidatos.<\/p>\n<p>Sem citar nomes diretamente, Mauro Mendes afirmou que Botelho disputa diretamente com dois advers\u00e1rios, j\u00e1 que um deles \u00e9 apenas uma \u201cmarionete\u201d do atual prefeito Emanuel Pinheiro (MDB) \u2013 refer\u00eancia a Domingos Kennedy (MDB).<\/p>\n<p>\u201cTem dois candidatos. Um, todo mundo sabe, \u00e9 marionete do atual prefeito. O outro? Um candidato que est\u00e3o falando \u2018louco de jogar pedra\u2019. Com todo o respeito, ele, de vez em quando, ou de vez em sempre, tem aquelas caracter\u00edsticas que criam desconex\u00e3o. Como voc\u00ea senta com uma pessoa que, de repente, do nada muda. Um dia, ele foi participar de uma inaugura\u00e7\u00e3o na Santa Casa, ele saiu da inaugura\u00e7\u00e3o come\u00e7ou fazer v\u00eddeo esculhambando. A partir da\u00ed, n\u00e3o dei mais moral. \u00c9 assim que funciona: se a pessoa te trata mal, voc\u00ea exclui a pessoa, e isso \u00e9 muito ruim para nossa querida Cuiab\u00e1\u201d, afirmou Mauro.<\/p>\n<p>Sem citar nome, o governador e referia ao bolsonarista Ab\u00edlio Brununi (PL).<\/p>\n<p>Mauro Mendes tamb\u00e9m mencionou o candidato do PT, afirmando que, embora n\u00e3o tenha nada pessoal contra ele, o partido e seu grupo pol\u00edtico n\u00e3o t\u00eam condi\u00e7\u00f5es de administrar a Capital.<\/p>\n<p>\u201cEle representa um grupo pol\u00edtico que, aqui em Cuiab\u00e1, n\u00e3o tem a menor condi\u00e7\u00e3o de administrar, nunca ganhou e, num curto espa\u00e7o de s\u00e9culo, n\u00e3o vai ganhar\u201d, afirmou.<\/p>\n<p>Em seu discurso, o governador afirmou que o Governo Estadual assumiu diversas fun\u00e7\u00f5es que deveriam ser da prefeitura, como a pavimenta\u00e7\u00e3o de bairros e a inaugura\u00e7\u00e3o de hospitais.<\/p>\n<p>Ele destacou o impacto positivo que essa colabora\u00e7\u00e3o j\u00e1 teve e como ela continuar\u00e1 beneficiando a capital, se Botelho for eleito. \u201cO Governo j\u00e1 fez muito por Cuiab\u00e1, asfaltamos bairros e estamos entregando hospitais. No ano que vem, vamos inaugurar o Hospital Central, que ter\u00e1 a melhor estrutura de sa\u00fade de toda a regi\u00e3o. Agora, imaginem ter Botelho, que j\u00e1 \u00e9 parte desse time, como prefeito? Isso vai dar muito certo para Cuiab\u00e1, e \u00e9 importante que a popula\u00e7\u00e3o tenha clareza disso. N\u00e3o podemos perder essa oportunidade\u201d, afirmou.<\/p>\n<p>Mauro Mendes tamb\u00e9m destacou que, com Botelho \u00e0 frente da prefeitura, a capital estar\u00e1 alinhada com o governo estadual, o que facilitar\u00e1 a execu\u00e7\u00e3o de projetos e garantir\u00e1 maior efici\u00eancia na administra\u00e7\u00e3o p\u00fablica. \u201cBotelho vai contar com o nosso apoio para trabalhar com honestidade e coragem. Cuiab\u00e1 precisa recuperar o tempo perdido nos \u00faltimos anos, e ele \u00e9 a pessoa certa para fazer isso\u201d, declarou o governador.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 ODOC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes (Uni\u00e3o) reafirmou, no domingo (15), seu apoio ao candidato Eduardo Botelho &hellip;<\/p>\n","protected":false},"author":4,"featured_media":84864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,59],"tags":[],"class_list":["post-84863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaque"],"wps_subtitle":"Governador faz cr\u00edticas a Ab\u00edlio e reafirma apoio \u00e0 candidatura de Botelho a prefeito de Cuiab\u00e1","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/84863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=84863"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/84863\/revisions"}],"predecessor-version":[{"id":84865,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/84863\/revisions\/84865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/84864"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=84863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=84863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=84863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}