{"id":85680,"date":"2024-10-08T15:12:47","date_gmt":"2024-10-08T19:12:47","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=85680"},"modified":"2024-10-08T15:12:47","modified_gmt":"2024-10-08T19:12:47","slug":"investimento-bilionario-em-soja-impulsiona-setor-de-biodiesel-e-fortalece-agronegocio","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/investimento-bilionario-em-soja-impulsiona-setor-de-biodiesel-e-fortalece-agronegocio\/","title":{"rendered":"Investimento bilion\u00e1rio em soja impulsiona setor de biodiesel e fortalece agroneg\u00f3cio"},"content":{"rendered":"<p>A Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias de \u00d3leos Vegetais (Abiove) anunciou um investimento de R$ 5,76 bilh\u00f5es voltado \u00e0 constru\u00e7\u00e3o e amplia\u00e7\u00e3o de unidades industriais de esmagamento de soja. O objetivo \u00e9 preparar o setor para a crescente demanda, tanto no mercado interno quanto externo, e atender \u00e0s novas metas de biodiesel do pa\u00eds.<\/p>\n<p>Com a inje\u00e7\u00e3o de capital, a expectativa \u00e9 que a \u00e1rea plantada de soja no Brasil cres\u00e7a cerca de 3%, alcan\u00e7ando 47,4 milh\u00f5es de hectares na pr\u00f3xima safra. Al\u00e9m disso, a produ\u00e7\u00e3o deve dar um salto de 12,8%, chegando a um total de 166,3 milh\u00f5es de toneladas de gr\u00e3os.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-285607\" src=\"https:\/\/pensaragro.com.br\/wp-content\/uploads\/2024\/10\/soj-300x236.jpg\" alt=\"\" width=\"725\" height=\"570\" \/><\/p>\n<p>Para o presidente do Instituto do Agroneg\u00f3cio, Isan Rezende, esse movimento \u00e9 estrat\u00e9gico, considerando que a soja \u00e9 a principal mat\u00e9ria-prima para a produ\u00e7\u00e3o de biodiesel, e o pa\u00eds se prepara para aumentar o percentual de mistura do biocombust\u00edvel de 14% para 15%, a partir de mar\u00e7o de 2025.<\/p>\n<p>\u201cO incremento na produ\u00e7\u00e3o de soja ser\u00e1 essencial para atender \u00e0 demanda crescente por biocombust\u00edveis, ao mesmo tempo em que fortalece o Brasil como um dos maiores produtores e exportadores globais de \u00f3leo de soja\u201d.<\/p>\n<p>\u201cO investimento bilion\u00e1rio na amplia\u00e7\u00e3o das ind\u00fastrias esmagadoras de soja \u00e9 um passo crucial para o fortalecimento do agroneg\u00f3cio brasileiro. A soja j\u00e1 \u00e9 um pilar de nossa economia, e com a crescente demanda por biocombust\u00edveis, esse movimento prepara o pa\u00eds para atender tanto o mercado interno quanto o externo, garantindo mais competitividade e sustentabilidade ao setor,\u201d destacou Rezende.<\/p>\n<p>\u201cCom o aumento na mistura de biodiesel previsto para 2025, essa expans\u00e3o se torna ainda mais relevante. Ela n\u00e3o s\u00f3 alavanca a produ\u00e7\u00e3o de soja, como tamb\u00e9m refor\u00e7a o papel do Brasil como l\u00edder na produ\u00e7\u00e3o de energia renov\u00e1vel. Estamos entrando em uma nova fase, onde o agroneg\u00f3cio brasileiro une for\u00e7a e inova\u00e7\u00e3o para seguir crescendo de maneira sustent\u00e1vel,\u201d completou.<\/p>\n<p>A expans\u00e3o das plataformas industriais e o crescimento da produ\u00e7\u00e3o de soja v\u00e3o ao encontro de um mercado cada vez mais exigente por alternativas sustent\u00e1veis e renov\u00e1veis, e colocam o Brasil em posi\u00e7\u00e3o de destaque no cen\u00e1rio mundial de energia limpa.<\/p>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/investimento-bilionario-em-soja-impulsiona-setor-de-biodiesel-e-fortalece-agronegocio\/#d4a0d9a9-fe7a-41d8-9f6a-fc975c614185\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias de \u00d3leos Vegetais (Abiove) anunciou um investimento de R$ 5,76 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":85681,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-85680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/85680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=85680"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/85680\/revisions"}],"predecessor-version":[{"id":85682,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/85680\/revisions\/85682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/85681"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=85680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=85680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=85680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}