{"id":86884,"date":"2024-11-11T14:28:45","date_gmt":"2024-11-11T18:28:45","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=86884"},"modified":"2024-11-11T14:28:45","modified_gmt":"2024-11-11T18:28:45","slug":"mda-e-embrapa-lancam-programa-de-capacitacao-online-voltado-para-o-fortalecimento-da-agricultura","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mda-e-embrapa-lancam-programa-de-capacitacao-online-voltado-para-o-fortalecimento-da-agricultura\/","title":{"rendered":"MDA e Embrapa lan\u00e7am programa de capacita\u00e7\u00e3o online voltado para o fortalecimento da agricultura"},"content":{"rendered":"<p>Com o crescimento do mercado de trabalho formal no Brasil, o Minist\u00e9rio do Desenvolvimento Agr\u00e1rio e Agricultura Familiar (MDA) e a Empresa Brasileira de Pesquisa Agropecu\u00e1ria (Embrapa) lan\u00e7aram um programa de capacita\u00e7\u00e3o online voltado para o fortalecimento da agricultura familiar e o incentivo a pr\u00e1ticas sustent\u00e1veis no campo. A iniciativa \u00e9 uma resposta ao aumento da competitividade no setor, com a crescente demanda por t\u00e9cnicas mais eficientes e ambientalmente respons\u00e1veis.<\/p>\n<p>O programa oferece uma s\u00e9rie de cursos online gratuitos, que j\u00e1 podem ser acessados na plataforma e-Campo. O primeiro curso dispon\u00edvel, \u201cBem-estar animal para produ\u00e7\u00e3o sustent\u00e1vel de leite\u201d, marca o in\u00edcio da sequ\u00eancia de treinamentos que seguir\u00e3o at\u00e9 dezembro. Entre os temas que ser\u00e3o abordados, destacam-se tamb\u00e9m \u201cBoas pr\u00e1ticas de fabrica\u00e7\u00e3o no beneficiamento da castanha-de-caju\u201d, \u201cProcessamento de mandioca de mesa pela agricultura familiar\u201d e \u201cProdu\u00e7\u00e3o de ovos na agricultura familiar\u201d.<\/p>\n<p>O formato digital das capacita\u00e7\u00f5es permite alcan\u00e7ar um n\u00famero maior de produtores e t\u00e9cnicos de Assist\u00eancia T\u00e9cnica e Extens\u00e3o Rural (Ater) em todo o Brasil, ampliando o alcance do conhecimento gerado pelas pesquisas da Embrapa. Atrav\u00e9s dessas aulas, agentes de Ater poder\u00e3o aprimorar suas habilidades e aplicar pr\u00e1ticas inovadoras e sustent\u00e1veis no campo, com foco no aumento da produ\u00e7\u00e3o e na redu\u00e7\u00e3o de impactos ambientais.<\/p>\n<p>Com a participa\u00e7\u00e3o de diversos grupos, incluindo assentados da reforma agr\u00e1ria, povos ind\u00edgenas e comunidades quilombolas, o programa visa promover uma agricultura mais inclusiva e eficiente, proporcionando acesso a capacita\u00e7\u00e3o de qualidade. O diretor de Inova\u00e7\u00e3o, Neg\u00f3cios e Transfer\u00eancia de Tecnologia da Embrapa, Ana Euler, destaca que a digitaliza\u00e7\u00e3o dessas capacita\u00e7\u00f5es \u00e9 uma forma de garantir que as solu\u00e7\u00f5es desenvolvidas no campo da pesquisa cheguem a quem mais precisa.<\/p>\n<p>A s\u00e9rie de cursos, com in\u00edcio em outubro e t\u00e9rmino previsto para 6 de dezembro, representa um avan\u00e7o significativo para o setor agr\u00edcola brasileiro, que continua a buscar alternativas mais sustent\u00e1veis e rent\u00e1veis, ao mesmo tempo em que gera oportunidades de crescimento para os produtores rurais em diversas regi\u00f5es do pa\u00eds.<\/p>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"https:\/\/pensaragro.com.br\/mda-e-embrapa-lancam-programa-de-capacitacao-online-voltado-para-o-fortalecimento-da-agricultura\/#20348795-a6bd-4226-9d7d-08e402ce8f4f\" target=\"_blank\" rel=\"noopener\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o crescimento do mercado de trabalho formal no Brasil, o Minist\u00e9rio do Desenvolvimento Agr\u00e1rio &hellip;<\/p>\n","protected":false},"author":4,"featured_media":86885,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-86884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/86884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=86884"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/86884\/revisions"}],"predecessor-version":[{"id":86886,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/86884\/revisions\/86886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/86885"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=86884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=86884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=86884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}