{"id":89548,"date":"2025-02-03T14:32:02","date_gmt":"2025-02-03T18:32:02","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=89548"},"modified":"2025-02-03T14:33:12","modified_gmt":"2025-02-03T18:33:12","slug":"abilio-destaca-reforma-administrativa-sem-custos-e-revogacao-da-taxa-do-lixo","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/abilio-destaca-reforma-administrativa-sem-custos-e-revogacao-da-taxa-do-lixo\/","title":{"rendered":"Abilio destaca reforma administrativa sem custos e revoga\u00e7\u00e3o da taxa do lixo"},"content":{"rendered":"<p>O prefeito de Cuiab\u00e1, Abilio Brunini, abriu os trabalhos legislativos na C\u00e2mara Municipal com um discurso em que destacou medidas priorit\u00e1rias de sua gest\u00e3o. Entre os principais pontos, ressaltou a reforma administrativa, que n\u00e3o gerar\u00e1 custos extras, e entregou o projeto de lei que revoga a taxa do lixo, cumprindo uma de suas principais metas.<\/p>\n<p>Abilio enfatizou que a reforma administrativa criar\u00e1 duas novas secretarias \u2013 Seguran\u00e7a P\u00fablica e Esporte, separadas da Cultura \u2013 sem aumento de despesas. \u201cN\u00e3o h\u00e1 e n\u00e3o haver\u00e1 aumento de custos\u201d, afirmou o prefeito. Al\u00e9m disso, Brunini anunciou a reestrutura\u00e7\u00e3o da administra\u00e7\u00e3o regional, acrescentando 21 subprefeituras, o que aumentar\u00e1 a efici\u00eancia dos servi\u00e7os p\u00fablicos.<\/p>\n<p>Outro destaque foi a entrega do projeto que revoga a taxa do lixo. \u201cEstamos protocolando o projeto que revoga a taxa do lixo. Como prometido, vamos acabar com essa cobran\u00e7a injusta. E acredito que teremos apoio praticamente un\u00e2nime dos parlamentares\u201d, declarou.<\/p>\n<p>Em seu discurso, o prefeito tamb\u00e9m refor\u00e7ou o compromisso com a transpar\u00eancia e agradeceu aos vereadores pela abertura ao di\u00e1logo. \u201cTodos os arquivos e dados da prefeitura est\u00e3o amplamente abertos \u00e0 C\u00e2mara e\u00a0popula\u00e7\u00e3o. Fiscaliza\u00e7\u00e3o e transpar\u00eancia s\u00e3o essenciais para combater a corrup\u00e7\u00e3o que tanto assombra nossa cidade\u201d, afirmou.<\/p>\n<p>Abilio destacou os desafios enfrentados no in\u00edcio da gest\u00e3o, como atrasos salariais e d\u00edvidas herdadas, e pediu o apoio dos parlamentares para superar as dificuldades. O prefeito pontuou que a educa\u00e7\u00e3o \u00e9 a \u00e1rea mais atingida com o sucateamento das escolas e creches, que apresentam problemas de seguran\u00e7a graves, com riscos el\u00e9tricos para as crian\u00e7as e servidores. Com isso, a pasta precisou adiar o in\u00edcio das aulas para 10 de fevereiro. \u201cN\u00e3o \u00e9 poss\u00edvel resolver os problemas de Cuiab\u00e1 sozinho. Preciso do apoio da popula\u00e7\u00e3o e dos vereadores. Torcer contra a cidade n\u00e3o resolve nada\u201d, concluiu.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0 Foto:\u00a0 Rennan Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Cuiab\u00e1, Abilio Brunini, abriu os trabalhos legislativos na C\u00e2mara Municipal com um &hellip;<\/p>\n","protected":false},"author":4,"featured_media":89549,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-89548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=89548"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89548\/revisions"}],"predecessor-version":[{"id":89550,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89548\/revisions\/89550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/89549"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=89548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=89548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=89548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}