{"id":89559,"date":"2025-02-03T15:02:51","date_gmt":"2025-02-03T19:02:51","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=89559"},"modified":"2025-02-03T15:02:51","modified_gmt":"2025-02-03T19:02:51","slug":"pode-entrar-a-escola-e-sua","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/pode-entrar-a-escola-e-sua\/","title":{"rendered":"Pode entrar, a escola \u00e9 sua!"},"content":{"rendered":"<section id=\"post-body\" class=\"post-body godo-canvas mx-auto relative font-article\">Neste dia 03 de fevereiro, mais de 310 mil alunos da rede estadual de ensino retornam \u00e0s salas de aula, prontos para embarcar em novas jornadas de aprendizado. Contudo, o in\u00edcio do ano letivo de 2025 n\u00e3o \u00e9 apenas um marco para os estudantes.<\/p>\n<p>Vejo esse momento como uma celebra\u00e7\u00e3o do esfor\u00e7o e dedica\u00e7\u00e3o de todos os profissionais que comp\u00f5em a Secretaria de Estado de Educa\u00e7\u00e3o de Mato Grosso (Seduc-MT), as diretorias regionais de educa\u00e7\u00e3o, as 627 escolas da rede, parceiros, colaboradores e a comunidade. Como sempre digo: educa\u00e7\u00e3o se faz de forma coletiva.<\/p>\n<p>\u00c9 imprescind\u00edvel reconhecer que, por tr\u00e1s de cada aluno que retorna das f\u00e9rias escolares, h\u00e1 um grande time de pessoas comprometidas com a nossa educa\u00e7\u00e3o p\u00fablica. E elas n\u00e3o est\u00e3o apenas na rede estadual. H\u00e1 um verdadeiro batalh\u00e3o de guerreiros da educa\u00e7\u00e3o nas redes municipais, preparando as crian\u00e7as que mais adiante estar\u00e3o matriculados nas escolas estaduais.<\/p>\n<p>S\u00e3o pessoas que se prepararam arduamente durante todo o ano para oferecer um ambiente acolhedor e estimulante, inspirando, motivando e guiando os alunos em suas descobertas para que se tornem protagonistas tanto na rotina escolar quanto em suas vidas.<\/p>\n<p>Confesso que sempre me emociono no primeiro dia de cada ano letivo e, fatalmente, me vem \u00e0 mente lembran\u00e7as de como foi no meu tempo de ensino fundamental. N\u00e3o era muito diferente de hoje. L\u00f3gico que a vida, atualmente, \u00e9 mais fren\u00e9tica e a educa\u00e7\u00e3o caminha lado a lado com tecnologia embarcada na sala de aula.<\/p>\n<p>Considero essencial o acolhimento que fazemos em nossas escolas nessa primeira semana de aula, pois, o retorno \u00e0s aulas muitas vezes de torna um momento de ansiedade e expectativa. Por essa raz\u00e3o, a Seduc oferta um ambiente seguro e acolhedor.<\/p>\n<p>Posso garantir que esse \u00e9 o primeiro passo para garantir que os alunos se sintam confort\u00e1veis e prontos para interagirem com seus colegas e professores.<\/p>\n<p>As boas-vindas a todos os envolvidos na educa\u00e7\u00e3o s\u00e3o mais do que merecidas.<\/p>\n<p>Cada palavra de incentivo e cada gesto de carinho neste momento fazem a diferen\u00e7a. Afinal, a educa\u00e7\u00e3o \u00e9 um esfor\u00e7o coletivo e cada um de n\u00f3s tem um papel importante a desempenhar nessa jornada que ora se inicia.<\/p>\n<p>Pode entrar, a escola \u00e9 sua!.<\/p>\n<p><strong><em>Alan Porto \u00e9 secret\u00e1rio de Estado de Educa\u00e7\u00e3o de Mato Grosso<\/em><\/strong><\/p>\n<\/section>\n<footer class=\"post-footer godo-canvas pt-10\">\n<div class=\"post-tags mb-8\">\n<div class=\"buttons\"><a class=\"button is-light font-medium text-sm capitalize godo-tracking\" title=\"Opini\u00e3o\" href=\"https:\/\/www.odocumento.com.br\/tag\/opiniao\/\" data-event-category=\"Article\" data-event-action=\"Tags\" data-event-label=\"Opini\u00e3o\" data-event-non-interaction=\"true\">Odoc<\/a><\/div>\n<\/div>\n<aside class=\"text-title flex gap-x-1 items-center flex-none\"><\/aside>\n<\/footer>\n","protected":false},"excerpt":{"rendered":"<p>Neste dia 03 de fevereiro, mais de 310 mil alunos da rede estadual de ensino &hellip;<\/p>\n","protected":false},"author":4,"featured_media":89560,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-89559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=89559"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89559\/revisions"}],"predecessor-version":[{"id":89561,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89559\/revisions\/89561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/89560"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=89559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=89559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=89559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}