{"id":89683,"date":"2025-02-06T09:22:08","date_gmt":"2025-02-06T13:22:08","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=89683"},"modified":"2025-02-06T09:22:08","modified_gmt":"2025-02-06T13:22:08","slug":"prefeito-mostra-forca-tarefa-a-promotor-e-discute-retorno-seguro-as-aulas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeito-mostra-forca-tarefa-a-promotor-e-discute-retorno-seguro-as-aulas\/","title":{"rendered":"Prefeito mostra for\u00e7a-tarefa a promotor e discute retorno seguro \u00e0s aulas"},"content":{"rendered":"<p>O prefeito Abilio Brunini acompanhou o promotor Miguel Slhessarenko Junior, coordenador do Centro de Apoio Operacional (CAO) de Educa\u00e7\u00e3o do Minist\u00e9rio P\u00fablico de Mato Grosso, em uma visita \u00e0 Secretaria de Educa\u00e7\u00e3o para apresentar os desafios enfrentados na gest\u00e3o. O encontro serviu para esclarecer d\u00favidas sobre o in\u00edcio das aulas, previsto para o dia 10 de fevereiro, e refor\u00e7ar a transpar\u00eancia da administra\u00e7\u00e3o municipal.<\/p>\n<p>Durante a visita, realizada na tarde desta quarta-feira (5), o promotor demonstrou preocupa\u00e7\u00e3o com a organiza\u00e7\u00e3o do retorno escolar, questionando aspectos como transporte, cuidadores, manuten\u00e7\u00e3o das unidades e equipe gestora. Contudo, ap\u00f3s conhecer de perto o trabalho realizado, Slhessarenko se mostrou mais tranquilo e ressaltou que a estrutura necess\u00e1ria para o in\u00edcio do ano letivo j\u00e1 est\u00e1 planejada. \u201cA sociedade pode ficar tranquila, pois o retorno das aulas est\u00e1 garantido para o dia 10, sem preju\u00edzo ao calend\u00e1rio escolar. Entretanto, ao longo do ano, precisaremos de mais reuni\u00f5es para alinhar poss\u00edveis demandas\u201d, destacou o promotor.<\/p>\n<p>O prefeito Abilio enfatizou que a atual gest\u00e3o tem enfrentado dificuldades estruturais e administrativas, como o uso excessivo de processos manuais e a falta de transpar\u00eancia em contratos anteriores. Ele mencionou que auditorias ser\u00e3o abertas para verificar suspeitas de irregularidades em documentos de presta\u00e7\u00e3o de servi\u00e7os nas escolas, mas garantiu que o foco imediato \u00e9 o retorno das aulas sem interrup\u00e7\u00f5es.<\/p>\n<p>\u201cA educa\u00e7\u00e3o foi muito usada como pe\u00e7a publicit\u00e1ria no ano passado, mas a administra\u00e7\u00e3o interna estava contaminada. Agora, nosso compromisso \u00e9 garantir que os alunos estejam em sala de aula e que haja transpar\u00eancia na gest\u00e3o\u201d, afirmou.<\/p>\n<p>Em um gesto de abertura e colabora\u00e7\u00e3o, Abilio reiterou que o Minist\u00e9rio P\u00fablico ter\u00e1 total liberdade para fiscalizar as a\u00e7\u00f5es da prefeitura. \u201cAs portas est\u00e3o abertas para qualquer membro do MP, sem necessidade de aviso pr\u00e9vio. O mais importante \u00e9 mostrar a realidade e garantir que as coisas aconte\u00e7am da melhor forma poss\u00edvel\u201d, disse o prefeito.<\/p>\n<p>O encontro refor\u00e7ou a import\u00e2ncia do di\u00e1logo entre poder p\u00fablico e \u00f3rg\u00e3os fiscalizadores, garantindo que a educa\u00e7\u00e3o municipal caminhe de forma estruturada e transparente ao longo do ano.<\/p>\n<p>#PraCegoVer<\/p>\n<p>A imagem principal\u00a0prefeito Abilio Brunini, de camiseta cinza segura um documento e conversa com um promotor de cabelos escuros e terno preto. Eles est\u00e3o na sede da secretaria de educa\u00e7\u00e3o\u00a0com prateleiras ao fundo, onde h\u00e1 pap\u00e9is e materiais administrativos. Ambos t\u00eam express\u00f5es s\u00e9rias, e outras pessoas trabalham ao redor.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Prefeitura de Cuiab\u00e1\u00a0 |\u00a0 \u00a0Foto:\u00a0 Rennan Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Abilio Brunini acompanhou o promotor Miguel Slhessarenko Junior, coordenador do Centro de Apoio &hellip;<\/p>\n","protected":false},"author":4,"featured_media":89684,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-89683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=89683"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89683\/revisions"}],"predecessor-version":[{"id":89685,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/89683\/revisions\/89685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/89684"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=89683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=89683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=89683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}