{"id":90173,"date":"2025-02-20T16:09:36","date_gmt":"2025-02-20T20:09:36","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=90173"},"modified":"2025-02-20T16:09:36","modified_gmt":"2025-02-20T20:09:36","slug":"nosso-objetivo-e-criar-condicoes-para-que-os-municipios-tenham-suporte-para-crescer-afirma-secretario","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/nosso-objetivo-e-criar-condicoes-para-que-os-municipios-tenham-suporte-para-crescer-afirma-secretario\/","title":{"rendered":"&#8220;Nosso objetivo \u00e9 criar condi\u00e7\u00f5es para que os munic\u00edpios tenham suporte para crescer&#8221;, afirma secret\u00e1rio"},"content":{"rendered":"<p>&#8220;Nosso papel \u00e9 criar condi\u00e7\u00f5es para que os munic\u00edpios tenham suporte para crescer, seja por meio de incentivos fiscais, linhas de cr\u00e9dito ou atra\u00e7\u00e3o de novos investimentos&#8221;, afirmou o secret\u00e1rio de Estado de Desenvolvimento Econ\u00f4mico, C\u00e9sar Miranda, nesta quarta-feira (19.2), durante o Encontro Mato-grossense dos Munic\u00edpios.<\/p>\n<p>C\u00e9sar foi um dos palestrantes no encontro, que re\u00fane cerca de 1.300 participantes, entre prefeitos, vereadores e secret\u00e1rios, no Cenarium Rural entre ter\u00e7a-feira (18.2) e quarta-feira (19.2). O evento \u00e9 promovido pela Associa\u00e7\u00e3o Mato-grossense dos Munic\u00edpios (AMM) em parceria com o Tribunal de Contas do Estado (TCE-MT).<\/p>\n<p>O secret\u00e1rio apresentou aos prefeitos e vereadores as pol\u00edticas p\u00fablicas para fomentar a economia e impulsionar o desenvolvimento regional por meio de parcerias com os munic\u00edpios. &#8220;O Governo de Mato Grosso tem buscado parcerias estrat\u00e9gicas para impulsionar o desenvolvimento e fortalecer nossa economia&#8221;, disse.<\/p>\n<p>Durante sua apresenta\u00e7\u00e3o, C\u00e9sar Miranda detalhou a atua\u00e7\u00e3o dos setores estrat\u00e9gicos como minera\u00e7\u00e3o, turismo, ind\u00fastria, com\u00e9rcio, incentivos fiscais, agroneg\u00f3cio, oferta de cr\u00e9dito, dados econ\u00f4micos e energia.<\/p>\n<p>Al\u00e9m disso, o secret\u00e1rio descreveu o trabalho da Sedec na atra\u00e7\u00e3o de investimentos e na promo\u00e7\u00e3o comercial dos produtos e servi\u00e7os mato-grossenses, ampliando oportunidades para empreendedores e fortalecendo a economia local.<\/p>\n<p>O secret\u00e1rio de Desenvolvimento Econ\u00f4mico da Prefeitura de Lucas do Rio Verde, Welligton Willen Nogueira Souto, avaliou a import\u00e2ncia da parceria entre a Sedec de Mato Grosso e os munic\u00edpios.<\/p>\n<p>\u201cO Estado conta com uma secretaria [de Desenvolvimento Econ\u00f4mico] muito robusta. A palestra do secret\u00e1rio foi essencial, pois apresentou diretrizes claras e revelou como os trabalhos est\u00e3o sendo conduzidos. Isso \u00e9 fundamental para secret\u00e1rios e prefeitos que est\u00e3o iniciando suas gest\u00f5es e precisam de apoio para estruturar ou expandir suas a\u00e7\u00f5es de desenvolvimento econ\u00f4mico. A Sedec \u00e9 uma aliada importante nesse processo\u201d, destacou Souto.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 \u00a0Assessoria\/Sedec<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Nosso papel \u00e9 criar condi\u00e7\u00f5es para que os munic\u00edpios tenham suporte para crescer, seja por &hellip;<\/p>\n","protected":false},"author":4,"featured_media":90174,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-90173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"No Encontro Mato-grossense dos Munic\u00edpios, que reuniu prefeitos e vereadores do Estado, C\u00e9sar Miranda apresentou pol\u00edticas p\u00fablicas da pasta para desenvolver munic\u00edpios","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/90173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=90173"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/90173\/revisions"}],"predecessor-version":[{"id":90175,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/90173\/revisions\/90175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/90174"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=90173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=90173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=90173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}