{"id":90390,"date":"2025-02-27T16:07:39","date_gmt":"2025-02-27T20:07:39","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=90390"},"modified":"2025-02-27T16:07:39","modified_gmt":"2025-02-27T20:07:39","slug":"governador-assina-decreto-e-libera-repasse-de-r-144-milhoes-a-municipios-para-compensar-perdas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governador-assina-decreto-e-libera-repasse-de-r-144-milhoes-a-municipios-para-compensar-perdas\/","title":{"rendered":"Governador assina decreto e libera repasse de R$ 144 milh\u00f5es a munic\u00edpios para compensar perdas"},"content":{"rendered":"<p>O governador Mauro Mendes assinou decreto, nesta quarta-feira (26.2), que prev\u00ea o repasse de mais de R$ 144 milh\u00f5es aos munic\u00edpios afetados pela extin\u00e7\u00e3o do Fethab Diesel &#8211; fundo que foi considerado inconstitucional pelo Tribunal de Justi\u00e7a de Mato Grosso.<\/p>\n<p>As tr\u00eas primeiras cotas do repasse ser\u00e3o realizadas nos pr\u00f3ximos dias, totalizando R$ 36 milh\u00f5es.<\/p>\n<p>Mauro havia decidido, j\u00e1 no ano passado, que o estado iria compensar os munic\u00edpios pelas perdas de arrecada\u00e7\u00e3o, de forma a evitar preju\u00edzo \u00e0s obras e a\u00e7\u00f5es que as prefeituras prestam \u00e0 popula\u00e7\u00e3o, em especial na manuten\u00e7\u00e3o das estradas municipais.<\/p>\n<p>\u201cSabemos o quanto essa perda abala o caixa das prefeituras. Por isso, decidimos fazer a recomposi\u00e7\u00e3o para que nenhuma cidade seja impactada negativamente pela extin\u00e7\u00e3o do Fethab Diesel\u201d, afirmou o governador.<\/p>\n<p>O vice-governador Otaviano Pivetta ressaltou a parceria que o estado tem mantido com os munic\u00edpios desde o in\u00edcio da gest\u00e3o.<\/p>\n<p>&#8220;O Governo tem feito investimentos recordes em todos os munic\u00edpios, seja de forma direta ou por meio de conv\u00eanios. Somos uma gest\u00e3o municipalista e sempre vamos dar todo o apoio nas a\u00e7\u00f5es que beneficiam a popula\u00e7\u00e3o, afirmou.<\/p>\n<p>De acordo com o decreto, a recomposi\u00e7\u00e3o vai ocorrer por meio de 12 cotas. Neste m\u00eas, ser\u00e3o pagas tr\u00eas cotas, e at\u00e9 novembro uma cota mensal.<\/p>\n<p>Os valores repassados seguem o seguinte crit\u00e9rio: 30% considerando o quantitativo de quil\u00f4metros de estradas estaduais n\u00e3o pavimentadas que estejam nos limites do munic\u00edpio; e 70% considerando o quantitativo de quil\u00f4metros de estradas municipais n\u00e3o pavimentadas.<\/p>\n<p>\u201cO aux\u00edlio financeiro dever\u00e1 ser destinado, exclusivamente, aos seguintes fins: manuten\u00e7\u00e3o das rodovias estaduais n\u00e3o pavimentadas; obras de constru\u00e7\u00e3o e manuten\u00e7\u00e3o de rodovias municipais, incluindo pontes e bueiros; manuten\u00e7\u00e3o ou constru\u00e7\u00e3o de bueiros e pontes de at\u00e9 doze metros nas rodovias estaduais n\u00e3o pavimentadas; aquisi\u00e7\u00e3o e manuten\u00e7\u00e3o de equipamentos rodovi\u00e1rios, combust\u00edveis, lubrificantes, pe\u00e7as e servi\u00e7os de manuten\u00e7\u00e3o\u201d, diz trecho do documento.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Mayke Toscano\/Secom-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes assinou decreto, nesta quarta-feira (26.2), que prev\u00ea o repasse de mais &hellip;<\/p>\n","protected":false},"author":4,"featured_media":90391,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-90390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Decreto foi assinado nesta quarta-feira (26); primeiras cotas do repasse ser\u00e3o feitas ainda nesta semana","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/90390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=90390"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/90390\/revisions"}],"predecessor-version":[{"id":90392,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/90390\/revisions\/90392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/90391"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=90390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=90390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=90390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}