{"id":91088,"date":"2025-03-21T12:01:41","date_gmt":"2025-03-21T16:01:41","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=91088"},"modified":"2025-03-21T12:01:41","modified_gmt":"2025-03-21T16:01:41","slug":"prefeito-dialoga-sobre-projetos-culturais-com-o-cantor-e-ator-mauricio-mattar","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeito-dialoga-sobre-projetos-culturais-com-o-cantor-e-ator-mauricio-mattar\/","title":{"rendered":"Prefeito dialoga sobre projetos culturais com o cantor e ator Maur\u00edcio Mattar"},"content":{"rendered":"<p>Com o objetivo de estreitar as amizades e fortalecer futuros projetos, o ator e cantor Maur\u00edcio Mattar, acompanhado de sua equipe de produ\u00e7\u00e3o, fez uma visita e foi recebido pelo prefeito Abilio Brunini, no Pal\u00e1cio Alencastro, na tarde de quinta-feira (20). Os secret\u00e1rios municipais de Esporte e Lazer, Jefferson Neves, o de Turismo e Desenvolvimento Econ\u00f4mico, Fernando Medeiros,\u00a0o de Cultura, Johnny Everson e o de\u00a0Habita\u00e7\u00e3o e Regulariza\u00e7\u00e3o Fundi\u00e1ria,\u00a0Willian Campos, tamb\u00e9m estiveram presentes, contribuindo com ideias.<\/p>\n<p>Segundo o secret\u00e1rio Jefferson, o ator j\u00e1 tem uma presen\u00e7a muito forte no Estado, costuma sempre estar por aqui encampando projetos, inclusive trabalharam juntos ao Governo no Estado no passado. \u201cEle veio apresentar essa imagem e ajudar Mato Grosso, Cuiab\u00e1, em divulgar sua imagem ao n\u00edvel nacional. A ideia \u00e9 essa, pegar os projetos que n\u00f3s temos de qualidade aqui em Cuiab\u00e1 e dar visibilidade que o Maur\u00edcio tem. Isso para que a capital se torne mais reconhecida, pela sua cultura, sua arte e tudo aquilo que podemos oferecer para o nosso pa\u00eds\u201d, explicou o secret\u00e1rio.<\/p>\n<p>Segundo o prefeito Abilio, na \u00e1rea do cinema, produ\u00e7\u00f5es atemporais seriam bem-vindas. \u201cEventos passam e coisas atemporais marcam e permanecem vivas na mem\u00f3ria, e o povo se v\u00ea pertencente\u201d, destacou o gestor, ao lembrar que Cuiab\u00e1 ainda \u00e9 carente nesse cen\u00e1rio.<\/p>\n<p>\u201cFoi muito gratificante, \u00e9 sempre muito positivo a gente poder falar de projetos novos, principalmente, no meu caso, sobre a arte, sobre a cultura, trazendo ideias e projetos para uma terra que tem muita riqueza de informa\u00e7\u00e3o cultural, de muitos segredos e mist\u00e9rios que o p\u00fablico do Brasil inteiro n\u00e3o conhece. Ent\u00e3o, acho que isso \u00e9 sempre gratificante fomentar projetos e tomara que eles se tornem realidade\u201d, pontuou Maur\u00edcio Mattar.<\/p>\n<p>Na oportunidade o cantor falou dos 30 anos de carreira que virou um projeto comemorativo com o show \u201cNada Paga Essa Paix\u00e3o\u201d, cuja turn\u00ea percorrer\u00e1 o pa\u00eds, e com perspectiva de incluir Cuiab\u00e1 na rota da programa\u00e7\u00e3o.<\/p>\n<p>\u201cEspero que em breve eu venha pra c\u00e1, pra fazer algum show novamente. Seja pra show, o para alguns projetos. \u00c9, projetos. Muita coisa vai brotar e vai se realizar\u201d, disse ele.<\/p>\n<p><strong>#PraCegoVer<\/strong><\/p>\n<p>A foto registra o momento em que o prefeito Abilio Brunini mostra a cidade de Cuiab\u00e1 ao cantor Maur\u00edcio Mattar, numa vis\u00e3o ampla do terra\u00e7o do Pal\u00e1cio Alencastro, sede da Prefeitura de Cuiab\u00e1. Os secret\u00e1rios de Cultura, Johnny Everson, de Turismo, Fernando Medeiros e o de Esporte e Lazer, Jefferson Neves tamb\u00e9m est\u00e3o na imagem.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Rennan Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de estreitar as amizades e fortalecer futuros projetos, o ator e cantor &hellip;<\/p>\n","protected":false},"author":4,"featured_media":91089,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-91088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/91088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=91088"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/91088\/revisions"}],"predecessor-version":[{"id":91090,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/91088\/revisions\/91090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/91089"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=91088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=91088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=91088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}