{"id":91194,"date":"2025-03-25T10:04:23","date_gmt":"2025-03-25T14:04:23","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=91194"},"modified":"2025-03-25T10:04:23","modified_gmt":"2025-03-25T14:04:23","slug":"mercado-de-acucar-enfrenta-incertezas-com-deficit-na-safra-e-volatilidade-nos-precos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mercado-de-acucar-enfrenta-incertezas-com-deficit-na-safra-e-volatilidade-nos-precos\/","title":{"rendered":"Mercado de a\u00e7\u00facar enfrenta incertezas com d\u00e9ficit na safra e volatilidade nos pre\u00e7os"},"content":{"rendered":"<p class=\"\" data-start=\"96\" data-end=\"593\">O Brasil, maior exportador de a\u00e7\u00facar do mundo, enfrenta um cen\u00e1rio desafiador na safra 2024\/25, com um d\u00e9ficit projetado de 4,1 milh\u00f5es de toneladas. O mercado foi impactado pela entrega recorde de contratos no final de fevereiro, totalizando 34,4 mil contratos \u2013 o equivalente a 1,7 milh\u00e3o de toneladas de a\u00e7\u00facar. Esse movimento gerou preocupa\u00e7\u00f5es sobre a demanda global, j\u00e1 que muitos traders entregaram a\u00e7\u00facar sem um destino definido, o que pode indicar um enfraquecimento do consumo mundial.<\/p>\n<p class=\"\" data-start=\"595\" data-end=\"1151\">Apesar disso, os pre\u00e7os internacionais do a\u00e7\u00facar registraram uma leve alta no final de fevereiro. O contrato para mar\u00e7o de 2025 subiu 0,8%, fechando a R$ 112,30 por libra-peso. No entanto, ap\u00f3s o vencimento desse contrato, os pre\u00e7os recuaram, refletindo o grande volume de entregas e as perspectivas de produ\u00e7\u00e3o na \u00cdndia e na Tail\u00e2ndia. As estimativas para a safra indiana de 2024\/25 variam entre 26 e 28 milh\u00f5es de toneladas, mas proje\u00e7\u00f5es mais otimistas indicam que a produ\u00e7\u00e3o pode alcan\u00e7ar 32 milh\u00f5es de toneladas, dependendo das condi\u00e7\u00f5es clim\u00e1ticas.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"uee28e67b8420c1d05b78f2be4d2e5972-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Livro e revista sobre o Agroneg\u00f3cio Brasileiro ser\u00e3o lan\u00e7ados hoje em Cuiab\u00e1<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p class=\"\" data-start=\"1223\" data-end=\"1543\">O evento Dubai Week, realizado nos Emirados \u00c1rabes Unidos, trouxe an\u00e1lises sobre o mercado global de a\u00e7\u00facar, destacando que a oferta continuar\u00e1 restrita no curto prazo. No entanto, para a safra 2025\/26, a expectativa \u00e9 de um super\u00e1vit na produ\u00e7\u00e3o global, podendo levar a uma press\u00e3o sobre os pre\u00e7os internacionais.<\/p>\n<p class=\"\" data-start=\"1545\" data-end=\"1965\">No Brasil, as proje\u00e7\u00f5es para a safra 2025\/26 indicam um super\u00e1vit de 4,4 milh\u00f5es de toneladas, trazendo um cen\u00e1rio mais otimista. No entanto, a produ\u00e7\u00e3o no Centro-Sul, que inicia a colheita em abril, enfrenta desafios como o impacto de inc\u00eandios ocorridos no ano passado e um clima inst\u00e1vel. A disponibilidade de cana para moagem e os custos de produ\u00e7\u00e3o s\u00e3o fatores que podem influenciar a oferta de a\u00e7\u00facar no mercado.<\/p>\n<p class=\"\" data-start=\"2018\" data-end=\"2560\">A expans\u00e3o da produ\u00e7\u00e3o mundial de a\u00e7\u00facar na safra 2025\/26 depender\u00e1 de fatores como a recupera\u00e7\u00e3o do clima e a manuten\u00e7\u00e3o de uma demanda firme. No Brasil, a queda nos pre\u00e7os internacionais pode levar as usinas a direcionarem mais cana para a produ\u00e7\u00e3o de etanol, reduzindo a oferta de a\u00e7\u00facar. Tradicionalmente, a produ\u00e7\u00e3o de a\u00e7\u00facar se torna mais vantajosa quando os pre\u00e7os do a\u00e7\u00facar bruto superam R$ 17,28 por libra-peso. No entanto, se os pre\u00e7os permanecerem abaixo de R$ 106,56 por libra-peso, a produ\u00e7\u00e3o de etanol pode ser mais lucrativa.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"ub157ef1ba3a8634867177d4d83d4b515-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Vendas da soja na Bahia atingem 35%; mercado fecha a semana com pre\u00e7os em queda<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p class=\"\" data-start=\"2562\" data-end=\"2879\">Diante desse cen\u00e1rio, as proje\u00e7\u00f5es para a produ\u00e7\u00e3o brasileira de a\u00e7\u00facar ainda podem ser revistas, caso as condi\u00e7\u00f5es clim\u00e1ticas e os pre\u00e7os internacionais n\u00e3o evoluam conforme o esperado. A incerteza sobre a oferta e a volatilidade dos pre\u00e7os s\u00e3o fatores que devem continuar influenciando o mercado nos pr\u00f3ximos meses.<\/p>\n<p data-start=\"2562\" data-end=\"2879\">\n<p data-start=\"2562\" data-end=\"2879\">\n<p data-start=\"2562\" data-end=\"2879\"><a href=\"https:\/\/pensaragro.com.br\/mercado-de-acucar-enfrenta-incertezas-com-deficit-na-safra-e-volatilidade-nos-precos\/\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil, maior exportador de a\u00e7\u00facar do mundo, enfrenta um cen\u00e1rio desafiador na safra 2024\/25, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":91195,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-91194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/91194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=91194"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/91194\/revisions"}],"predecessor-version":[{"id":91196,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/91194\/revisions\/91196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/91195"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=91194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=91194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=91194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}