{"id":92191,"date":"2025-04-20T13:53:28","date_gmt":"2025-04-20T17:53:28","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=92191"},"modified":"2025-04-20T13:53:28","modified_gmt":"2025-04-20T17:53:28","slug":"sema-contribui-para-melhorias-implementadas-no-monitoramento-reprodutivo-de-peixes-em-2023-e-2024","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sema-contribui-para-melhorias-implementadas-no-monitoramento-reprodutivo-de-peixes-em-2023-e-2024\/","title":{"rendered":"Sema contribui para melhorias implementadas no monitoramento reprodutivo de peixes em 2023 e 2024"},"content":{"rendered":"<p>Na \u00faltima reuni\u00e3o ordin\u00e1ria do Conselho Estadual de Pesca (Cepesca), realizada em 10 de abril, em que foi definido o per\u00edodo de defeso da piracema de 2025, foram apresentados os avan\u00e7os no monitoramento reprodutivo dos peixes de interesse pesqueiro, realizados com apoio da Secretaria de Estado de Meio Ambiente (Sema). Os dados contribuem para a precis\u00e3o das informa\u00e7\u00f5es obtidas sobre as atividades reprodutivas das esp\u00e9cies e subsidia a decis\u00e3o do Conselho sobre manter o mesmo per\u00edodo de defeso.<\/p>\n<p>Os dados t\u00e9cnicos sobre o monitoramento foram apresentados, durante a reuni\u00e3o, pelo pesquisador da Universidade Estadual de Mato Grosso (Unemat), Claumir Muniz, que destacou entre as melhorias implementadas, o aumento dos pontos de coleta nas bacias Amaz\u00f4nica e Pantanal. Os rios Manso, Piquiri e Cuiab\u00e1 (tamb\u00e9m conhecido como S\u00e3o Louren\u00e7o) foram os adicionados ao monitoramento.<\/p>\n<p>Al\u00e9m disso, avan\u00e7os foram realizados no estudo de indica\u00e7\u00e3o dos s\u00edtios de desova e na organiza\u00e7\u00e3o do banco de dados de ovos e larvas, com a inclus\u00e3o de novos locais at\u00e9 ent\u00e3o n\u00e3o monitorados. Foram adicionados aos pontos de coleta, os rios Jauru, Caba\u00e7al, Sepotuba e a \u00e1rea da Esta\u00e7\u00e3o Ecol\u00f3gica de Taiam\u00e3, aumentando consideravelmente a amplitude amostral.<\/p>\n<p>Sobre a import\u00e2ncia dessas melhorias implementadas no monitoramento e seu impacto nos estudos das atividades reprodutivas das esp\u00e9cies, o pesquisador Claumir Muniz, destaca que \u201co aumento dos s\u00edtios amostrais representa uma maior seguran\u00e7a na defini\u00e7\u00e3o do per\u00edodo de defeso, garantindo a manuten\u00e7\u00e3o da ictiofauna\u201d, que define o conjunto de peixes que habita uma determinada regi\u00e3o.<\/p>\n<p>Muniz tamb\u00e9m destacou o papel fundamental que o apoio da Sema teve nesse processo, j\u00e1 a disponibiliza\u00e7\u00e3o de recursos foi essencial para que os estudos atingissem os objetivos tra\u00e7ados. \u201cO aporte financeiro mediado pela Sema foi importante para as atividades desenvolvidas, gerando mais dados e seguran\u00e7a anal\u00edtica para gest\u00e3o dos recursos pesqueiros\u201d, concluiu o pesquisador.<\/p>\n<p><em>*Com supervis\u00e3o de Renata Prata\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima reuni\u00e3o ordin\u00e1ria do Conselho Estadual de Pesca (Cepesca), realizada em 10 de abril, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":92192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-92191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Sema contribui para melhorias implementadas no monitoramento reprodutivo de peixes em 2023 e 2024","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/92191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=92191"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/92191\/revisions"}],"predecessor-version":[{"id":92193,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/92191\/revisions\/92193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/92192"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=92191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=92191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=92191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}