{"id":92260,"date":"2025-04-22T15:21:45","date_gmt":"2025-04-22T19:21:45","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=92260"},"modified":"2025-04-22T15:21:45","modified_gmt":"2025-04-22T19:21:45","slug":"governo-deve-investir-cerca-de-r-900-milhoes-no-parque-novo-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governo-deve-investir-cerca-de-r-900-milhoes-no-parque-novo-mato-grosso\/","title":{"rendered":"Governo deve investir cerca de R$ 900 milh\u00f5es no Parque Novo Mato Grosso"},"content":{"rendered":"<p>A Comiss\u00e3o de Infraestrutura Urbana e de Transportes da Assembleia Legislativa de Mato Grosso (ALMT) ouviu, na manh\u00e3 desta ter\u00e7a-feira (22), o presidente da Mato Grosso Participa\u00e7\u00f5es e Projetos (MT Par), Wener Kesley dos Santos, para prestar esclarecimentos sobre o andamento das obras do Parque Novo Mato Grosso, localizado na regi\u00e3o de Chapada dos Guimar\u00e3es.<\/p>\n<p>Nas obras, a previs\u00e3o \u00e9 de o Governo do Estado de Mato Grosso investir R$ 900 milh\u00f5es. De acordo com o presidente do MT Par, a obra deve ficar pronta e ser entregue 100% \u00e0 popula\u00e7\u00e3o at\u00e9 o final de 2026. No contrato com as construtoras, segundo Santos, a m\u00e9dia para a entrega das obras \u00e9 de 14 meses.<\/p>\n<p>\u201cEstamos torcendo para que as empresas boas ganhem para as obras n\u00e3o travarem. Por isso, o governo trabalha para entregar 100% do Parque Novo Mato Grosso at\u00e9 o final do pr\u00f3ximo ano. A parte que leva mais tempo para ser executada, a terraplanagem, est\u00e1 pronta. Com isso, ganhamos um tempo na execu\u00e7\u00e3o das obras\u201d, explicou Santos. \u200b<\/p>\n<p>O presidente da Comiss\u00e3o de Infraestrutura da Assembleia Legislativa, deputado Valmir Moretto (Republicanos), afirmou que a maior preocupa\u00e7\u00e3o n\u00e3o \u00e9 em rela\u00e7\u00e3o aos custos da obra, mas o valor a ser cobrado da popula\u00e7\u00e3o mato-grossense e dos turistas para terem acesso ao parque.<\/p>\n<p>\u201cN\u00e3o ser\u00e1 cobrada taxa de entrada ao parque. O presidente do MT Par nos deixou tranquilo, o governo vai cobrar apenas uma taxa de manuten\u00e7\u00e3o \u00e0s pessoas que utilizarem os equipamentos. Esperamos que as obras sejam entregues at\u00e9 o final de 2026, mas sabemos da dificuldade com a m\u00e3o de obra em Mato Grosso\u201d, explicou Moretto.<\/p>\n<p>A proposta inicial do governo para o Parque Novo Mato Grosso, de acordo com Wener Santos, era \u00e0 constru\u00e7\u00e3o de um aut\u00f3dromo, mas depois veio as expectativas para a constru\u00e7\u00e3o de outras \u00e1reas esportivas e para shows. Hoje, segundo ele, a pista do Kart\u00f3dromo est\u00e1 pronta. Quando o parque estiver pronto, de acordo com Santos, ser\u00e1 refer\u00eancia para a Am\u00e9rica Latina.<\/p>\n<p>\u201cO Parque tem um conceito diferenciado no mundo. N\u00e3o \u00e9 s\u00f3 para eventos de corrida, \u00e9 para esporte, \u00e9 para cultura, \u00e9 para lazer e \u00e9 para o turismo. \u00c9 o espa\u00e7o onde vamos atrair turistas e investidores de todo o Brasil e do mundo e, com isso, mostrar a for\u00e7a que Mato Grosso tem tamb\u00e9m com o turismo\u201d, explicou o presidente do MT Par.<\/p>\n<p>\u201cQueremos entregar uma parte da obra ainda este ano e a segunda etapa at\u00e9 o final de 2026. No parque s\u00e3o v\u00e1rias frentes de obra, tem setores com 70%, 80%, 90% e at\u00e9 30% conclu\u00eddas, porque cada um \u00e9 um contrato diferente. O espa\u00e7o show est\u00e1 com 60% feito e queremos inaugur\u00e1-lo em novembro desse ano\u201d, afirmou Santos.<\/p>\n<p>O vice-presidente da Comiss\u00e3o de Infraestrutura, deputado J\u00falio Campos (Uni\u00e3o), afirmou que a obra \u00e9 suntuosa e que vai ficar na hist\u00f3ria de Mato Grosso e, por isso, questionou Wener Santos se pelo menos 70% das obras ser\u00e3o entregues at\u00e9 o final de 2026. Wener Santos respondeu que sim. \u201cO nosso foco \u00e9 fazer a entrega \u00e0 popula\u00e7\u00e3o at\u00e9 o final de 2026\u201d, refor\u00e7ou.<\/p>\n<p>Uma das atra\u00e7\u00f5es do Parque, segundo Santos, \u00e9 a roda gigante com aproximadamente 108 metros de altura. Ela \u00e9 composta por 42 cabines, com capacidade m\u00e1xima de oito pessoas por cabine, totalizando 336 pessoas. Ela poder\u00e1 ser vista a partir do centro da cidade e tamb\u00e9m da rodovia que d\u00e1 acesso \u00e0 Chapada dos Guimar\u00e3es.<\/p>\n<p>J\u00e1 o Espa\u00e7o Show para eventos nacionais e internacionais tem a capacidade para 80 mil pessoas, ocupando uma \u00e1rea total de 45 mil m\u00b2. Enquanto isso. o projeto do aut\u00f3dromo abrange uma \u00e1rea de aproximadamente 83 hectares e inclui diversos circuitos e edifica\u00e7\u00f5es, como uma pista de autocross e uma de arrancada.<\/p>\n<p>O aut\u00f3dromo contar\u00e1 com camarotes e arquibancadas localizados pr\u00f3ximos \u00e0 reta principal do circuito. A pista principal ter\u00e1 cerca de 4,6 km de extens\u00e3o e o aut\u00f3dromo ser\u00e1 preparado para receber competi\u00e7\u00f5es de velocidade em n\u00edvel regional, nacional e internacional.<\/p>\n<p>A pista de kart profissional tem uma infraestrutura de 95.571,42 m\u00b2, oferece arquibancada, paddock, estacionamento, salas de apoio, p\u00f3dio e torre de vigil\u00e2ncia. A pista foi projetada para possibilitar mais de 20 circuitos diferentes, sendo o maior deles com 1.150 metros de extens\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 ALMT\u00a0 \u00a0|\u00a0 \u00a0 Foto:\u00a0 <i>GILBERTO LEITE<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Infraestrutura Urbana e de Transportes da Assembleia Legislativa de Mato Grosso (ALMT) &hellip;<\/p>\n","protected":false},"author":4,"featured_media":92261,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-92260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"A Comiss\u00e3o de Infraestrutura deve fazer uma visita in loco no Parque Novo Mato Grosso nos pr\u00f3ximos dias","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/92260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=92260"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/92260\/revisions"}],"predecessor-version":[{"id":92262,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/92260\/revisions\/92262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/92261"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=92260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=92260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=92260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}