{"id":93049,"date":"2025-05-13T13:00:30","date_gmt":"2025-05-13T17:00:30","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=93049"},"modified":"2025-05-13T13:00:30","modified_gmt":"2025-05-13T17:00:30","slug":"deputados-aprovam-em-1a-votacao-projeto-que-altera-cadastro-estadual-de-pedofilos-em-mt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/deputados-aprovam-em-1a-votacao-projeto-que-altera-cadastro-estadual-de-pedofilos-em-mt\/","title":{"rendered":"Deputados aprovam em 1\u00aa vota\u00e7\u00e3o projeto que altera Cadastro Estadual de Ped\u00f3filos em MT"},"content":{"rendered":"<p>Os deputados estaduais de Mato Grosso aprovaram por unanimidade, em sess\u00e3o ordin\u00e1ria, o<a href=\"https:\/\/www.al.mt.gov.br\/proposicao?almt_form_proposicao_search_proposicao%5BtipoPropositura%5D=1&amp;almt_form_proposicao_search_proposicao%5BpalavraChave%5D=&amp;almt_form_proposicao_search_proposicao%5BnumeroPropositura%5D=527&amp;almt_form_proposicao_search_proposicao%5Bano%5D=2025&amp;almt_form_proposicao_search_proposicao%5Bautor%5D=&amp;almt_form_proposicao_search_proposicao%5BdataPublicacaoInicio%5D=&amp;almt_form_proposicao_search_proposicao%5BdataPublicacaoFim%5D=&amp;almt_form_proposicao_search_proposicao%5BbuscaTextual%5D=&amp;almt_form_proposicao_search_proposicao%5B_token%5D=c4798b54651a84e73cc118a8a66556a.foDbtSlhMy769SwlUx1idOsZSfyKQ4VyG5KqHKgxtGA.Kt-BxxBXQmWIkHVNFEooAoBNcJK4btwRItzQSJhkggE5ybD-ECZnFp6ZfQ\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0Projeto de Lei n\u00b0 527\/2025<\/a>, \u201cque altera dispositivos da Lei n\u00b0 10.315, de 15 de setembro de 2015, que cria o Cadastro Estadual de Ped\u00f3filos do Estado de Mato Grosso, e da Lei n\u00b0 10.915, de 1\u00ba de julho de 2019, que determina a veicula\u00e7\u00e3o na internet de pessoas condenadas por crime de viol\u00eancia contra a mulher praticado contra a mulher no Estado\u201d.<br \/>\nO artigo 1\u00ba do PL aprovado altera o caput e os incisos I, II, III e IV, todos do artigo 3\u00ba da Lei 10.315. O artigo 3\u00ba passa a vigorar com a seguinte reda\u00e7\u00e3o: \u201cO Cadastro Estadual de Ped\u00f3filos do Estado de Mato Grosso ser\u00e1 de acesso p\u00fablico e conter\u00e1 a rela\u00e7\u00e3o de pessoas condenadas, com senten\u00e7a transitado em julgado, por crimes contra a dignidade sexual previstos no Estatuto da Crian\u00e7a e do Adolescente, no C\u00f3digo Penal Brasileiro e em legisla\u00e7\u00f5es penais espec\u00edficas, quando praticados contra crian\u00e7as e ou adolescentes\u201d.<br \/>\nO artigo 2\u00ba altera os incisos I e II do artigo 4\u00ba da Lei 10.315, de 15 de setembro de 2015, que fica com a seguinte reda\u00e7\u00e3o: \u201cqualquer pessoa poder\u00e1 acessar o Cadastro Estadual de Ped\u00f3filos do Estado de Mato Grosso, cujos dados ser\u00e3o de acesso p\u00fablico a partir da condena\u00e7\u00e3o em senten\u00e7a transitada em julgado at\u00e9 o t\u00e9rmino do cumprimento da pena\u201d.<br \/>\nNa Lei 10.915, de 1\u00ba de julho de 2019, as altera\u00e7\u00f5es s\u00e3o no caput, o par\u00e1grafo \u00fanico, que fica remunerado para par\u00e1grafo 1\u00ba, bem como alterados os incisos I e II, todos do artigo 1\u00ba da referida lei. Com isso, o artigo 1\u00ba passa a vigorar: \u201cfica criado o Cadastro Estadual de Condenados por Crime de Viol\u00eancia contra a Mulher praticado no Estado de Mato Grosso, destinado a registrar pessoas condenadas criminalmente com senten\u00e7a transitada em julgado, por qualquer dos crimes de viol\u00eancia praticados contra a mulher no Estado\u201d.<br \/>\nNo artigo 6\u00ba do PL 527\/2025, a altera\u00e7\u00e3o no caput e acrescidos os par\u00e1grafos 1\u00ba e 2\u00ba ao artigo 2\u00ba da Lei 10.915, de julho de 2019. O artigo 2\u00ba fica com esta nova reda\u00e7\u00e3o: \u201cA Secretaria de Estado de Seguran\u00e7a P\u00fablica regulamentar\u00e1 a cria\u00e7\u00e3o, a atualiza\u00e7\u00e3o e o acesso ao Cadastro Estadual de Condenados por Crime de Viol\u00eancia contra a Mulher no Estado de Mato Grosso\u201d. O par\u00e1grafo 1\u00ba cita que \u201caos indiv\u00edduos com nome inscrito neste cadastro, fica vedada a investidura em cargos p\u00fablicos da Administra\u00e7\u00e3o P\u00fablica direta, indireta, autarquias e funda\u00e7\u00f5es no \u00e2mbito do Estado de Mato Grosso\u201d.<br \/>\nO par\u00e1grafo 2\u00ba diz que \u201cpara retirada do nome do referido cadastro, o interessado dever\u00e1 apresentar requerimento dirigido ao secret\u00e1rio de Estado de Seguran\u00e7a P\u00fablica, comprovando o cumprimento da pena, a qual ser\u00e1 realizada a confirma\u00e7\u00e3o pelo \u00f3rg\u00e3o competente das informa\u00e7\u00f5es constantes do requerimento e retirado seu nome dos cadastros, num prazo m\u00e1ximo de 60 (sessenta dias)\u201d.<br \/>\nEm justificativa ao PL, o Executivo argumenta que \u201ca presente proposta se faz necess\u00e1ria para adequa\u00e7\u00e3o da norma, tendo como par\u00e2metro o entendimento constante no Ac\u00f3rd\u00e3o proferido pelo Supremo Tribunal Federal na A\u00e7\u00e3o Direta de Inconstitucionalidade \u2014 ADI n\u00b0 6.620 &#8212; que validou a cria\u00e7\u00e3o dos cadastros, desde que a disponibiliza\u00e7\u00e3o, em s\u00edtio eletr\u00f4nico, se restrinja \u00e0s condena\u00e7\u00f5es transitadas em julgado.<br \/>\n\u201cNesta esteira, al\u00e9m da necessidade de conferir interpreta\u00e7\u00e3o conforme a Constitui\u00e7\u00e3o Federal, as altera\u00e7\u00f5es propostas visam tamb\u00e9m otimizar a implanta\u00e7\u00e3o dos Cadastros Estaduais (Ped\u00f3filos e Condenador por Viol\u00eancia contra a Mulher) pelo Poder Executivo Estadual, no \u00e2mbito da Secretaria de Estado de Seguran\u00e7a P\u00fablica\u201d, observa ainda na justificativa.<br \/>\nEm rela\u00e7\u00e3o ao Cadastro Estadual de Ped\u00f3filos, o Executivo cita que \u201ca altera\u00e7\u00e3o permitir\u00e1 o acesso p\u00fablico dos dados do r\u00e9u a partir de condena\u00e7\u00e3o em senten\u00e7a transitada em julgado, com amplia\u00e7\u00e3o do rol dos crimes, vez que no texto anterior constava apenas C\u00f3digo Penal Brasileiro, e com a nova reda\u00e7\u00e3o, constar\u00e1 previstos os crimes contra a dignidade sexual previstos no Estatuto da Crian\u00e7a e do Adolescente, e na legisla\u00e7\u00e3o penal extravagante, al\u00e9m do previsto no C\u00f3digo Penal Brasileiro, quando praticados contra a crian\u00e7a e ou adolescente\u201d.<\/p>\n<p>O projeto foi aprovado em primeira vota\u00e7\u00e3o no dia 7 de maio e j\u00e1 passou por tr\u00eas sess\u00f5es e pode ser aprovado em segunda vota\u00e7\u00e3o j\u00e1 na sess\u00e3o plen\u00e1ria desta quarta-feira (14).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ALMT\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 <i>Luciano Campbell\/ALMT<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os deputados estaduais de Mato Grosso aprovaram por unanimidade, em sess\u00e3o ordin\u00e1ria, o\u00a0Projeto de Lei &hellip;<\/p>\n","protected":false},"author":4,"featured_media":93050,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-93049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"O Projeto de Lei n\u00b0 527\/2025, do Poder Executivo, foi aprovado e segue agora para vota\u00e7\u00e3o em segunda","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=93049"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93049\/revisions"}],"predecessor-version":[{"id":93051,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93049\/revisions\/93051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/93050"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=93049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=93049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=93049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}