{"id":93183,"date":"2025-05-19T09:59:49","date_gmt":"2025-05-19T13:59:49","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=93183"},"modified":"2025-05-19T10:00:57","modified_gmt":"2025-05-19T14:00:57","slug":"cursos-de-limpeza-de-pele-e-bolos-decorados-comecam-nesta-segunda","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/cursos-de-limpeza-de-pele-e-bolos-decorados-comecam-nesta-segunda\/","title":{"rendered":"Cursos de \u201cLimpeza de Pele\u201d e \u201cBolos Decorados\u201d come\u00e7am nesta segunda"},"content":{"rendered":"<p dir=\"ltr\">Cerca de 40 mulheres cuiabanas iniciam, na pr\u00f3xima semana, os cursos de \u201cBolos e Docinhos Decorados\u201d e \u201cLimpeza de Pele\u201d, promovidos pela Secretaria Municipal da Mulher (SMM), por meio do Programa Escola da Mulher, em parceria com o Senac (Servi\u00e7o Nacional de Aprendizagem Comercial).<\/p>\n<p dir=\"ltr\">Ao todo, 340 mulheres ser\u00e3o capacitadas para o mercado de trabalho, com cursos gratuitos oferecidos nos meses de maio e junho.<\/p>\n<p dir=\"ltr\">O curso de \u201cBolos e Docinhos Decorados\u201d ser\u00e1 realizado na Igreja Adna, localizada na Rua Greg\u00f3rio de Matos Guerra, no bairro Santa Cruz. Tamb\u00e9m a partir de segunda-feira (19), ter\u00e1 in\u00edcio o curso de \u201cLimpeza de Pele\u201d, destinado \u00e0s mulheres inscritas no programa.<\/p>\n<p dir=\"ltr\">A secret\u00e1ria da Mulher, tenente-coronel Hadassah Suzannah, refor\u00e7a o compromisso da gest\u00e3o municipal com o desenvolvimento e fortalecimento da autonomia feminina na capital mato-grossense: \u201cNossa miss\u00e3o, enquanto Secretaria da Mulher, \u00e9 justamente levar mais qualifica\u00e7\u00e3o, autonomia e oportunidades para todas as mulheres de Cuiab\u00e1. Acreditamos que investir em capacita\u00e7\u00e3o \u00e9 uma forma efetiva de promover a verdadeira transforma\u00e7\u00e3o social\u201d, afirmou Hadassah.<\/p>\n<p dir=\"ltr\">A secret\u00e1ria-adjunta da Mulher, Stefanya Paiva, completou, enfatizando que a iniciativa tem como objetivo a qualifica\u00e7\u00e3o e o empoderamento de mulheres em situa\u00e7\u00e3o de vulnerabilidade, com foco na gera\u00e7\u00e3o de renda, inser\u00e7\u00e3o no mercado de trabalho e conquista da autonomia financeira.<\/p>\n<p dir=\"ltr\">Al\u00e9m dos cursos de \u201cLimpeza de Pele\u201d e \u201cBolos e Docinhos Decorados\u201d, est\u00e3o dispon\u00edveis vagas para os cursos de: assistente financeiro, recepcionista, produ\u00e7\u00e3o de salgados, qualidade no atendimento, tran\u00e7as, cabeleireiro, manicure e pedicure, unhas de gel e assistente de recursos humanos. Todas as forma\u00e7\u00f5es s\u00e3o gratuitas e oferecem certificado com reconhecimento do Senac.<\/p>\n<p dir=\"ltr\">Interessadas podem se inscrever por meio do formul\u00e1rio online, dispon\u00edvel no link: https:\/\/formulario.mt.senac.br\/lead\/educacao-que-transforma.<\/p>\n<p dir=\"ltr\">A Secretaria Municipal da Mulher disponibiliza o contato:<strong>\u00a0(65) 9 9917-7739<\/strong>\u00a0para esclarecimento de d\u00favidas.<\/p>\n<p dir=\"ltr\"><strong>CONFIRA ABAIXO AS AGENDAS DOS CURSOS<\/strong><\/p>\n<p dir=\"ltr\">Bolos e Docinhos Decorados<\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">19\/05 a 23\/05\/2025<\/p>\n<p dir=\"ltr\">07h30 \u00e0s 11h30 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: Igreja Adna | R. Greg\u00f3rio de Matos Guerra, 10 &#8211; Santa Cruz<\/p>\n<p dir=\"ltr\"><strong>Limpeza de Pele<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">19\/05 a 18\/07\/2025<\/p>\n<p dir=\"ltr\">18h30 \u00e0s 21h30 (segunda, ter\u00e7a e quarta-feira)<\/p>\n<p dir=\"ltr\">Local: Escola Municipal Ranulfo Paes de Barros | Santa Isabel<\/p>\n<p dir=\"ltr\"><strong>Panifica\u00e7\u00e3o e Confeitaria<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">26\/05 a 23\/06\/2025<\/p>\n<p dir=\"ltr\">07h30 \u00e0s 11h30 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: SENAC | Av. Edgar Vieira, 1.625 &#8211; Boa Esperan\u00e7a<\/p>\n<p dir=\"ltr\">Marketing em M\u00eddias Digitais e Redes Sociais<\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">26\/05 a 30\/05\/2025<\/p>\n<p dir=\"ltr\">07h30 \u00e0s 11h30 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: Igreja Adna | R. Greg\u00f3rio de Matos Guerra, 10 &#8211; Santa Cruz<\/p>\n<p dir=\"ltr\"><strong>Qualidade no Atendimento<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">26\/05 a 16\/06\/2025<\/p>\n<p dir=\"ltr\">13h30 \u00e0s 17h30 (segunda, quarta e sexta-feira)<\/p>\n<p dir=\"ltr\">Local: Secretaria Municipal da Mulher | Av. Pres. Get\u00falio Vargas, 490<\/p>\n<p dir=\"ltr\"><strong>Massagista<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">26\/05 a 18\/08\/2025<\/p>\n<p dir=\"ltr\">07h30 \u00e0s 11h30 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: SENAC | Av. Edgar Vieira, 1.625 &#8211; Boa Esperan\u00e7a<\/p>\n<p dir=\"ltr\"><strong>Recepcionista<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">02\/06 a 01\/09\/2025<\/p>\n<p dir=\"ltr\">13h30 \u00e0s 17h30 (segunda, quarta e sexta-feira)<\/p>\n<p dir=\"ltr\">Local: Secretaria Municipal da Mulher | Av. Pres. Get\u00falio Vargas<\/p>\n<p dir=\"ltr\"><strong>Assistente Financeiro<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">02\/06 a 25\/07\/2025<\/p>\n<p dir=\"ltr\">07h30 \u00e0s 11h30 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: Secretaria Municipal da Mulher | Av. Pres. Get\u00falio Vargas<\/p>\n<p dir=\"ltr\"><strong>Salgadeira<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">05\/06 a 30\/07\/2025<\/p>\n<p dir=\"ltr\">13h00 \u00e0s 17h00 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: SENAC | Av. Edgar Vieira, 1.625 &#8211; Boa Esperan\u00e7a<\/p>\n<p dir=\"ltr\"><strong>Tran\u00e7as<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">09\/06 a 18\/06\/2025<\/p>\n<p dir=\"ltr\">18h30 \u00e0s 21h30 (segunda, ter\u00e7a e quarta-feira)<\/p>\n<p dir=\"ltr\">Local: Escola Municipal Ranulfo Paes de Barros | Santa Isabel<\/p>\n<p dir=\"ltr\"><strong>Unhas de Gel<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">23\/06 a 01\/07\/2025<\/p>\n<p dir=\"ltr\">19h00 \u00e0s 22h00 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: SENAC | Av. Edgar Vieira, 1.625 &#8211; Boa Esperan\u00e7a<\/p>\n<p dir=\"ltr\"><strong>Manicure e Pedicure<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">23\/06 a 01\/10\/2025<\/p>\n<p dir=\"ltr\">18h30 \u00e0s 21h30 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: MT QUEER | R. Seis, 07 \u2013 Bairro Jardim Novo Mil\u00eanio<\/p>\n<p dir=\"ltr\"><strong>Cabeleireira<\/strong><\/p>\n<p dir=\"ltr\">Curso com certificado \u2013 100% gratuito<\/p>\n<p dir=\"ltr\">23\/06 a 06\/11\/2025<\/p>\n<p dir=\"ltr\">07h30 \u00e0s 11h30 (segunda a sexta-feira)<\/p>\n<p dir=\"ltr\">Local: SENAC | Av. Edgar Vieira, 1.625 &#8211; Boa Esperan\u00e7a<\/p>\n<p dir=\"ltr\">Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Erlan Aquino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 40 mulheres cuiabanas iniciam, na pr\u00f3xima semana, os cursos de \u201cBolos e Docinhos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":93184,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-93183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=93183"}],"version-history":[{"count":2,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93183\/revisions"}],"predecessor-version":[{"id":93186,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93183\/revisions\/93186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/93184"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=93183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=93183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=93183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}