{"id":93593,"date":"2025-05-30T10:11:49","date_gmt":"2025-05-30T14:11:49","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=93593"},"modified":"2025-05-30T10:11:49","modified_gmt":"2025-05-30T14:11:49","slug":"brasil-conquista-status-internacional-de-pais-livre-da-febre-aftosa-sem-vacinacao","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/brasil-conquista-status-internacional-de-pais-livre-da-febre-aftosa-sem-vacinacao\/","title":{"rendered":"Brasil conquista status internacional de pa\u00eds livre da febre aftosa sem vacina\u00e7\u00e3o"},"content":{"rendered":"<p data-start=\"125\" data-end=\"449\">O Brasil acaba de dar um passo hist\u00f3rico na pecu\u00e1ria: foi reconhecido pela Organiza\u00e7\u00e3o Mundial de Sa\u00fade Animal (OMSA), nesta quinta-feira (29.05), como pa\u00eds livre de febre aftosa sem vacina\u00e7\u00e3o. Isso significa que, al\u00e9m de n\u00e3o haver casos da doen\u00e7a desde 2006, o pa\u00eds provou que consegue manter seu rebanho saud\u00e1vel sem precisar aplicar a vacina.<\/p>\n<p data-start=\"451\" data-end=\"712\">Essa conquista n\u00e3o \u00e9 s\u00f3 uma vit\u00f3ria t\u00e9cnica, mas uma oportunidade concreta de abrir portas para mercados internacionais mais exigentes, como Jap\u00e3o, Coreia do Sul e Indon\u00e9sia, que antes n\u00e3o compravam nossa carne justamente por causa da vacina\u00e7\u00e3o obrigat\u00f3ria.<\/p>\n<p data-start=\"757\" data-end=\"1162\">Para o produtor rural, especialmente o pecuarista, o reconhecimento pode significar valoriza\u00e7\u00e3o do gado, maior demanda pela carne brasileira e at\u00e9 pre\u00e7os melhores. Mas aten\u00e7\u00e3o: isso n\u00e3o quer dizer que tudo muda de uma hora para outra. O Minist\u00e9rio da Agricultura alerta que a libera\u00e7\u00e3o das exporta\u00e7\u00f5es para novos pa\u00edses ser\u00e1 feita caso a caso, conforme acordos comerciais forem sendo firmados.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"ub3a59414e6e034a46a88773d7a2de590-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Mapa cria sistema que permite acompanhar hist\u00f3rico, localiza\u00e7\u00e3o e trajet\u00f3ria de animais<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p data-start=\"1210\" data-end=\"1399\">Se por um lado o pa\u00eds n\u00e3o precisa mais vacinar, por outro os cuidados sanit\u00e1rios devem ser ainda mais rigorosos. Sem vacina, o risco de reintrodu\u00e7\u00e3o do v\u00edrus exige vigil\u00e2ncia constante.<\/p>\n<p data-start=\"1401\" data-end=\"1668\">Os produtores precisam ficar atentos a qualquer sintoma nos animais e seguir as orienta\u00e7\u00f5es de manejo com rigor. A entrada e sa\u00edda de animais da propriedade, a participa\u00e7\u00e3o em feiras, leil\u00f5es e o transporte em caminh\u00f5es devem ser controlados com responsabilidade.<\/p>\n<p data-start=\"2385\" data-end=\"2733\">Segundo Roberto Perosa, presidente da Abiec (Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Exportadora de Carne), essa certifica\u00e7\u00e3o internacional serve como um trunfo nas negocia\u00e7\u00f5es com pa\u00edses exigentes, como o Jap\u00e3o. Ele lembra, por\u00e9m, que o reconhecimento da OMSA elimina apenas uma barreira t\u00e9cnica \u2014 o trabalho diplom\u00e1tico e comercial precisa seguir.<\/p>\n<p data-start=\"2735\" data-end=\"2997\">Hoje, a China \u00e9 o maior comprador da carne brasileira, e mant\u00e9m exig\u00eancias sanit\u00e1rias rigorosas, como idade m\u00e1xima do boi (30 meses) e aus\u00eancia de doen\u00e7as. Outros compradores importantes incluem Estados Unidos, M\u00e9xico, Uni\u00e3o Europeia, Chile e Ar\u00e1bia Saudita.<\/p>\n<p data-start=\"2735\" data-end=\"2997\"><strong>SAIBA MAIS<\/strong><\/p>\n<p data-start=\"1698\" data-end=\"1867\">A febre aftosa \u00e9 uma doen\u00e7a viral altamente contagiosa, que atinge principalmente bovinos, mas tamb\u00e9m bubalinos, caprinos, ovinos e su\u00ednos. Os principais sinais s\u00e3o:<\/p>\n<ul data-start=\"1869\" data-end=\"2023\">\n<li data-start=\"1869\" data-end=\"1904\">\n<p data-start=\"1871\" data-end=\"1904\">Bolhas na boca, focinho e casco<\/p>\n<\/li>\n<li data-start=\"1905\" data-end=\"1935\">\n<p data-start=\"1907\" data-end=\"1935\">Febre alta e perda de peso<\/p>\n<\/li>\n<li data-start=\"1936\" data-end=\"1959\">\n<p data-start=\"1938\" data-end=\"1959\">Saliva\u00e7\u00e3o excessiva<\/p>\n<\/li>\n<li data-start=\"1960\" data-end=\"1995\">\n<p data-start=\"1962\" data-end=\"1995\">Diminui\u00e7\u00e3o na produ\u00e7\u00e3o de leite<\/p>\n<\/li>\n<li data-start=\"1996\" data-end=\"2023\">\n<p data-start=\"1998\" data-end=\"2023\">Enfraquecimento e cansa\u00e7o<\/p>\n<\/li>\n<\/ul>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"ufca4b170e76a6fa453e5483842b35761-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">MT: produtores devem informar rebanho at\u00e9 30 de novembro<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p data-start=\"2025\" data-end=\"2181\">A transmiss\u00e3o acontece pelo contato entre animais, mas tamb\u00e9m por objetos, ve\u00edculos, roupas e at\u00e9 pelas m\u00e3os de pessoas que lidaram com animais doentes.<\/p>\n<p data-start=\"2183\" data-end=\"2346\">A doen\u00e7a n\u00e3o tem cura imediata, e os animais se recuperam em semanas. Por\u00e9m, em caso de surto, o sacrif\u00edcio pode ser necess\u00e1rio para evitar que ela se espalhe.<\/p>\n<p data-start=\"2183\" data-end=\"2346\">\n<p data-start=\"2183\" data-end=\"2346\"><a href=\"https:\/\/pensaragro.com.br\/brasil-conquista-status-internacional-de-pais-livre-da-febre-aftosa-sem-vacinacao\/\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil acaba de dar um passo hist\u00f3rico na pecu\u00e1ria: foi reconhecido pela Organiza\u00e7\u00e3o Mundial &hellip;<\/p>\n","protected":false},"author":4,"featured_media":93594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-93593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=93593"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93593\/revisions"}],"predecessor-version":[{"id":93595,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93593\/revisions\/93595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/93594"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=93593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=93593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=93593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}