{"id":93616,"date":"2025-06-02T09:44:00","date_gmt":"2025-06-02T13:44:00","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=93616"},"modified":"2025-06-02T09:44:00","modified_gmt":"2025-06-02T13:44:00","slug":"participantes-da-virada-sustentavel-recebem-orientacoes-sobre-compostagem-e-prevencao-a-dengue-e-chikungunya","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/participantes-da-virada-sustentavel-recebem-orientacoes-sobre-compostagem-e-prevencao-a-dengue-e-chikungunya\/","title":{"rendered":"Participantes da Virada Sustent\u00e1vel recebem orienta\u00e7\u00f5es sobre compostagem e preven\u00e7\u00e3o \u00e0 dengue e chikungunya"},"content":{"rendered":"<p>Estudantes do curso de Agronomia e colaboradores volunt\u00e1rios do Instituto Rumo aproveitaram a programa\u00e7\u00e3o da Virada Sustent\u00e1vel Mato Grosso, em Rondon\u00f3polis, para levar orienta\u00e7\u00f5es \u00e0 popula\u00e7\u00e3o sobre a pr\u00e1tica da compostagem e os cuidados para preven\u00e7\u00e3o e elimina\u00e7\u00e3o dos criadouros dos mosquitos Aedes Aegypti e Aedes Albopictus, transmissores da Dengue e da Chikungunya. Al\u00e9m da distribui\u00e7\u00e3o de panfletos, o trabalho orientativo incluiu entrega de saquinhos de adubo org\u00e2nico e abordagens seguidas de muita conversa com os participantes do evento.<\/p>\n<p>A estudante do curso de Agronomia Marcela Tavares explicou que a Virada Sustent\u00e1vel foi uma oportunidade para os alunos do primeiro ao quinto semestre transmitirem os conhecimentos adquiridos em sala de aula. \u201cN\u00f3s come\u00e7amos em fevereiro a fazer a composteira com res\u00edduos de cascas de frutas. Hoje estamos entregando os saquinhos de adubo e explicando \u00e0 popula\u00e7\u00e3o o que \u00e9 a compostagem, como usar e como montar a composteira\u201d, destacou.<\/p>\n<p>A compostagem, segundo ela, \u00e9 o processo natural de decomposi\u00e7\u00e3o de res\u00edduos org\u00e2nicos (restos de comida, folhas secas, cascas de frutas etc). \u201cAl\u00e9m de reduzir o lixo nos aterros sanit\u00e1rios, a compostagem evita a emiss\u00e3o de gases do efeito estufa, melhora a fertilidade do solo, promove a educa\u00e7\u00e3o ambiental e contribui para a sa\u00fade p\u00fablica\u201d, ensinou a estudante.<\/p>\n<p>A a\u00e7\u00e3o de sensibiliza\u00e7\u00e3o em torno das medidas a serem adotadas para eliminar os criadouros dos mosquitos respons\u00e1veis pela transmiss\u00e3o dos v\u00edrus causadores da Dengue e Chikungunya tamb\u00e9m chamou a aten\u00e7\u00e3o dos participantes da Virada Sustent\u00e1vel. O vendedor Jo\u00e3o Martins da Silva, 43 anos, explica que contraiu a Chikungunya h\u00e1 mais de tr\u00eas meses e at\u00e9 hoje ainda sofre com sequelas da doen\u00e7a.<\/p>\n<p>\u201cVira e mexe tenho dores nas articula\u00e7\u00f5es da m\u00e3o direita, ainda sofro com as sequelas da doen\u00e7a. Embora esse tema venha sendo abordado constantemente, considero de extrema import\u00e2ncia iniciativa como esta. Orienta\u00e7\u00f5es sobre os cuidados com a nossa sa\u00fade s\u00e3o sempre muito importantes\u201d, observou.<\/p>\n<p>A analista do Instituto Rumo, Maralina Matoso, explicou que o programa voluntariado corporativo abrange diversas \u00e1reas, al\u00e9m da sa\u00fade. \u201cOs colaboradores volunt\u00e1rios se organizam em equipes, se aproximam de uma institui\u00e7\u00e3o benefici\u00e1ria, elaboram e desenvolvem um projeto junto \u00e0 institui\u00e7\u00e3o escolhida. Trabalhamos com oito causas especificamente, assist\u00eancia social, desastres e emerg\u00eancias, cultura, esporte e lazer, sa\u00fade, bem-estar, meio ambiente e seguran\u00e7a ferrovi\u00e1ria. Por ano, s\u00e3o patrocinados 10 projetos\u201d, disse.<\/p>\n<p>A Virada Sustent\u00e1vel Mato Grosso come\u00e7ou na quinta-feira (29), em Rondon\u00f3polis, e encerra-se neste domingo (01), na Pra\u00e7a P\u00f4r do Sol. Na pr\u00f3xima semana, as atividades ser\u00e3o realizadas em Cuiab\u00e1.<\/p>\n<p>O evento \u00e9 uma realiza\u00e7\u00e3o da Secretaria de Estado de Meio Ambiente (Sema) e Instituto Virada Sustent\u00e1vel, com apoio do Governo Federal via Lei de Incentivo \u00e0 Cultura e patroc\u00ednio da Rumo Log\u00edstica, atrav\u00e9s do Instituto Rumo. Recebe ainda apoio da Prefeitura de Cuiab\u00e1, Prefeitura de Rondon\u00f3polis, Assembleia Legislativa de Mato Grosso (ALMT), Secretaria de Estado de Cultura, Esporte e Lazer (Secel), Secretaria de Estado de Educa\u00e7\u00e3o (Seduc), TV Centro Am\u00e9rica, Universidade Federal do Mato Grosso (UFMT), Museu de Arte e Cultura Popular, Cineclube Coxipon\u00e9s, Universidade Federal de Rondon\u00f3polis (UFR), Sesc e Minist\u00e9rio do Meio Ambiente.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 \u00a0Foto:\u00a0 Sema<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudantes do curso de Agronomia e colaboradores volunt\u00e1rios do Instituto Rumo aproveitaram a programa\u00e7\u00e3o da &hellip;<\/p>\n","protected":false},"author":4,"featured_media":93617,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-93616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Al\u00e9m da distribui\u00e7\u00e3o de panfletos, a\u00e7\u00e3o teve entrega de saquinhos de adubo org\u00e2nico e abordagens seguidas de muita conversa","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=93616"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93616\/revisions"}],"predecessor-version":[{"id":93618,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93616\/revisions\/93618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/93617"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=93616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=93616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=93616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}