{"id":93652,"date":"2025-06-02T15:14:31","date_gmt":"2025-06-02T19:14:31","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=93652"},"modified":"2025-06-02T15:14:31","modified_gmt":"2025-06-02T19:14:31","slug":"camara-de-cuiaba-realiza-blitz-da-saude-para-servidores","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/camara-de-cuiaba-realiza-blitz-da-saude-para-servidores\/","title":{"rendered":"C\u00e2mara de Cuiab\u00e1 realiza Blitz da Sa\u00fade para servidores"},"content":{"rendered":"<div>ECOM \u2013 C\u00e2mara Municipal de Cuiab\u00e1<\/div>\n<div><\/div>\n<div>A C\u00e2mara Municipal de Cuiab\u00e1 realizar\u00e1, nesta quarta-feira (4), a Blitz da Sa\u00fade, voltada aos servidores da Casa de Leis. A iniciativa \u00e9 do ambulat\u00f3rio do Parlamento e promover\u00e1 o acompanhamento da press\u00e3o arterial e da glicemia.<\/div>\n<div><\/div>\n<div>A glicemia mede a quantidade de glicose (a\u00e7\u00facar) no sangue, podendo indicar condi\u00e7\u00f5es como diabetes, hipoglicemia e hiperglicemia. J\u00e1 a aferi\u00e7\u00e3o da press\u00e3o arterial avalia a for\u00e7a exercida pelo sangue nas paredes das art\u00e9rias, podendo apontar casos de hipertens\u00e3o.<\/div>\n<div><\/div>\n<div>A enfermeira e servidora da Casa, Aline Moreira, ressaltou a import\u00e2ncia da participa\u00e7\u00e3o dos servidores na a\u00e7\u00e3o e os benef\u00edcios que o check-up proporciona.<\/div>\n<div><\/div>\n<div>\u201cPedimos que os servidores compare\u00e7am em jejum, para que a verifica\u00e7\u00e3o da glicemia seja mais precisa. \u00c9 fundamental monitorarmos regularmente a press\u00e3o arterial e a glicemia, para que, se necess\u00e1rio, o diagn\u00f3stico seja feito o mais cedo poss\u00edvel, permitindo o in\u00edcio do tratamento adequado\u201d, destacou Aline.<\/div>\n<div><\/div>\n<div>A Blitz da Sa\u00fade ser\u00e1 realizada nos dias 4 e 18 de junho (quartas-feiras), das 7h30 \u00e0s 10h30, no sagu\u00e3o da C\u00e2mara de Cuiab\u00e1. A a\u00e7\u00e3o \u00e9 voltada exclusivamente aos servidores da Casa de Leis.<\/div>\n<div><\/div>\n<div>O ambulat\u00f3rio tamb\u00e9m realiza atendimentos para familiares de primeiro grau dos servidores (pais, filhos e c\u00f4njuges).<\/div>\n<div><\/div>\n<div>SECOM \u2013 <a href=\"https:\/\/www.camaracuiaba.mt.gov.br\/noticia.php?id=15966\">C\u00e2mara Municipal de Cuiab\u00e1<\/a>\u00a0 \u00a0 |\u00a0 \u00a0Foto:\u00a0 Jess\u00e9 Soares<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ECOM \u2013 C\u00e2mara Municipal de Cuiab\u00e1 A C\u00e2mara Municipal de Cuiab\u00e1 realizar\u00e1, nesta quarta-feira (4), &hellip;<\/p>\n","protected":false},"author":4,"featured_media":93653,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-93652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=93652"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93652\/revisions"}],"predecessor-version":[{"id":93654,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/93652\/revisions\/93654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/93653"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=93652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=93652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=93652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}