{"id":94028,"date":"2025-06-13T10:13:44","date_gmt":"2025-06-13T14:13:44","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=94028"},"modified":"2025-06-13T10:13:44","modified_gmt":"2025-06-13T14:13:44","slug":"prefeito-e-secretarios-dialogam-com-vereadores-e-setor-de-eventos-sobre-poluicao-sonora","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeito-e-secretarios-dialogam-com-vereadores-e-setor-de-eventos-sobre-poluicao-sonora\/","title":{"rendered":"Prefeito e secret\u00e1rios dialogam com vereadores e setor de eventos sobre polui\u00e7\u00e3o sonora"},"content":{"rendered":"<p>O prefeito de Cuiab\u00e1, Abilio Brunini, cumpriu o compromisso firmado nesta semana com representantes de bares, casas noturnas e produtores culturais e encaminhou \u00e0 C\u00e2mara Municipal, nesta quinta-feira (12), uma proposta de atualiza\u00e7\u00e3o na legisla\u00e7\u00e3o que regulamenta os limites de som em eventos e estabelecimentos da capital. A inten\u00e7\u00e3o foi revelada ap\u00f3s encontro na sala de reuni\u00f5es da presid\u00eancia da C\u00e2mara de Vereadores, em coletiva \u00e0 imprensa. Representantes sugeriram, dialogaram e chegaram em entendimento para alcan\u00e7ar o equil\u00edbrio na chamada \u201cLei do Sil\u00eancio\u201d.<\/p>\n<p>A reuni\u00e3o contou com as participa\u00e7\u00f5es dos secret\u00e1rios Johnny Everson (Cultura) e Fernando Medeiros (Turismo) e Juliana Palhares (Ordem P\u00fablica) al\u00e9m de outros parlamentares e representantes da Abrasel e da presidente da Casa, Paula Calil. \u201cNos comprometemos e estamos cumprindo. O objetivo \u00e9 estabelecer regras claras, equilibrando o direito ao descanso dos moradores com a valoriza\u00e7\u00e3o do entretenimento, cultura e economia criativa\u201d, afirmou Abilio.<\/p>\n<p>Entre os pontos principais da proposta, o projeto diferencia os tipos de eventos e seus respectivos limites de emiss\u00e3o sonora. Festas residenciais, por exemplo, seguiriam o limite de 60 decib\u00e9is at\u00e9 \u00e0s 22h. Das 22h \u00e0 meia-noite, cai para 55 decib\u00e9is, e ap\u00f3s esse hor\u00e1rio, n\u00e3o ser\u00e1 permitido som mec\u00e2nico.<\/p>\n<p>J\u00e1 bares e restaurantes com alvar\u00e1 espec\u00edfico dever\u00e3o emitir som at\u00e9 75 decib\u00e9is at\u00e9 22h, 65 at\u00e9 a meia-noite, e 60 decib\u00e9is ap\u00f3s esse hor\u00e1rio. Eventos especiais e pontuais, como grandes shows e festas religiosas, ter\u00e3o limites diferenciados, podendo chegar a 130 decib\u00e9is mediante autoriza\u00e7\u00e3o pr\u00e9via e comunica\u00e7\u00e3o \u00e0 vizinhan\u00e7a.<\/p>\n<p>\u201cO som ser\u00e1 medido inclusive dentro do im\u00f3vel de quem se sentir incomodado, desde que a pessoa se identifique. Estamos modernizando a legisla\u00e7\u00e3o e respeitando todos os lados\u201d, disse o prefeito.<\/p>\n<p>O projeto prev\u00ea ainda a apreens\u00e3o de equipamentos sonoros em caso de infra\u00e7\u00e3o, com multa progressiva em caso de reincid\u00eancia. A responsabilidade ser\u00e1 compartilhada entre o organizador e o dono do equipamento.<\/p>\n<p>A secret\u00e1ria de Ordem P\u00fablica de Cuiab\u00e1, Juliana Palhares, avaliou como produtiva a reuni\u00e3o realizada com representantes do setor de entretenimento para discutir a proposta de atualiza\u00e7\u00e3o da lei de polui\u00e7\u00e3o sonora. Segundo ela, o objetivo da Prefeitura \u00e9 mediar os interesses conflitantes entre a realiza\u00e7\u00e3o de eventos e o direito ao descanso da popula\u00e7\u00e3o.<\/p>\n<p>&#8220;Nosso objetivo \u00e9 encontrar um ponto de equil\u00edbrio entre o direito ao entretenimento, que movimenta a economia da cidade, e o direito ao sossego da popula\u00e7\u00e3o. A nova legisla\u00e7\u00e3o sobre polui\u00e7\u00e3o sonora precisa refletir a realidade de Cuiab\u00e1, contemplando tanto os grandes eventos, que s\u00e3o espor\u00e1dicos, quanto a rotina de moradores que convivem com o barulho diariamente. \u00c9 um desafio, mas o poder p\u00fablico tem a responsabilidade de mediar esses interesses conflitantes com responsabilidade e di\u00e1logo&#8221;.<\/p>\n<p>J\u00e1 o secret\u00e1rio de Cultura Jhonny Everson ponderou que o objetivo \u00e9 termos uma capital viva, movimentada e cultura viva. &#8220;Nossa cidade precisa de shows internacionais, ou de cantores locais para manter viva a Cidade. As nossas conversas convergem para um equil\u00edbrio&#8221;, comentou.<\/p>\n<p>A proposta ser\u00e1 debatida em audi\u00eancia p\u00fablica na segunda-feira (16) e deve ser fechada at\u00e9 a pr\u00f3xima ter\u00e7a-feira (17), a tempo de vigorar durante as festas universit\u00e1rias que movimentam a cidade.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 SECOM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Cuiab\u00e1, Abilio Brunini, cumpriu o compromisso firmado nesta semana com representantes de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":94029,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-94028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=94028"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94028\/revisions"}],"predecessor-version":[{"id":94030,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94028\/revisions\/94030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/94029"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=94028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=94028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=94028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}