{"id":94162,"date":"2025-06-17T09:39:58","date_gmt":"2025-06-17T13:39:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=94162"},"modified":"2025-06-17T09:39:58","modified_gmt":"2025-06-17T13:39:58","slug":"sine-estadual-disponibiliza-mais-de-25-mil-vagas-de-trabalho-nesta-semana","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sine-estadual-disponibiliza-mais-de-25-mil-vagas-de-trabalho-nesta-semana\/","title":{"rendered":"Sine Estadual disponibiliza mais de 2,5 mil vagas de trabalho nesta semana"},"content":{"rendered":"<div class=\"full-content\">\n<p>O Sistema Nacional de Emprego (Sine-MT), vinculado \u00e0 Secretaria de Estado de Assist\u00eancia Social e Cidadania (Setasc), divulgou 2.545 vagas de trabalho dispon\u00edveis para esta semana em Mato Grosso.<\/p>\n<p>As oportunidades abrangem diversas \u00e1reas de atua\u00e7\u00e3o e est\u00e3o distribu\u00eddas entre os 36 postos de atendimento do Sine, instalados em 32 munic\u00edpios de Mato Grosso.<\/p>\n<p>Em Cuiab\u00e1 e V\u00e1rzea Grande, s\u00e3o 426 empregos dispon\u00edveis em fun\u00e7\u00f5es como auxiliar de linha de produ\u00e7\u00e3o (99), balanceiro (80), servente de pedreiro (30), cortador de carne em matadouro (20), desossador (20), magarefe (20), retalhador de carne (20), operador de caixa (9), motorista carreteiro (8), servente de obras (8), auxiliar de limpeza (7), pedreiro (7), motorista entregador (6), ajudante de obras (5), a\u00e7ougueiro (4), dentre outras.<\/p>\n<p>H\u00e1 tamb\u00e9m a disponibilidade de 21 oportunidades de trabalho exclusivas para Pessoas com Defici\u00eancia (PCD). As fun\u00e7\u00f5es s\u00e3o servente de limpeza (8), frentista (3), lubrificador de autom\u00f3veis (3), operador de caixa (3), auxiliar de limpeza (2), oficial de manuten\u00e7\u00e3o (1) e promotor de vendas (1).<\/p>\n<p>No munic\u00edpio de C\u00e1ceres, est\u00e3o dispon\u00edveis 136 vagas de trabalho nas fun\u00e7\u00f5es de trabalhador agropecu\u00e1rio em geral (30), vendedor de servi\u00e7os (17), ajudante de obras (15), auxiliar operacional de log\u00edstica (7), empacotador \u00e0 m\u00e3o (6), motorista de caminh\u00e3o (5), oficial de servi\u00e7os gerais na manuten\u00e7\u00e3o de edifica\u00e7\u00f5es (5), a\u00e7ougueiro (4), instalador de equipamentos de comunica\u00e7\u00e3o (4), trabalhador volante da agricultura (4), auxiliar mec\u00e2nico de autos (3), empregado dom\u00e9stico arrumador (3), repositor (3), atendente de lojas (2), atendente do setor de frios e latic\u00ednios (2), gar\u00e7om (2), operador de caixa (2), professor instrutor de ensino e aprendizagem agroflorestal (2), t\u00e9cnico em seguran\u00e7a do trabalho (2), atendente de mesa (1), atendente de padaria (1), consultor de vendas (1), cuidador de idosos domiciliar (1), eletricista de manuten\u00e7\u00e3o industrial (1), empregado dom\u00e9stico faxineiro (1), mec\u00e2nico (1), mec\u00e2nico de bicicletas (1), mec\u00e2nico de motocicletas (1), motorista entregador (1), servente de limpeza (1), torneiro ajustador (1) e vendedor de com\u00e9rcio varejista (1).<\/p>\n<p>Em Rondon\u00f3polis, s\u00e3o 110 vagas dispon\u00edveis nas ocupa\u00e7\u00f5es de auxiliar de linha de produ\u00e7\u00e3o (39), ajudante de obras (5), operador de tr\u00e1fego (5), carpinteiro (4), soldador (4), ajudante de acabamento de fundi\u00e7\u00e3o (3), auxiliar de limpeza (3), eletricista de instala\u00e7\u00f5es industriais (3), operador de m\u00e1quina agr\u00edcola (3), servente de obras (3), instalador de pel\u00edcula solar (2), instalador de som e acess\u00f3rios de ve\u00edculos (2), motorista de caminh\u00e3o leve (2), pedreiro (2), porteiro (2), servente de limpeza (2), tapeceiro de ve\u00edculos (2), alinhador veicular (1), auxiliar de manuten\u00e7\u00e3o predial (1), auxiliar t\u00e9cnico de mec\u00e2nica (1), balconista (1), consultor de vendas (1), eletricista de instala\u00e7\u00f5es de ve\u00edculos automotores (1), guarda de vigil\u00e2ncia (1), motorista entregador (1), t\u00e9cnico eletr\u00f4nico (1), t\u00e9cnico em instala\u00e7\u00e3o de sistemas \u00f3pticos (1), torneiro mec\u00e2nico (1) e vendedor pracista (1).<\/p>\n<p>A lista detalhada e completa das vagas ofertadas pela Rede Sine pode ser acessada diariamente utilizando o Portal Emprega Brasil.<\/p>\n<p><strong>Atendimento<\/strong><\/p>\n<p>Al\u00e9m do trabalho de intermedia\u00e7\u00e3o de m\u00e3o de obra, o Sine-MT realiza servi\u00e7o de habilita\u00e7\u00e3o do seguro desemprego, atendimento orientado sobre a utiliza\u00e7\u00e3o da Carteira de Trabalho Digital. \u00c9 preciso verificar na unidade a disponibilidade das vagas, que s\u00e3o oferecidas diariamente.<\/p>\n<p>Os interessados podem comparecer aos postos de atendimento portando documentos pessoais, facilitando os tr\u00e2mites do atendimento.<\/p>\n<p>Na regi\u00e3o metropolitana, o hor\u00e1rio de atendimento dos Sines, localizados nas unidades do Ganha Tempo Ipiranga e do CPA I, \u00e9 de 8h \u00e0s 17h, de segunda a sexta-feira. J\u00e1 no Sine no Centro Estadual de Cidadania do V\u00e1rzea Grande Shopping o hor\u00e1rio de funcionamento \u00e9 das 10h \u00e0s 17h30.<\/p>\n<p>Para ter acesso completo a todas as oportunidades dispon\u00edveis nos munic\u00edpios de Mato Grosso, acesse o documento em anexo.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"container mt-5\">\n<div class=\"row justify-content-md-center\">\n<div class=\"col-sm-12 anexos\">Anexos<\/p>\n<p><a href=\"https:\/\/www.secom.mt.gov.br\/documents\/364148\/0\/VAGAS+SINE+-+16.06.2025+%281%29.pdf\/0b132c14-f8be-b965-7890-aa60c4146b14?t=1750108716091\" target=\"_blank\" rel=\"noopener\">VAGAS SINE &#8211; 16.06.2025 (1).pdf<\/a><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>MTGOV<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Sistema Nacional de Emprego (Sine-MT), vinculado \u00e0 Secretaria de Estado de Assist\u00eancia Social e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":94163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-94162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Interessados devem procurar a unidade do Sine mais pr\u00f3xima com documento de identifica\u00e7\u00e3o civil com foto","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=94162"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94162\/revisions"}],"predecessor-version":[{"id":94164,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94162\/revisions\/94164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/94163"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=94162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=94162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=94162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}