{"id":94463,"date":"2025-06-27T14:48:34","date_gmt":"2025-06-27T18:48:34","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=94463"},"modified":"2025-06-27T14:48:34","modified_gmt":"2025-06-27T18:48:34","slug":"mtprev-conquista-dois-premios-nacionais-e-completa-cinco-anos-consecutivos-entre-os-destaques-do-pais","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mtprev-conquista-dois-premios-nacionais-e-completa-cinco-anos-consecutivos-entre-os-destaques-do-pais\/","title":{"rendered":"MTPrev conquista dois pr\u00eamios nacionais e completa cinco anos consecutivos entre os destaques do pa\u00eds"},"content":{"rendered":"<p>O Mato Grosso Previd\u00eancia (MTPrev) mais uma vez teve seu trabalho reconhecido em n\u00edvel nacional. Pela quinta vez consecutiva, a funda\u00e7\u00e3o conquistou posi\u00e7\u00e3o de destaque no Pr\u00eamio \u201cDestaque Brasil\u201d, promovido pela Associa\u00e7\u00e3o Brasileira de Institui\u00e7\u00f5es de Previd\u00eancia Estaduais e Municipais (ABIPEM). A cerim\u00f4nia de premia\u00e7\u00e3o aconteceu na noite desta quinta-feira (26.6), durante o 58\u00ba Congresso Nacional da ABIPEM, realizado em Foz do Igua\u00e7u (PR).<\/p>\n<p>Nesta edi\u00e7\u00e3o, o MTPrev alcan\u00e7ou o 1\u00ba lugar na categoria Governan\u00e7a Previdenci\u00e1ria e o 2\u00ba lugar em Responsabilidade Previdenci\u00e1ria, reafirmando seu compromisso com uma gest\u00e3o moderna, transparente e focada na sustentabilidade do Regime Pr\u00f3prio de Previd\u00eancia Social (RPPS) do Estado de Mato Grosso.<\/p>\n<p>\u201cEstar entre os melhores do Brasil pelo quinto ano consecutivo \u00e9 uma grande satisfa\u00e7\u00e3o e refor\u00e7a que estamos no caminho certo. Isso \u00e9 resultado de um trabalho coletivo, feito com planejamento, seriedade e respeito pela previd\u00eancia dos servidores p\u00fablicos de Mato Grosso\u201d, celebrou Elliton Oliveira de Souza, diretor-presidente do MTPrev.<\/p>\n<p>Para o chefe da Unidade de Compliance Previdenci\u00e1rio, Guelfo Luis Munhoz Rodrigues, a conquista representa o acerto na condu\u00e7\u00e3o dos processos internos.<\/p>\n<p>\u201cO planejamento estrat\u00e9gico estruturado, as certifica\u00e7\u00f5es de todos os servidores, gestores e conselheiros, os comit\u00eas ativos, as assessorias t\u00e9cnicas qualificadas, a maturidade no Pr\u00f3-Gest\u00e3o, o ISP A \u2014 tudo isso mostra que cada servidor do MTPrev tem um papel fundamental nesse processo. Todos est\u00e3o de parab\u00e9ns. \u00c9 com muita satisfa\u00e7\u00e3o que estamos aqui representando o Mato Grosso nessa premia\u00e7\u00e3o.\u201d<\/p>\n<p>Guelfo tamb\u00e9m destacou o papel do MTPrev como refer\u00eancia e apoio a outros estados.<\/p>\n<p>\u201cTemos orgulho de ajudar estados como Acre e Piau\u00ed a se prepararem para o Pr\u00f3-Gest\u00e3o. Isso mostra que conseguimos multiplicar conhecimento e contribuir com o fortalecimento dos RPPS no Brasil.\u201d<\/p>\n<p>O presidente da ABIPEM, Jo\u00e3o Carlos Figueiredo, destacou a evolu\u00e7\u00e3o da funda\u00e7\u00e3o e o impacto positivo de sua atua\u00e7\u00e3o.<\/p>\n<p>\u201cConseguimos ver a evolu\u00e7\u00e3o que o MTPrev teve nos \u00faltimos anos, a ponto de alcan\u00e7ar o n\u00edvel 4 do Pr\u00f3-Gest\u00e3o. Isso \u00e9 fruto de um trabalho s\u00e9rio, de uma equipe alinhada, que joga junto. Para a ABIPEM, \u00e9 uma satisfa\u00e7\u00e3o ver o MTPrev como refer\u00eancia nacional. Esperamos que esse reconhecimento traga novos desafios e ainda mais avan\u00e7os nos pr\u00f3ximos anos\u201d, afirmou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Joycy Ambr\u00f3sio &#8211; MTPrev<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Mato Grosso Previd\u00eancia (MTPrev) mais uma vez teve seu trabalho reconhecido em n\u00edvel nacional. &hellip;<\/p>\n","protected":false},"author":4,"featured_media":94464,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-94463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Premia\u00e7\u00f5es refor\u00e7am excel\u00eancia em governan\u00e7a e responsabilidade na gest\u00e3o da previd\u00eancia dos servidores estaduais","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=94463"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94463\/revisions"}],"predecessor-version":[{"id":94465,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/94463\/revisions\/94465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/94464"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=94463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=94463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=94463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}