{"id":95167,"date":"2025-07-15T11:49:59","date_gmt":"2025-07-15T15:49:59","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=95167"},"modified":"2025-07-15T11:49:59","modified_gmt":"2025-07-15T15:49:59","slug":"escola-de-governo-abre-inscricoes-para-capacitacao-em-gestao-por-processos-com-ferramenta-bizagi-modeler","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/escola-de-governo-abre-inscricoes-para-capacitacao-em-gestao-por-processos-com-ferramenta-bizagi-modeler\/","title":{"rendered":"Escola de Governo abre inscri\u00e7\u00f5es para capacita\u00e7\u00e3o em gest\u00e3o por processos com ferramenta Bizagi Modeler"},"content":{"rendered":"<p>A Secretaria de Estado de Planejamento e Gest\u00e3o (Seplag), por meio da Escola de Governo, abriu nesta segunda-feira (14.7) as inscri\u00e7\u00f5es para o curso Introdu\u00e7\u00e3o em Gest\u00e3o por Processos BPM e Nota\u00e7\u00e3o BPMN com Bizagi Modeler. S\u00e3o 200 vagas exclusivas para servidores do Poder Executivo Estadual.<\/p>\n<p>Os interessados devem se inscrever por meio deste\u00a0<a href=\"http:\/\/capacitacoes.controladoria.mt.gov.br\/curso\/3311\/INTRODUCAO-EM-GESTAO-POR-PROCESSOS-BPM-E-INTRODUCAO-A-NOTACAO-BPMN-UTILIZANDO-BIZAGI-MODELER-TURMA-06-\" target=\"_blank\" rel=\"noopener\">link<\/a>, at\u00e9 o dia 23 de julho. Essa capacita\u00e7\u00e3o ser\u00e1 realizada na modalidade remota e o conte\u00fado program\u00e1tico ficar\u00e1 dispon\u00edvel na plataforma Classroom no per\u00edodo de 28 de julho a 22 de agosto.<\/p>\n<p>O Bizagi Modeler \u00e9 um software que contribui para a elabora\u00e7\u00e3o de manuais t\u00e9cnicos de processos e procedimentos e promove a constru\u00e7\u00e3o coletiva, a transpar\u00eancia e a agilidade na tomada de decis\u00f5es.<\/p>\n<p>Essa ferramenta ser\u00e1 combinada \u00e0 metodologia para modelos de processos para neg\u00f3cios (em ingl\u00eas Business Process Model &#8211; BPM) e ao modelo de nota\u00e7\u00e3o Business Process Model and Notation (BPMN).<\/p>\n<p>O curso est\u00e1 estruturado em 10 m\u00f3dulos que, ao final, possibilitam a visualiza\u00e7\u00e3o e padroniza\u00e7\u00e3o de rotinas internas da administra\u00e7\u00e3o p\u00fablica.<\/p>\n<p>Esses m\u00f3dulos abordam temas como governan\u00e7a de processos, cadeia de valor, escopo, modelagem, nota\u00e7\u00e3o BPMN, al\u00e9m da aplica\u00e7\u00e3o pr\u00e1tica com o uso do Bizagi Modeler para fortalecer a gest\u00e3o por processos e a cultura da melhoria cont\u00ednua.<\/p>\n<p>Os participantes que cumprirem os requisitos, como presen\u00e7a e realiza\u00e7\u00e3o das tarefas propostas, receber\u00e3o certificado de 20 horas-aula.<\/p>\n<p>Mais informa\u00e7\u00f5es: ead@seplag.mt.gov.br<br \/>\n<em>*com supervis\u00e3o de In\u00e1cio de Paula<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 Foto:\u00a0 Divulga\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Planejamento e Gest\u00e3o (Seplag), por meio da Escola de Governo, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":95168,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-95167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"S\u00e3o 200 vagas; os interessados devem se inscrever at\u00e9 o dia 23 de julho","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=95167"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95167\/revisions"}],"predecessor-version":[{"id":95169,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95167\/revisions\/95169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/95168"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=95167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=95167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=95167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}