{"id":95196,"date":"2025-07-16T11:13:04","date_gmt":"2025-07-16T15:13:04","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=95196"},"modified":"2025-07-16T11:13:04","modified_gmt":"2025-07-16T15:13:04","slug":"prefeitura-de-cuiaba-mantem-forca-tarefa-para-conter-surto-de-catapora-entre-migrantes-warao","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeitura-de-cuiaba-mantem-forca-tarefa-para-conter-surto-de-catapora-entre-migrantes-warao\/","title":{"rendered":"Prefeitura de Cuiab\u00e1 mant\u00e9m for\u00e7a-tarefa para conter surto de catapora entre migrantes Warao"},"content":{"rendered":"<p>As secretarias municipais de Sa\u00fade e de Assist\u00eancia Social de Cuiab\u00e1 intensificaram medidas preventivas e de conten\u00e7\u00e3o diante de um surto de catapora identificado entre migrantes ind\u00edgenas venezuelanos da etnia Warao, acolhidos no Albergue Manoel Miraglia, na capital. A situa\u00e7\u00e3o tem mobilizado esfor\u00e7os conjuntos das duas pastas para conter a propaga\u00e7\u00e3o da doen\u00e7a e garantir o atendimento necess\u00e1rio \u00e0s fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade.<\/p>\n<p>Como parte da for\u00e7a-tarefa, tr\u00eas crian\u00e7as Warao foram encaminhadas ao Hospital Municipal de Cuiab\u00e1 (HMC) com complica\u00e7\u00f5es cl\u00ednicas decorrentes da catapora. As tr\u00eas est\u00e3o sob cuidados m\u00e9dicos, com estado de sa\u00fade est\u00e1vel, medicadas e em constante monitoramento. Paralelamente, as equipes de sa\u00fade refor\u00e7aram a vacina\u00e7\u00e3o entre os acolhidos, priorizando especialmente o p\u00fablico infantil.<\/p>\n<p>A gest\u00e3o municipal tem enfrentado desafios extras no enfrentamento do surto, como barreiras lingu\u00edsticas e culturais que dificultam o acesso integral aos cuidados de sa\u00fade e \u00e0 informa\u00e7\u00e3o. Nem todas as fam\u00edlias falam espanhol ou portugu\u00eas, o que exige media\u00e7\u00e3o constante e aten\u00e7\u00e3o redobrada das equipes t\u00e9cnicas.<\/p>\n<p>A secret\u00e1ria municipal de Assist\u00eancia Social, Direitos Humanos e Inclus\u00e3o, H\u00e9lida Vilela, afirmou que a Prefeitura est\u00e1 acompanhando pessoalmente os casos e mantendo todos os entes respons\u00e1veis devidamente informados sobre a situa\u00e7\u00e3o. J\u00e1 foram notificados o Poder Judici\u00e1rio de Mato Grosso, a Defensoria P\u00fablica da Uni\u00e3o, a Funai e representantes do Governo Federal e MPU. O grupo comp\u00f5e uma for\u00e7a-tarefa determinada pelo Judici\u00e1rio que busca alternativas de acolhimento para as fam\u00edlias Warao.<\/p>\n<p>Al\u00e9m da aten\u00e7\u00e3o \u00e0 sa\u00fade, a Prefeitura tem atuado em v\u00e1rias frentes: alimenta\u00e7\u00e3o, oferta de atividades em contraturno escolar, inclus\u00e3o das crian\u00e7as na rede de ensino, emiss\u00e3o de documentos e acompanhamento psicossocial. Tamb\u00e9m est\u00e1 em articula\u00e7\u00e3o com o Governo do Estado para viabilizar recursos e pol\u00edticas complementares.<\/p>\n<p>\u201cA Prefeitura de Cuiab\u00e1 manifesta profunda preocupa\u00e7\u00e3o com a sa\u00fade e o bem-estar do povo Warao e reafirma seu compromisso com a assist\u00eancia humanizada. Estamos buscando, junto aos entes legalmente respons\u00e1veis, alternativas efetivas para garantir acolhimento digno, respeitando as particularidades culturais dessas fam\u00edlias que encontraram ref\u00fagio em nossa cidade\u201d, declarou H\u00e9lida.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 SECOM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As secretarias municipais de Sa\u00fade e de Assist\u00eancia Social de Cuiab\u00e1 intensificaram medidas preventivas e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":95197,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-95196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=95196"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95196\/revisions"}],"predecessor-version":[{"id":95198,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95196\/revisions\/95198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/95197"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=95196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=95196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=95196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}