{"id":95297,"date":"2025-07-18T15:01:31","date_gmt":"2025-07-18T19:01:31","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=95297"},"modified":"2025-07-18T15:01:31","modified_gmt":"2025-07-18T19:01:31","slug":"camara-aprova-ldo-de-2026-e-garante-avanco-no-planejamento-fiscal-de-cuiaba","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/camara-aprova-ldo-de-2026-e-garante-avanco-no-planejamento-fiscal-de-cuiaba\/","title":{"rendered":"C\u00e2mara aprova LDO de 2026 e garante avan\u00e7o no planejamento fiscal de Cuiab\u00e1"},"content":{"rendered":"<p>A C\u00e2mara Municipal de Cuiab\u00e1 aprovou, nesta quinta-feira (17), durante sess\u00f5es ordin\u00e1ria e extraordin\u00e1ria, o projeto da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) para o exerc\u00edcio de 2026, enviado pelo Poder Executivo. O texto define as metas fiscais e os par\u00e2metros que orientar\u00e3o a elabora\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria Anual (LOA), instrumento que estrutura as receitas e despesas do munic\u00edpio.<\/p>\n<p>O prefeito Abilio Brunini comemorou a aprova\u00e7\u00e3o e destacou o compromisso da atual gest\u00e3o com o equil\u00edbrio fiscal e a transpar\u00eancia na aplica\u00e7\u00e3o dos recursos p\u00fablicos.<\/p>\n<p>\u201cA LDO \u00e9 a base do nosso planejamento para 2026. Essa aprova\u00e7\u00e3o nos d\u00e1 seguran\u00e7a para continuar construindo um or\u00e7amento respons\u00e1vel, que priorize as pessoas e respeite os limites legais. Cuiab\u00e1 vive um novo momento de responsabilidade e reconstru\u00e7\u00e3o, e essa aprova\u00e7\u00e3o fortalece nosso trabalho\u201d, afirmou o gestor.<\/p>\n<p>Durante a sess\u00e3o ordin\u00e1ria, os vereadores aprovaram os pareceres favor\u00e1veis ao projeto de lei do Executivo, incluindo a Emenda Modificativa apresentada pela presidente da Casa, vereadora Paula Calil (PL), que assegura a destina\u00e7\u00e3o obrigat\u00f3ria de 2% da receita corrente l\u00edquida para emendas parlamentares, conforme a Lei Org\u00e2nica do Munic\u00edpio. A medida refor\u00e7a a legalidade e a transpar\u00eancia na execu\u00e7\u00e3o or\u00e7ament\u00e1ria, em alinhamento com a Lei de Responsabilidade Fiscal.<\/p>\n<p>J\u00e1 a emenda de autoria da vereadora Maria Avalone (PSDB), que inclui na LDO a exig\u00eancia do Relat\u00f3rio Tem\u00e1tico \u201cOr\u00e7amento Mulheres\u201d, tamb\u00e9m foi aprovada ap\u00f3s derrubada do parecer contr\u00e1rio das comiss\u00f5es, com 21 votos favor\u00e1veis.<\/p>\n<p>O projeto da LDO recebeu ainda os pareceres das Comiss\u00f5es de Constitui\u00e7\u00e3o, Justi\u00e7a e Reda\u00e7\u00e3o (CCJR) e de Fiscaliza\u00e7\u00e3o e Acompanhamento da Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria (CFAEO), sendo aprovado por ampla maioria em sess\u00e3o extraordin\u00e1ria.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><\/p>\n<p>Com a aprova\u00e7\u00e3o da LDO, a Prefeitura de Cuiab\u00e1 inicia agora a elabora\u00e7\u00e3o da proposta da Lei Or\u00e7ament\u00e1ria Anual (LOA) para 2026, que ser\u00e1 enviada \u00e0 C\u00e2mara at\u00e9 o fim do segundo semestre.<\/p>\n<p>A LOA \u00e9 o documento que detalha, de forma precisa, onde e como ser\u00e3o aplicados os recursos p\u00fablicos, garantindo a execu\u00e7\u00e3o das pol\u00edticas previstas nas diretrizes aprovadas.<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 |\u00a0 \u00a0Foto:\u00a0 Davi Valle<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara Municipal de Cuiab\u00e1 aprovou, nesta quinta-feira (17), durante sess\u00f5es ordin\u00e1ria e extraordin\u00e1ria, o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":95298,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-95297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=95297"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95297\/revisions"}],"predecessor-version":[{"id":95299,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95297\/revisions\/95299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/95298"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=95297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=95297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=95297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}