{"id":95896,"date":"2025-08-04T14:00:06","date_gmt":"2025-08-04T18:00:06","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=95896"},"modified":"2025-08-04T14:00:06","modified_gmt":"2025-08-04T18:00:06","slug":"corpo-de-bombeiros-e-sema-iniciam-operacao-de-protecao-e-resgate-de-fauna","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/corpo-de-bombeiros-e-sema-iniciam-operacao-de-protecao-e-resgate-de-fauna\/","title":{"rendered":"Corpo de Bombeiros e Sema iniciam opera\u00e7\u00e3o de prote\u00e7\u00e3o e resgate de fauna"},"content":{"rendered":"<p>O Corpo de Bombeiros Militar de Mato Grosso (CBMMT) e a Secretaria de Estado de Meio Ambiente (Sema) deram in\u00edcio, nesta segunda-feira (4.8), \u00e0 opera\u00e7\u00e3o conjunta Arca de No\u00e9, voltada \u00e0 prote\u00e7\u00e3o e ao resgate da fauna silvestre, com foco especial nas \u00e1reas que forem afetadas por inc\u00eandios florestais, queimadas irregulares e desmatamento no Estado.<\/p>\n<p>Equipes especializadas, que incluem m\u00e9dicos veterin\u00e1rios, far\u00e3o o monitoramento constante das regi\u00f5es impactadas, com o objetivo de minimizar os danos ambientais causados pelo fogo e pela degrada\u00e7\u00e3o do habitat natural. A opera\u00e7\u00e3o inclui a\u00e7\u00f5es de resgate de animais feridos ou em risco, al\u00e9m da destina\u00e7\u00e3o adequada para um novo local seguro ou para tratamento e reabilita\u00e7\u00e3o, se necess\u00e1rio.<\/p>\n<p>O comandante do Batalh\u00e3o de Emerg\u00eancias Ambientais (BEA), tenente-coronel Rafael Ribeiro Marcondes explicou que essa \u00e9 a primeira vez que uma opera\u00e7\u00e3o conjunta desse tipo \u00e9 realizada de forma estruturada e cont\u00ednua. Em anos anteriores, a atua\u00e7\u00e3o do Corpo de Bombeiros Militar se dava apenas por meio de apoios pontuais \u00e0s a\u00e7\u00f5es de resgate conduzidas pela Sema.\u00a0Agora, com a integra\u00e7\u00e3o das equipes desde o in\u00edcio, o trabalho ganha mais alcance, agilidade e efici\u00eancia no resgate e na prote\u00e7\u00e3o da fauna silvestre.<\/p>\n<div><picture data-fileentryid=\"73693444\"><source srcset=\"\/o\/adaptive-media\/image\/73693444\/Thumbnail-1024x1024\/sema_cbm+%282%29.jpg?t=1754320319546\" media=\"(max-width:1024px)\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/bombeiros\/sema_cbm-2-?imageThumbnail=3\" alt=\"\" width=\"800\" height=\"600\" \/><\/picture>\n<div id=\"imgCaption_0\" class=\"imgCaption\"><\/div>\n<\/div>\n<p>Nesta fase inicial, as equipes atuar\u00e3o no acompanhamento e no mapeamento das \u00e1reas afetadas em todo Estado, com aten\u00e7\u00e3o especial ao bioma Pantanal, que \u00e9 uma regi\u00e3o com rica diversidade de fauna e cujas caracter\u00edsticas naturais favorecem a r\u00e1pida propaga\u00e7\u00e3o do fogo.<\/p>\n<p>\u201cNeste primeiro momento, realizamos o monitoramento e o acompanhamento das \u00e1reas afetadas. Nas grandes opera\u00e7\u00f5es, especialmente em casos de inc\u00eandios de grande propor\u00e7\u00e3o, percorremos as regi\u00f5es queimadas em busca de animais que, porventura, tenham sido atingidos pelo fogo, estejam feridos, debilitados ou em risco\u201d, explicou o comandante.<\/p>\n<p>A secret\u00e1ria de Estado de Meio Ambiente, Mauren Lazzaretti, destacou a import\u00e2ncia da opera\u00e7\u00e3o, que neste ano ocorre de forma mais abrangente. Ela ressaltou que as a\u00e7\u00f5es realizadas pelo \u00f3rg\u00e3o ambiental constam em um plano de atendimento emergencial \u00e0 fauna silvestre em Mato Grosso.<\/p>\n<p>Al\u00e9m da capacita\u00e7\u00e3o dos profissionais que atuam diretamente nessa prote\u00e7\u00e3o, a Sema est\u00e1 realizando cadastro de volunt\u00e1rios que tenham interesse em atuar no resgate, manejo e destina\u00e7\u00e3o dos animais silvestres em Unidades de Conserva\u00e7\u00e3o geridas pelo \u00f3rg\u00e3o ambiental. Informa\u00e7\u00f5es sobre como se voluntariar est\u00e3o dispon\u00edveis no site da\u00a0<a href=\"https:\/\/www.sema.mt.gov.br\/\" target=\"_blank\" rel=\"noopener\">Sema<\/a>.<\/p>\n<div><picture data-fileentryid=\"73693436\"><source srcset=\"\/o\/adaptive-media\/image\/73693436\/Thumbnail-1024x1024\/sema_cbm+%281%29.jpg?t=1754320317981\" media=\"(max-width:1024px)\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/bombeiros\/sema_cbm-1-?imageThumbnail=3\" alt=\"\" width=\"800\" height=\"600\" \/><\/picture>\n<div id=\"imgCaption_1\" class=\"imgCaption\"><\/div>\n<\/div>\n<p><strong>Preven\u00e7\u00e3o e combate aos inc\u00eandios florestais<\/strong><\/p>\n<p>Al\u00e9m da prote\u00e7\u00e3o \u00e0 fauna, o Governo de Mato Grosso est\u00e1 investindo R$ 125 milh\u00f5es em a\u00e7\u00f5es voltadas ao combate do desmatamento ilegal e \u00e0 preven\u00e7\u00e3o e combate dos inc\u00eandios florestais. Desse montante, R$ 78 milh\u00f5es diretamente nas a\u00e7\u00f5es realizadas pela corpora\u00e7\u00e3o que contempla, al\u00e9m das medidas de preven\u00e7\u00e3o, a contrata\u00e7\u00e3o de brigadistas, amplia\u00e7\u00e3o da estrutura da corpora\u00e7\u00e3o, uso de maquin\u00e1rio pesado, firmamento de parcerias, entre outras a\u00e7\u00f5es estrat\u00e9gicas.<\/p>\n<p><strong>Proibi\u00e7\u00e3o do uso do fogo<\/strong><\/p>\n<p>O CBMMT refor\u00e7a o alerta \u00e0 popula\u00e7\u00e3o sobre a proibi\u00e7\u00e3o do uso fogo para limpeza e manejo de \u00e1reas rurais em Mato Grosso. Desde 1\u00ba de junho, est\u00e1 proibido o uso do fogo no Pantanal, medida que se estende at\u00e9 31 de dezembro. Nas regi\u00f5es da Amaz\u00f4nia e do Cerrado, o per\u00edodo proibitivo teve in\u00edcio em 1\u00ba de julho e vai at\u00e9 30 de novembro. J\u00e1 nas \u00e1reas urbanas, o uso do fogo \u00e9 proibido durante todo o ano.\u00a0Em caso de qualquer ind\u00edcio de inc\u00eandio florestal no bioma, a orienta\u00e7\u00e3o \u00e9 que a den\u00fancia seja feita imediatamente pelos n\u00fameros 193 ou 190.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 CBMMT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Corpo de Bombeiros Militar de Mato Grosso (CBMMT) e a Secretaria de Estado de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":95897,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-95896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Essa \u00e9 a primeira vez que uma opera\u00e7\u00e3o conjunta para resgate de animais silvestres \u00e9 realizada em Mato Grosso","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=95896"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95896\/revisions"}],"predecessor-version":[{"id":95898,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95896\/revisions\/95898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/95897"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=95896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=95896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=95896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}