{"id":95970,"date":"2025-08-05T15:28:17","date_gmt":"2025-08-05T19:28:17","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=95970"},"modified":"2025-08-05T15:28:17","modified_gmt":"2025-08-05T19:28:17","slug":"professores-de-cuiaba-se-qualificam-para-ensino-da-escrita-nas-series-iniciais","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/professores-de-cuiaba-se-qualificam-para-ensino-da-escrita-nas-series-iniciais\/","title":{"rendered":"Professores de Cuiab\u00e1 se qualificam para ensino da escrita nas s\u00e9ries iniciais"},"content":{"rendered":"<p data-end=\"424\" data-start=\"90\">Setenta professores vinculados \u00e0 Prefeitura de Cuiab\u00e1 participaram, de um curso de forma\u00e7\u00e3o continuada para refor\u00e7ar a aprendizagem infantil nas escolas p\u00fablicas. Trata-se de mais uma etapa do programa \u201cAlfabetiza MT\u201d, resultado de um termo de coopera\u00e7\u00e3o firmado pela Prefeitura de Cuiab\u00e1 com o governo do Estado.<\/p>\n<p data-end=\"650\" data-start=\"426\">A aula de capacita\u00e7\u00e3o continuada ocorreu no Hotel Fazenda Mato Grosso. Duas turmas foram divididas em salas de aula com 35 participantes, todos professores do 1\u00ba e 2\u00ba ano das s\u00e9ries iniciais. O curso durou das 7h30 \u00e0s 11h30.<\/p>\n<p data-end=\"905\" data-start=\"652\">O principal debate foi a psicog\u00eanese da escrita, que descreve os diferentes n\u00edveis de hip\u00f3teses que as crian\u00e7as constroem sobre a escrita antes de atingir a alfabetiza\u00e7\u00e3o plena. Esses n\u00edveis s\u00e3o: pr\u00e9-sil\u00e1bico, sil\u00e1bico, sil\u00e1bico-alfab\u00e9tico e alfab\u00e9tico.<\/p>\n<p data-end=\"1284\" data-start=\"907\">\u201cEste \u00e9 um processo de aprendizagem que capacita nossos professores a compreenderem a psicog\u00eanese da escrita. Ao mesmo tempo, foram oferecidas t\u00e9cnicas de interven\u00e7\u00e3o na sala de aula, visando os melhores resultados da aprendizagem aos nossos alunos. A educa\u00e7\u00e3o infantil \u00e9 uma prioridade total para a constru\u00e7\u00e3o de um futuro melhor\u201d, ressalta a professora Marina Lucca Penhavel.<\/p>\n<p data-end=\"1551\" data-start=\"1286\">\u201c\u00c9 um trabalho direcionado, com a intensidade pedag\u00f3gica da qual os professores s\u00e3o muito dispostos a participar, o que nos deixa muito felizes\u201d, destaca a professora Eva Sandra In\u00e1cio da Silva, da Escola Nossa Senhora Aparecida, localizada no bairro Novo Colorado.<\/p>\n<p data-end=\"1551\" data-start=\"1286\">Os cursos de forma\u00e7\u00e3o continuada j\u00e1 est\u00e3o programados at\u00e9 o final de setembro, contemplando professores de toda a rede p\u00fablica municipal do 1\u00ba e 2\u00ba ano, gestores e t\u00e9cnicos de desenvolvimento infantil.<\/p>\n<p data-end=\"1672\" data-start=\"1553\"><strong>#PraCegoVer<\/strong><\/p>\n<p data-end=\"1672\" data-start=\"1553\">A foto ilustra um grupo de professores sentados em cadeiras almofadadas, prestando aten\u00e7\u00e3o numa palestra.<\/p>\n<p data-end=\"1672\" data-start=\"1553\">\n<p data-end=\"1672\" data-start=\"1553\">Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 Foto:\u00a0 Francinei Marans<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Setenta professores vinculados \u00e0 Prefeitura de Cuiab\u00e1 participaram, de um curso de forma\u00e7\u00e3o continuada para &hellip;<\/p>\n","protected":false},"author":4,"featured_media":95971,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-95970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=95970"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95970\/revisions"}],"predecessor-version":[{"id":95972,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/95970\/revisions\/95972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/95971"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=95970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=95970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=95970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}