{"id":96157,"date":"2025-08-11T14:17:43","date_gmt":"2025-08-11T18:17:43","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=96157"},"modified":"2025-08-11T14:17:43","modified_gmt":"2025-08-11T18:17:43","slug":"cuiaba-faz-novas-contratacoes-e-soma-1-940-cuidadoras-de-alunos-com-deficiencia","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/cuiaba-faz-novas-contratacoes-e-soma-1-940-cuidadoras-de-alunos-com-deficiencia\/","title":{"rendered":"Cuiab\u00e1 faz novas contrata\u00e7\u00f5es e soma 1.940 Cuidadoras de Alunos com Defici\u00eancia"},"content":{"rendered":"<p data-end=\"400\" data-start=\"218\">A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Educa\u00e7\u00e3o (SME), contratou, nos meses de julho e agosto deste ano, 240 novas Cuidadoras de Alunos com Defici\u00eancia (CADs).<\/p>\n<p data-end=\"520\" data-start=\"402\">Agora, s\u00e3o 1.940 profissionais que acompanham, no turno escolar, crian\u00e7as com defici\u00eancia f\u00edsica, visual e auditiva.<\/p>\n<p data-end=\"613\" data-start=\"522\">Atualmente, 2.645 crian\u00e7as s\u00e3o atendidas diariamente nas unidades educacionais de Cuiab\u00e1.<\/p>\n<p data-end=\"883\" data-start=\"615\">&#8220;A amplia\u00e7\u00e3o do quadro de profissionais, em apoio \u00e0s crian\u00e7as que n\u00e3o possuem autonomia para alimenta\u00e7\u00e3o, higieniza\u00e7\u00e3o e locomo\u00e7\u00e3o, atende a pedido do prefeito Abilio Brunini e da primeira-dama Samantha Iris&#8221;, afirma o secret\u00e1rio municipal de Educa\u00e7\u00e3o, Amauri Monge.<\/p>\n<p data-end=\"1709\" data-start=\"885\">A coordenadora de Educa\u00e7\u00e3o Especial da SME, professora Neuraides Ribeiro, explica que a disponibiliza\u00e7\u00e3o do profissional de apoio para atendimento \u00e0 crian\u00e7a com defici\u00eancia \u00e9 regulamentada pela Nota T\u00e9cnica n\u00ba 19\/2010 do Minist\u00e9rio da Educa\u00e7\u00e3o e pelo Parecer n\u00ba 50, homologado em 2024 pelo Conselho Nacional de Educa\u00e7\u00e3o, assegurando o profissional de apoio aos estudantes com TEA, conforme descrito no artigo 3\u00ba, inciso XIII, da LDI:<br data-end=\"1321\" data-start=\"1318\" \/>[&#8230;] XIII \u2013 Profissional de apoio escolar: pessoa que exerce atividades de alimenta\u00e7\u00e3o, higiene e locomo\u00e7\u00e3o do estudante com defici\u00eancia e atua em todas as atividades escolares nas quais se fizer necess\u00e1ria, em todos os n\u00edveis e modalidades de ensino, em institui\u00e7\u00f5es p\u00fablicas e privadas, exclu\u00eddas as t\u00e9cnicas ou os procedimentos identificados com profiss\u00f5es legalmente estabelecidas.<\/p>\n<p data-end=\"1854\" data-start=\"1711\">&#8220;A necessidade do profissional de apoio est\u00e1 definida nestes documentos. Estamos trabalhando para cumprir rigorosamente essas regras&#8221;, disse.<\/p>\n<p data-end=\"2338\" data-start=\"1856\">Para que a crian\u00e7a tenha o acompanhamento do profissional de apoio (CAD \u2013 Cuidador), \u00e9 necess\u00e1rio que a fam\u00edlia ou respons\u00e1vel entre em contato com a dire\u00e7\u00e3o escolar e apresente laudos e documentos. Caso a crian\u00e7a apresente algum comportamento at\u00edpico, a equipe gestora tem autonomia para, a partir da autoriza\u00e7\u00e3o dos pais ou respons\u00e1veis, solicitar a presen\u00e7a da equipe de avalia\u00e7\u00e3o multidisciplinar formada por psic\u00f3logo, fonoaudi\u00f3logo e psicopedagoga da Secretaria de Educa\u00e7\u00e3o.<\/p>\n<p data-end=\"2581\" data-start=\"2340\">#<strong>PraCegoVer<\/strong><\/p>\n<p data-end=\"2581\" data-start=\"2340\">\u00a0A foto ilustra a fachada do pr\u00e9dio da Secretaria Municipal de Educa\u00e7\u00e3o. O fundo \u00e9 verde, o bras\u00e3o da Prefeitura de Cuiab\u00e1 est\u00e1 no lado esquerdo. Ao centro, em letras mai\u00fasculas, est\u00e1 escrito &#8220;Secretaria Municipal de Educa\u00e7\u00e3o&#8221;.<\/p>\n<p data-end=\"2581\" data-start=\"2340\">\n<p data-end=\"2581\" data-start=\"2340\">\n<p data-end=\"2581\" data-start=\"2340\">Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Emanoele Daiane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Educa\u00e7\u00e3o (SME), contratou, nos meses &hellip;<\/p>\n","protected":false},"author":4,"featured_media":96158,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-96157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=96157"}],"version-history":[{"count":2,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96157\/revisions"}],"predecessor-version":[{"id":96160,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96157\/revisions\/96160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/96158"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=96157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=96157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=96157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}