{"id":96258,"date":"2025-08-13T10:55:32","date_gmt":"2025-08-13T14:55:32","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=96258"},"modified":"2025-08-13T10:55:32","modified_gmt":"2025-08-13T14:55:32","slug":"carnes-somaram-mais-de-r-412-bilhoes-na-primeira-quinzena-de-agosto","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/carnes-somaram-mais-de-r-412-bilhoes-na-primeira-quinzena-de-agosto\/","title":{"rendered":"Carnes somaram mais de R$ 4,12 bilh\u00f5es na primeira quinzena de agosto"},"content":{"rendered":"<p>As exporta\u00e7\u00f5es brasileiras de carne bovina, su\u00edna e de frango alcan\u00e7aram juntas cerca de\u00a0<strong data-start=\"368\" data-end=\"387\">R$ 4,12 bilh\u00f5es<\/strong>\u00a0nas duas primeiras semanas de agosto de 2025, segundo dados da Secretaria de Com\u00e9rcio Exterior (Secex). No per\u00edodo, o volume embarcado somou aproximadamente\u00a0<strong data-start=\"545\" data-end=\"568\">227,1 mil toneladas<\/strong>\u00a0\u2014 80,4 mil de carne bovina, 33,9 mil de su\u00edna e 112,8 mil de frango \u2014 mantendo o ritmo acelerado mesmo com as tarifas de 50% impostas pelos Estados Unidos. A m\u00e9dia di\u00e1ria de faturamento combinada ultrapassou\u00a0<strong data-start=\"777\" data-end=\"795\">R$ 685 milh\u00f5es<\/strong>, refletindo tanto o aumento dos pre\u00e7os m\u00e9dios da carne bovina e su\u00edna quanto a alta no volume exportado das tr\u00eas prote\u00ednas.<\/p>\n<p data-start=\"643\" data-end=\"1135\">A carne bovina puxa o movimento. At\u00e9 a segunda semana de agosto, foram embarcadas 80,4 mil toneladas, com m\u00e9dia di\u00e1ria pr\u00f3xima de 13,4 mil toneladas \u2014 um salto de 35,7% em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2024. O pre\u00e7o m\u00e9dio tamb\u00e9m subiu, atingindo US$ 5.557 por tonelada, 25,3% acima do valor do ano passado. O faturamento di\u00e1rio cresceu 70%, chegando a US$ 74,5 milh\u00f5es, e a proje\u00e7\u00e3o \u00e9 que o volume total de agosto possa alcan\u00e7ar 320 mil toneladas, superando as 276,8 mil registradas em julho.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u1e8f84eaf1706bb83254507ad8be4ae7-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Apesar das intemp\u00e9ries clim\u00e1ticas, plantio da soja no Brasil atingiu 30% da \u00e1rea prevista<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p data-start=\"1137\" data-end=\"1505\">A carne su\u00edna tamb\u00e9m apresenta resultado firme. Foram 33,9 mil toneladas exportadas at\u00e9 a segunda semana do m\u00eas, com m\u00e9dia di\u00e1ria de 5,6 mil toneladas, alta de 17,4% sobre agosto do ano anterior. O pre\u00e7o m\u00e9dio teve leve eleva\u00e7\u00e3o, para US$ 2.545,2 por tonelada, e a receita total j\u00e1 ultrapassa US$ 86 milh\u00f5es, com avan\u00e7o de 21,4% na m\u00e9dia di\u00e1ria em compara\u00e7\u00e3o a 2024.<\/p>\n<p data-start=\"1507\" data-end=\"1981\">Nas aves, o volume embarcado alcan\u00e7ou 112,8 mil toneladas at\u00e9 agora, crescimento de 16,3% na m\u00e9dia di\u00e1ria. Embora o pre\u00e7o m\u00e9dio por tonelada tenha recuado 13%, para US$ 1.800,4, a receita di\u00e1ria avan\u00e7ou 1,1%, somando US$ 33,9 milh\u00f5es. Segundo o analista de mercado Fernando Henrique Iglesias, da Safras &amp; Mercado, a tend\u00eancia \u00e9 de recupera\u00e7\u00e3o mais forte nos pr\u00f3ximos meses, com potencial de amplia\u00e7\u00e3o das vendas caso Uni\u00e3o Europeia e China retomem compras em maior escala.<\/p>\n<p data-start=\"1983\" data-end=\"2265\">Com esses resultados, o Brasil reafirma sua posi\u00e7\u00e3o de pot\u00eancia mundial na exporta\u00e7\u00e3o de carnes, mostrando resili\u00eancia diante de desafios externos e capacidade de ampliar mercados. Se o ritmo se mantiver, agosto poder\u00e1 consolidar-se como um dos melhores meses do ano para o setor.<\/p>\n<p data-start=\"1983\" data-end=\"2265\">\n<p data-start=\"1983\" data-end=\"2265\">\n<p data-start=\"1983\" data-end=\"2265\"><a href=\"https:\/\/pensaragro.com.br\/carnes-somaram-mais-de-r-412-bilhoes-na-primeira-quinzena-de-agosto\/\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As exporta\u00e7\u00f5es brasileiras de carne bovina, su\u00edna e de frango alcan\u00e7aram juntas cerca de\u00a0R$ 4,12 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":96259,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-96258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=96258"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96258\/revisions"}],"predecessor-version":[{"id":96260,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96258\/revisions\/96260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/96259"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=96258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=96258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=96258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}