{"id":96275,"date":"2025-08-14T09:46:21","date_gmt":"2025-08-14T13:46:21","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=96275"},"modified":"2025-08-14T09:46:21","modified_gmt":"2025-08-14T13:46:21","slug":"mais-de-200-simininas-do-carumbe-e-primeiro-de-marco-visitam-aquario","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mais-de-200-simininas-do-carumbe-e-primeiro-de-marco-visitam-aquario\/","title":{"rendered":"Mais de 200 Simininas do Carumb\u00e9 e Primeiro de Mar\u00e7o visitam Aqu\u00e1rio"},"content":{"rendered":"<p>Mais de 200 meninas atendidas pelas unidades do Programa Siminina dos bairros Carumb\u00e9 e Primeiro de Mar\u00e7o, em Cuiab\u00e1, participaram, nesta quarta-feira (13), nos per\u00edodos matutino e vespertino, de uma visita especial ao Aqu\u00e1rio Municipal Justino Malheiros. O espa\u00e7o disponibiliza aos visitantes mais de 600 peixes, distribu\u00eddos em aproximadamente 22 esp\u00e9cies, organizadas em tr\u00eas biomas: Amaz\u00f4nia, Pantanal e Cerrado.<\/p>\n<p>As crian\u00e7as puderam conhecer de perto esp\u00e9cies como pirarucu, tambaqui, pirarara, dourado, cachara, ja\u00fa, jundi\u00e1, entre outras. Para muitas delas, foi a primeira vez visitando o local.<\/p>\n<p>Maria Eduarda, de 12 anos, descreveu seu encanto com o peixe dourado, tamb\u00e9m conhecido por sua beleza: \u201cGostei do peixe dourado e queria voltar aqui mais vezes.\u201d J\u00e1 Suemy de Figueiredo, de 13 anos, destacou o aprendizado: \u201cEu achei muito legal, aprendi v\u00e1rias coisas e aprendi que alguns peixes s\u00e3o um pouco t\u00edmidos de manh\u00e3 e s\u00e3o mais ativos \u00e0 noite.\u201d<\/p>\n<p>A pequena Ana Beatriz, de 9 anos, afirmou que amou conhecer os peixes do aqu\u00e1rio, especialmente \u201cos pequenininhos\u201d. Ela tamb\u00e9m compartilhou as regras de visita\u00e7\u00e3o para garantir o bem-estar dos animais: \u201cTemos que fazer sil\u00eancio, n\u00e3o podemos usar flash, devemos falar baixo e n\u00e3o bater no vidro. Os peixes aqui s\u00e3o bem tratados e se alimentam. Amei conhecer os peixes e quero voltar mais vezes.\u201d<\/p>\n<p>A gerente regional do Programa Siminina, Gracineia Fernandes da Silva, respons\u00e1vel por acompanhar as meninas na visita\u00e7\u00e3o, afirmou que muitas delas nunca haviam visitado o espa\u00e7o. \u201cEnt\u00e3o, \u00e9 um momento gratificante. Teve menina que chegou emocionada, dizendo que estava realizando um sonho. Essa parceria com a Secretaria Municipal de Turismo e Desenvolvimento Econ\u00f4mico nos permite proporcionar experi\u00eancias \u00fanicas para as nossas crian\u00e7as.\u201d<\/p>\n<p>Segundo Gracineia, metade das unidades j\u00e1 realizou a visita ao aqu\u00e1rio. \u201cHoje vieram o Primeiro de Mar\u00e7o e o Carumb\u00e9. Ainda faltam oito unidades. Todas ter\u00e3o a oportunidade de viver essa experi\u00eancia\u201d, destacou.<\/p>\n<p>O Programa Siminina, da Prefeitura de Cuiab\u00e1, atua em 16 unidades distribu\u00eddas por bairros da capital, como Novo Para\u00edso II, Tr\u00eas Barras, CPA, Primeiro de Mar\u00e7o, Tijucal, Carumb\u00e9, entre outros, atendendo 1.149 meninas de 6 a 14 anos em situa\u00e7\u00e3o de vulnerabilidade social. S\u00e3o oferecidas atividades como bal\u00e9, fanfarra, refor\u00e7o escolar e a\u00e7\u00f5es socioeducativas. A expectativa \u00e9 que, em breve, a 17\u00aa unidade seja inaugurada no bairro Pedra 90.<\/p>\n<p><strong>#PraCegoVer<\/strong><\/p>\n<p>A imagem mostra as Simininas entrando no Aqu\u00e1rio Municipal Justino Malheiros.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Emanoele Daiane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 200 meninas atendidas pelas unidades do Programa Siminina dos bairros Carumb\u00e9 e Primeiro &hellip;<\/p>\n","protected":false},"author":4,"featured_media":96276,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-96275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=96275"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96275\/revisions"}],"predecessor-version":[{"id":96277,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96275\/revisions\/96277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/96276"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=96275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=96275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=96275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}