{"id":96792,"date":"2025-09-02T15:14:40","date_gmt":"2025-09-02T19:14:40","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=96792"},"modified":"2025-09-02T15:14:40","modified_gmt":"2025-09-02T19:14:40","slug":"acoes-na-capital-ampliam-indices-de-empregabilidade-em-cuiaba","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/acoes-na-capital-ampliam-indices-de-empregabilidade-em-cuiaba\/","title":{"rendered":"A\u00e7\u00f5es na capital ampliam \u00edndices de empregabilidade em Cuiab\u00e1"},"content":{"rendered":"<p data-end=\"508\" data-start=\"80\">A Secretaria Municipal de Agricultura e Trabalho (Smat) comemora os avan\u00e7os registrados nos \u00edndices de empregabilidade em Cuiab\u00e1. As a\u00e7\u00f5es desenvolvidas pela gest\u00e3o, como a Van do Sine Itinerante e a realiza\u00e7\u00e3o do primeiro curso de Educa\u00e7\u00e3o Financeira em parceria com o Sest Senat, refor\u00e7am o compromisso de aproximar oportunidades de emprego e capacita\u00e7\u00e3o da popula\u00e7\u00e3o. O curso acontecer\u00e1 na pr\u00f3xima sexta-feira (5), na Smat.<\/p>\n<p data-end=\"994\" data-start=\"510\">De janeiro a julho deste ano, o Sine Municipal emitiu 348 cartas de encaminhamento, auxiliando trabalhadores na busca por inser\u00e7\u00e3o no mercado formal. O resultado pode ser observado nos n\u00fameros divulgados pelo Cadastro Geral de Empregados e Desempregados (Caged), que apontam Cuiab\u00e1 como destaque nacional, considerando que somente em julho 1.632 pessoas conquistaram empregos com carteira assinada, o que representa um crescimento de 140% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado.<\/p>\n<p data-end=\"1215\" data-start=\"996\">Ao longo do m\u00eas, a capital registrou mais admiss\u00f5es (12.383) que demiss\u00f5es (10.751), obtendo desempenho superior \u00e0 m\u00e9dia do Estado (63,8%) e da regi\u00e3o Centro-Oeste (42%), e do Brasil, cujo \u00edndice foi negativo em -32%.<\/p>\n<p data-end=\"1567\" data-start=\"1217\">O setor de Servi\u00e7os foi o principal respons\u00e1vel pelo saldo positivo, contribuindo com 56% das novas vagas, equivalente a 921 postos de trabalho. Entre os destaques, o com\u00e9rcio, lojas e mercados foram respons\u00e1veis por 564 contrata\u00e7\u00f5es formais, fortalecendo a economia local e ampliando as oportunidades de crescimento profissional para os cuiabanos.<\/p>\n<p data-end=\"1815\" data-start=\"1569\">Comparado a junho deste ano, quando foram abertas 1.089 vagas, Cuiab\u00e1 obteve em julho um aumento de 49,86% no saldo entre admiss\u00f5es e demiss\u00f5es, confirmando a Capital mais calorosa do pa\u00eds como protagonista tamb\u00e9m na gera\u00e7\u00e3o de emprego e renda.<\/p>\n<p data-end=\"2158\" data-start=\"1817\">\u201cPara a Smat, os resultados refletem o empenho cont\u00ednuo da Prefeitura em promover pol\u00edticas p\u00fablicas voltadas ao desenvolvimento econ\u00f4mico, \u00e0 empregabilidade e \u00e0 qualifica\u00e7\u00e3o profissional, garantindo mais oportunidades e melhores condi\u00e7\u00f5es de vida para a popula\u00e7\u00e3o\u201d, frisou o secret\u00e1rio municipal de Agricultura e Trabalho, Vicente Falc\u00e3o.<\/p>\n<p data-end=\"2189\" data-start=\"2160\"><strong data-end=\"2187\" data-start=\"2160\">Qualifica\u00e7\u00e3o Financeira<\/strong><\/p>\n<p data-end=\"2487\" data-start=\"2191\">As informa\u00e7\u00f5es e inscri\u00e7\u00f5es para o Curso de Educa\u00e7\u00e3o Financeira est\u00e3o dispon\u00edveis em:\u00a0<a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf6eBX7X6yWLq6zV9hYn-jck0weOHRlxLQ8RZNXwBSn_xpQXA\/viewform?usp=dialog&amp;utm_source=chatgpt.com\" target=\"_new\" rel=\"noopener\" data-end=\"2387\" data-start=\"2277\">https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf6eBX7X6yWLq6zV9hYn-jck0weOHRlxLQ8RZNXwBSn_xpQXA\/viewform?usp=dialog<\/a>. O curso acontecer\u00e1 na sexta-feira (5), a partir das 14h, na sede da Secretaria, no bairro Po\u00e7\u00e3o.<\/p>\n<p>#PraCegoVer<\/p>\n<p>A imagem que ilustra o texto mostra a Van Intinerante que oferece atendimento em diversas \u00e1reas ao trabalhador. A o porta lateral do ve\u00edculo est\u00e1 aberta e pessoas est\u00e3o dentro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 Foto:\u00a0 Rennan Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Agricultura e Trabalho (Smat) comemora os avan\u00e7os registrados nos \u00edndices de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":96793,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-96792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=96792"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96792\/revisions"}],"predecessor-version":[{"id":96794,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/96792\/revisions\/96794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/96793"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=96792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=96792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=96792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}