{"id":97113,"date":"2025-09-15T10:38:13","date_gmt":"2025-09-15T14:38:13","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97113"},"modified":"2025-09-15T10:38:13","modified_gmt":"2025-09-15T14:38:13","slug":"secretaria-de-educacao-dialoga-com-comunidade-escolar-e-reforca-preparativos-para-o-saeb-2025-em-pocone","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/secretaria-de-educacao-dialoga-com-comunidade-escolar-e-reforca-preparativos-para-o-saeb-2025-em-pocone\/","title":{"rendered":"Secretaria de Educa\u00e7\u00e3o dialoga com comunidade escolar e refor\u00e7a preparativos para o Saeb 2025 em Pocon\u00e9"},"content":{"rendered":"<p>A Secretaria de Educa\u00e7\u00e3o de Mato Grosso (Seduc-MT) realiza, nesta segunda-feira (15.9), uma agenda de trabalho em Pocon\u00e9 (a 100 km de Cuiab\u00e1) com foco na escuta ativa de gestores, professores e estudantes, e na mobiliza\u00e7\u00e3o para o\u00a0Sistema de Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o B\u00e1sica (Saeb) 2025. A programa\u00e7\u00e3o inclui visitas a escolas, semin\u00e1rio e di\u00e1logos com a comunidade escolar.<\/p>\n<p>O primeiro compromisso foi realizado \u00e0s 7h30, no Distrito de Cangas, na Escola Estadual Dom Francisco de Aquino Correa, onde t\u00e9cnicos da Seduc e da Diretoria Metropolitana de Educa\u00e7\u00e3o (DME) ouviram a gest\u00e3o escolar, coordena\u00e7\u00e3o pedag\u00f3gica e estudantes sobre os desafios do dia a dia escolar.<\/p>\n<p>Ainda no per\u00edodo da manh\u00e3, a programa\u00e7\u00e3o prossegue em Pocon\u00e9 com o Semin\u00e1rio Alfabetiza MT, voltado ao fortalecimento das pr\u00e1ticas de alfabetiza\u00e7\u00e3o, e um bate-papo sobre o programa EducA\u00e7\u00e3o 10 Anos.<\/p>\n<p>\u00c0 tarde, as visitas se estender\u00e3o \u00e0s escolas estaduais Maria Helena de Ara\u00fajo Bastos, Ant\u00f4nio Jo\u00e3o Ribeiro, Bacharel Ribeiro de Arruda, Frei Carlos Valette e Professor Eucaris Nunes Cunha Moraes, permitindo que a equipe da Seduc conhe\u00e7a de perto as necessidades de infraestrutura, forma\u00e7\u00e3o de professores e apoio pedag\u00f3gico de cada unidade.<\/p>\n<p>O secret\u00e1rio de Estado de Educa\u00e7\u00e3o, Alan Porto, destaca que a escuta ativa \u00e9 uma ferramenta estrat\u00e9gica para alinhar as pol\u00edticas da rede \u00e0s necessidades reais da comunidade escolar.<\/p>\n<p>\u201cEstar presente nas escolas, ouvir professores, coordenadores e estudantes de perto nos permite entender os desafios reais da educa\u00e7\u00e3o e transformar essas demandas em pol\u00edticas efetivas. A rede precisa sentir que faz parte desse processo e que suas necessidades s\u00e3o levadas em considera\u00e7\u00e3o\u201d, disse o secret\u00e1rio.<\/p>\n<p>De acordo com ele, o objetivo \u00e9 levantar demandas, como a necessidade de refor\u00e7o na forma\u00e7\u00e3o continuada de professores, amplia\u00e7\u00e3o de materiais pedag\u00f3gicos para o ensino de L\u00edngua Portuguesa e Matem\u00e1tica e melhorias na infraestrutura de laborat\u00f3rios e espa\u00e7os de conviv\u00eancia.<\/p>\n<p>Tamb\u00e9m ser\u00e3o apresentadas sugest\u00f5es para aprimorar os mecanismos de acompanhamento das aprendizagens, especialmente no contexto das avalia\u00e7\u00f5es externas como o Saeb.<\/p>\n<p>As escutas tamb\u00e9m evidenciam o papel ativo dos estudantes, que compartilham suas expectativas em rela\u00e7\u00e3o ao futuro escolar e participa\u00e7\u00e3o em projetos de protagonismo juvenil, como o 2\u00ba Encontro Estadual dos Gr\u00eamios Estudantis e a 2\u00aa Expo Estudantil \u2013 O futuro \u00e9 agora, realizados em Cuiab\u00e1 na \u00faltima semana de agosto.\u00a0Para o secret\u00e1rio, esse di\u00e1logo direto \u00e9 fundamental.<\/p>\n<p>\u201cQuando o estudante \u00e9 ouvido, ele se sente parte da solu\u00e7\u00e3o e n\u00e3o apenas alvo de pol\u00edticas p\u00fablicas. Isso aumenta o engajamento e motiva a buscar melhores resultados\u201d, completou.<\/p>\n<p>Alan Porto ainda refor\u00e7ou que essas a\u00e7\u00f5es t\u00eam impacto direto no desempenho do estado no Saeb 2025.<\/p>\n<p>\u201cO Saeb, mais do que uma prova, \u00e9 uma oportunidade de avaliar onde estamos e onde queremos chegar. Cada encontro, cada escuta e cada a\u00e7\u00e3o formativa s\u00e3o passos para fortalecer a educa\u00e7\u00e3o de Mato Grosso e alcan\u00e7ar resultados que reflitam o trabalho de toda a rede\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Dacio Carvalho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Educa\u00e7\u00e3o de Mato Grosso (Seduc-MT) realiza, nesta segunda-feira (15.9), uma agenda de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"A\u00e7\u00e3o objetiva fortalecer pol\u00edticas educacionais e garantir melhores resultados nas avalia\u00e7\u00f5es nacionais","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97113"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97113\/revisions"}],"predecessor-version":[{"id":97115,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97113\/revisions\/97115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97114"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}