{"id":97238,"date":"2025-09-18T14:44:58","date_gmt":"2025-09-18T18:44:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97238"},"modified":"2025-09-18T14:44:58","modified_gmt":"2025-09-18T18:44:58","slug":"deputado-fabio-tardin-cobra-novo-hospital-para-varzea-grande","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/deputado-fabio-tardin-cobra-novo-hospital-para-varzea-grande\/","title":{"rendered":"Deputado Fabio Tardin cobra novo hospital para V\u00e1rzea Grande"},"content":{"rendered":"<p>O deputado estadual F\u00e1bio Tardin (PSB) cobrou nesta quarta-feira (17), a constru\u00e7\u00e3o de um novo hospital p\u00fablico em V\u00e1rzea Grande. Atualmente, o Pronto-Socorro Municipal \u00e9 o \u00fanico que atende de portas abertas moradores da Baixada Cuiabana e at\u00e9 pacientes de outros estados e pa\u00edses, o que refor\u00e7a, segundo o parlamentar, a urg\u00eancia de uma nova unidade.<\/p>\n<p>\u201cO Governo do Estado est\u00e1 de parab\u00e9ns, tem constru\u00eddo hospitais regionais, mas, infelizmente, n\u00e3o tem olhado para V\u00e1rzea Grande. Aquele velho Pronto-Socorro n\u00e3o comporta mais a demanda. Precisamos de um hospital novo na cidade\u201d, afirmou Fabinho.<\/p>\n<p>Ele destacou que a unidade \u00e9 a \u00fanica de portas abertas para pacientes de Cuiab\u00e1, da Baixada Cuiabana, de outras regi\u00f5es do Estado e at\u00e9 de fora do pa\u00eds, e que reformas paliativas j\u00e1 n\u00e3o s\u00e3o suficientes. \u201cN\u00e3o podemos mais gastar milh\u00f5es em pequenas reformas, porque isso n\u00e3o resolve. O problema vai continuar o mesmo. O que V\u00e1rzea Grande necessita \u00e9 de um hospital moderno e de qualidade\u201d, defendeu.<\/p>\n<p>Segunda maior cidade de Mato Grosso, V\u00e1rzea Grande \u00e9 tratada, de acordo com Fabinho, como uma localidade de \u201csegunda categoria\u201d. \u201cPrecisamos, com urg\u00eancia, que a Assembleia pe\u00e7a ao governador que olhe com aten\u00e7\u00e3o para V\u00e1rzea Grande. A constru\u00e7\u00e3o de um hospital vai beneficiar n\u00e3o apenas os moradores do munic\u00edpio, mas todos os mato-grossenses que buscam atendimento na cidade\u201d, completou.<\/p>\n<p>O deputado ainda acrescentou que atualmente, o Executivo est\u00e1 construindo hospitais regionais em Tangar\u00e1 da Serra, Alta Floresta, Ju\u00edna e no Araguaia (em Confresa). A previs\u00e3o \u00e9 de que as quatro unidades sejam entregues ainda este ano. Al\u00e9m disso, est\u00e3o em andamento duas grandes obras em Cuiab\u00e1: o Hospital Central e o novo Hospital Universit\u00e1rio J\u00falio M\u00fcller.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ALMT\u00a0 \u00a0|\u00a0 Foto:\u00a0 <i>GILBERTO LEITE\/SECRETARIA DE COMUNICA\u00c7\u00c3O SOCIAL<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual F\u00e1bio Tardin (PSB) cobrou nesta quarta-feira (17), a constru\u00e7\u00e3o de um novo &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97239,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97238"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97238\/revisions"}],"predecessor-version":[{"id":97240,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97238\/revisions\/97240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97239"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}