{"id":97286,"date":"2025-09-23T14:17:05","date_gmt":"2025-09-23T18:17:05","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97286"},"modified":"2025-09-23T14:17:05","modified_gmt":"2025-09-23T18:17:05","slug":"prefeitura-de-cuiaba-convoca-03-candidatos-aprovados-em-processo-seletivo-simplificado","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeitura-de-cuiaba-convoca-03-candidatos-aprovados-em-processo-seletivo-simplificado\/","title":{"rendered":"Prefeitura de Cuiab\u00e1 convoca 03 candidatos aprovados em Processo Seletivo Simplificado"},"content":{"rendered":"<section class=\"innerpage-text-content\">\n<div class=\"container\">\n<div class=\"content clearfix\">\n<div class=\"content-text text-break clearfix\">\n<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Educa\u00e7\u00e3o, convoca nesta ter\u00e7a-feira (23\/09) tr\u00eas candidatos aprovados no Processo Seletivo Simplificado para Contratos Tempor\u00e1rios de Presta\u00e7\u00e3o de Servi\u00e7os por Tempo Determinado e Forma\u00e7\u00e3o de Cadastro de Reserva N\u00ba 12\/2024\/GS\/SME, publicado na Gazeta Municipal N\u00ba 937, de 27\/08\/2024, para atuarem em unidades educacionais da rede municipal no ano letivo de 2025.<\/p>\n<p>Est\u00e3o sendo convocados candidatos para os cargos de Pedagogo, T\u00e9cnico em Desenvolvimento Infantil (TDI), T\u00e9cnico em Manuten\u00e7\u00e3o e Infraestrutura na fun\u00e7\u00e3o de Auxiliar de Servi\u00e7os Gerais (TMIE \u2013 ASG), T\u00e9cnico em Nutri\u00e7\u00e3o Escolar (TNE) e Professores de Arte e Educa\u00e7\u00e3o F\u00edsica, em unidades localizadas em todas as regionais e no campo.<\/p>\n<p>Os candidatos devem comparecer \u00e0 Secretaria Municipal de Educa\u00e7\u00e3o, na Rua Diogo Domingos Ferreira, n\u00ba 292, bairro Bandeirantes, no dia 24 de setembro de 2025, nos hor\u00e1rios previstos nos editais, para entrega de documentos e atribui\u00e7\u00e3o.<\/p>\n<p><strong>Orienta\u00e7\u00f5es importantes:<\/strong><\/p>\n<p>&#8211; \u00c9 fundamental que os candidatos leiam atentamente os editais. Quem n\u00e3o comparecer no dia e hor\u00e1rio previstos ou n\u00e3o entregar toda a documenta\u00e7\u00e3o exigida ser\u00e1 eliminado, sem segunda chamada, e o pr\u00f3ximo classificado ser\u00e1 convocado.<\/p>\n<p>&#8211; Documentos necess\u00e1rios: RG, CPF, T\u00edtulo de Eleitor, PIS\/PASEP, Certificado de Reservista, Conta Corrente no Banco do Brasil (se houver), comprovante de resid\u00eancia, diploma ou certificado de conclus\u00e3o de curso acompanhado do hist\u00f3rico escolar (do Ensino M\u00e9dio), exame admissional e certid\u00f5es negativas.<\/p>\n<p>&#8211; O candidato que chegar atrasado e j\u00e1 tiver sido chamado ser\u00e1 realocado ao final da lista. O comparecimento fora do hor\u00e1rio previsto poder\u00e1 resultar na elimina\u00e7\u00e3o do certame, conforme item 13.3 do edital.<\/p>\n<p>&#8211; O exame admissional poder\u00e1 ser realizado no local de prefer\u00eancia do candidato, desde que constem o cargo e a aptid\u00e3o.<\/p>\n<p><strong>Sobre o Processo Seletivo:<\/strong><br \/>\nO certame realizado em 2024 ofereceu 2.015 vagas para contrata\u00e7\u00e3o imediata e forma\u00e7\u00e3o de cadastro reserva de n\u00edveis m\u00e9dio e superior, para atuar nas unidades educacionais da rede p\u00fablica municipal, em substitui\u00e7\u00e3o tempor\u00e1ria de servidores efetivos, atendendo \u00e0 necessidade de excepcional interesse p\u00fablico.<\/p>\n<p>At\u00e9 o momento, j\u00e1 foram convocados 6.894 candidatos em 58 chamadas anteriores. Nesta 59\u00aa convoca\u00e7\u00e3o, tr\u00eas candidatos ser\u00e3o chamados para diversos cargos e regionais.<\/p>\n<p><strong>O edital de convoca\u00e7\u00e3o pode ser conferido em anexo.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<ul class=\"container\">\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/09\/23\/outros\/2025-09-23-11-57-03-24-09-2025-convocacao-tne-tecnico-em-nutricao-escolar-regional-norte-68d2c35adcd4f.pdf\" target=\"_blank\" rel=\"noopener\">03_24-09-2025-Convoca\u00e7\u00e3o-TNE-T\u00e9cnico-Em-Nutri\u00e7\u00e3o-Escolar-Regional-Norte.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/09\/23\/outros\/2025-09-23-11-57-02-24-09-2025-convocacao-tns-psicologo-68d2c35bdb257.pdf\" target=\"_blank\" rel=\"noopener\">02_24-09-2025-Convoca\u00e7\u00e3o-TNS-Psic\u00f3logo.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/09\/23\/outros\/2025-09-23-11-57-01-24-09-2025-convocacao-tns-nutricionista-68d2c35cd5cfa.pdf\" target=\"_blank\" rel=\"noopener\">01_24-09-2025-Convoca\u00e7\u00e3o-TNS-Nutricionista.pdf<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Emanoele Daiane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Educa\u00e7\u00e3o, convoca nesta ter\u00e7a-feira (23\/09) &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97287,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-97286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97286"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97286\/revisions"}],"predecessor-version":[{"id":97288,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97286\/revisions\/97288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97287"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}